{"id":386148,"date":"2019-07-17T16:32:41","date_gmt":"2019-07-17T23:32:41","guid":{"rendered":"https:\/\/blog.webex.com\/uncategorized-de\/cisco-wird-im-aragon-globe-als-fuhrendes-unternehmen-fur-intelligente-contact-center-eingestuft\/"},"modified":"2019-07-17T16:32:41","modified_gmt":"2019-07-17T23:32:41","slug":"cisco-wird-im-aragon-globe-als-fuhrendes-unternehmen-fur-intelligente-contact-center-eingestuft","status":"publish","type":"post","link":"https:\/\/blog.webex.com\/de\/kundenerfahrungen\/cisco-wird-im-aragon-globe-als-fuhrendes-unternehmen-fur-intelligente-contact-center-eingestuft\/","title":{"rendered":"Cisco wird im Aragon Globe als f\u00fchrendes Unternehmen f\u00fcr ..."},"content":{"rendered":"<p>Vor einigen Wochen bei Cisco Live hatte ich den Spa\u00df, Zeit mit vielen unserer Kunden, Partner und Kollegen zu verbringen, die unsere Contact Center-Portfolio-Vision und Produktin <a href=\"https:\/\/www.cisco.com\/c\/en\/us\/products\/contact-center\/index.html\"><\/a> innovationsstrategien teilen. Das Feedback ist von der Begeisterung und vor der Vornahme der Begeisterung sehr positiv worden, da sich unser Portfolio in der Zukunft weiterentwickeln wird.<\/p>\n<p>Ich freue mich, dass unser Portfolio und unsere Strategie k\u00fcrzlich vom weltweit anerkannten Branchenanalystenunternehmen Research best\u00e4tigt wurden. In seiner <a href=\"https:\/\/engage2demand.cisco.com\/LP=17033?ccid=cc001193&#038;oid=anrco017571\">2019 Globe f\u00fcr Intelligent Contact Center wurde Cisco als einer der F\u00fchrungskr\u00e4fte<\/a>im Intelligent Contact Center anerkannt.<\/p>\n<p>Eine gute Vision ist eine Sache, aber die \u00dcbersetzung der Vision in die Ausf\u00fchrung und Leistung bringt f\u00fcr unsere Kunden einen Mehrwert. Diese Anerkennung ist ein Bild davon, wie vollst\u00e4ndig unsere Strategie ist und wie stark unsere Leistung beim Erf\u00fcllen dieser Strategie auf dem Markt ist.<\/p>\n<p>Bei Research handelt es sich um ein unabh\u00e4ngiges Forschungs- und Beratungsunternehmen, das mehr als 100 Jahre Erfahrung bei der Entscheidungsfindung von Technologie- und Strategieentscheidungen in Unternehmen und IT-F\u00fchrungskr\u00e4ften sammeln konnte. DerStool Research Globe ist ein Evaluierungstool f\u00fcr den Markt, das \u00fcber Gr\u00f6\u00dfe und Marktanteil hinaus sucht und stattdessen diese als faktorische Faktoren zur Bewertung der vollst\u00e4ndigen Funktionen der Anbieter verwendet.<\/p>\n<p><div id=\"attachment_289716\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-289716\" class=\"wp-image-289716 size-full\" src=\"https:\/\/blog.webex.com\/wp-content\/uploads\/2019\/07\/5d2f4d4aebaed-1.png\" sizes=\"auto, (max-width: 677px) 100vw, 677px\" srcset=\"https:\/\/blog.webex.com\/wp-content\/uploads\/2019\/07\/5d2f4d4aebaed-1-300x327.png 300w, https:\/\/blog.webex.com\/wp-content\/uploads\/2019\/07\/5d2f4d4aebaed-1.png 677w\" alt=\"Cisco wird im Globe des Oder f\u00fcr Intelligent Contact Center als f\u00fchrendes Unternehmen identifiziert\" width=\"677\" height=\"739\" \/><p id=\"caption-attachment-289716\" class=\"wp-caption-text\">Copyright \u00a9 2019 Copyright Research Inc. und\/oder seine angeschlossenen Tochtergesellschaften. Alle Rechte vorbehalten. Taste Research und der Research Globe sind Marken von Taste Research Inc.<\/p><\/div> Die Analyse von Roadmaps bewertete Schl\u00fcsselbereiche wie Markenbewusstsein, Produktstrategie, Markt verstehen, Managementteam, Marketing, Produkt-Roadmaps, Das Verst\u00e4ndnis f\u00fcr die Bed\u00fcrfnisse unserer <\/p>\n<p> Kunden, Vervollst\u00e4ndigung des Portfolio und <\/p>\n<p> Ausf\u00fchrung.<\/p>\n<p>Die Bewertung von Unternehmen wird im Rahmen des \u00dcbergangs von traditionellen standortbasierten L\u00f6sungen zu cloudbasierten, KI-basierten Angeboten bewertet. Das gibt unsere F\u00e4higkeiten in diesen wichtigen Bereichen eine besondere Bedeutung.<\/p>\n<p>Nach dem Bericht von Jim Lundy, Chefanalyst von Jim Lundy, an der Forschungsleitung: &#8222;Cisco investieren kontinuierlich in die lokalen Produkte f\u00fcr seine aktuellen Kunden und bietet ihnen einen Weg zur Cloud, zu dem auch Das Collaboration Flex-Lizenzierungsprogramm und erweiterte Cloud-Dienste geh\u00f6ren, die von Kunden vor Ort verbraucht werden k\u00f6nnen.&#8220;<\/p>\n<p>Dies sind einige der Haupt gr\u00fcnde f\u00fcr unsere F\u00fchrungskraft:<\/p>\n<p><strong>Cisco Brand Cisco ist bekannt f\u00fcr seine F\u00e4higkeit, umfangreiche Contact Center-Bereitstellungen f\u00fcr Unternehmen auszuf\u00fchren, sowie f\u00fcr unsere tiefere Vertrautheit mit den<\/strong>  IT-Anforderungen des Unternehmens. Unsere Marke ist weltweit bekannt f\u00fcr seine Innovation, umfangreiche Produkt- und Entwicklungsprozesse, offene Plattformen, digitale Umsetzung und die Zukunft der Arbeit.<\/p>\n<p><strong>Contact Center Market Share Leadership Seit 20 Jahren bieten wir weltweit f\u00fchrende Contact Center-Technologie \u00fcber ein umfangreiches Partnernetzwerk an, um die<\/strong>  Kundenzufriedenheit zu verbessern. Mit mehr als 3 Millionen Agenten in 36.000 verschiedenen Unternehmen machen uns dadurch zum Marktf\u00fchrer f\u00fcr Kontaktzentren \u2013 die Nummer eins in Nordamerika und die Nummer zwei weltweit.<\/p>\n<p><strong>Fokus auf AI Einer der Grundsteine unserer Produktstrategie ist die kontinuierliche Innovation, wie dies durch die Verbesserungen im Cognitive Contact Center, die wir Anfang des Jahres eingef\u00fchrt<\/strong>   <a href=\"https:\/\/blogs.cisco.com\/collaboration\/cognitive-contact-center\"><\/a> haben, belegt ist. Ein Beispiel daf\u00fcr ist unser <a href=\"https:\/\/blogs.cisco.com\/collaboration\/cisco-contact-center-google-ai\">intelligenter Cisco<\/a> Answers-Agent, der von Google Contact Center AI unterst\u00fctzt wird. Cisco Answers h\u00f6rt kundengespr\u00e4chen in Echtzeit und pr\u00e4sentiert dem Agenten proaktiv intelligente Vorschl\u00e4ge und andere relevante Daten, w\u00e4hrend er mit einem Kunden interagiert.<\/p>\n<p><strong>Flexible Cloud-, Standort- und Hybrid-Bereitstellungsoptionen<\/strong>  Unser Ansatz &#8222;Cloud first, not cloud only&#8220; hilft unseren Kunden vor Ort,<br \/>\n ihr Unternehmen weiterzuentwickeln. Jeder m\u00f6chte die hohen CAPEX-Kosten minimieren und von der kontinuierlichen Bereitstellung innovativer Funktionen, die durch die Cloud erm\u00f6glicht werden, profitieren. Unsere Kunden m\u00f6chten eine f\u00fchrende Position haben, m\u00f6chten aber auch ihre Investitionen sch\u00fctzen und von der stabilen Sicherheit und Stabilit\u00e4t profitieren, die sie mit infrastrukturbasierten Einrichtungen vor Ort haben. Cisco hat die Strategie und Hybrid-Cloud-Dienste, um diesen \u00dcbergang zu Wirklichkeit zu machen.<\/p>\n<p><strong>End-to-End-Verschl\u00fcsselung <\/strong><b>Cisco hat einen<\/b>  branchenf\u00fchrenden Ruf f\u00fcr Unternehmenssicherheit. Wir investieren weiterhin, um die Sicherheit Ihrer Kontaktzentren zu gew\u00e4hrleisten und sorgen daf\u00fcr, dass Kunden- und Unternehmensinformationen vollst\u00e4ndig gesch\u00fctzt sind.<\/p>\n<p><strong>Allgemeine Unified Communications- und Collaboration-Funktionen Wir verf\u00fcgen \u00fcber ein umfassendes und integriertes Portfolio mit umfassendem Fachwissen in allen Kommunikationsbereichen, von<\/strong>  Contact Center <a href=\"https:\/\/www.cisco.com\/c\/en\/us\/products\/contact-center\/index.html\">\u00fcber<\/a> Zusammenarbeit, Anrufe, Sicherheit, <\/p>\n<p> Netzwerk und Ger\u00e4te bis hin zu Ger\u00e4ten. Auf diese Weise k\u00f6nnen wir durch die Integration wichtiger Funktionen enorme Produktivit\u00e4tsvorteile und Kosteneinsparungen erzielen. Ein Beispiel daf\u00fcr ist, wie wir die Agentenerfahrung nahtlos in Webex Teams integrieren und Ihren Agenten einen intuitiven Zugriff auf Fachexperten au\u00dferhalb des Contact Centers bieten k\u00f6nnen, damit Sie Ihren Kunden einen besseren und schnelleren Service bieten k\u00f6nnen.<\/p>\n<blockquote><p>Weitere Informationen finden Sie im <a href=\"https:\/\/engage2demand.cisco.com\/LP=17033?ccid=cc001193&#038;oid=anrco017571\">Bericht 2019 Globe for Intelligent Contact<\/a> Center.<\/p>\n<p><a href=\"https:\/\/blogs.cisco.com\/collaboration\/cisco-is-selected-as-a-leader-in-aragons-globe-for-unified-communications-and-collaboration-for-the-second-consecutive-year\">Cisco wird zum zweiten Mal hintereinander als f\u00fchrender Anbieter f\u00fcr Unified Communications und Collaboration in der Welt der Welt ausgew\u00e4hlt<\/a><\/p><\/blockquote>\n<p>\u00a0<\/p>\n<p><a href=\"https:\/\/blogs.cisco.com\/collaboration\/cisco-is-identified-as-a-leader-in-aragons-globe-for-intelligent-contact-center-2020\"><br \/>\n  <strong>Aktualisiert Cisco wird zum zweiten Mal hintereinander als Marktf\u00fchrer im Globe des Unternehmens f\u00fcr Intelligent Contact Center ausgew\u00e4hlt (2020) Disclaimer zu<\/strong> <\/a>  <sub>   <em>Unternehmensforschung: Aragon Research wirbt nicht f\u00fcr Anbieter oder deren Produkte oder Dienstleistungen, auf die in seinen Forschungspublikationen verwiesen wird, und r\u00e4t Anwendern auch nicht, die am besten bewerteten Anbieter auszuw\u00e4hlen. Die Ver\u00f6ffentlichungen von Aragon Research geben die Meinung der Aragon Research and Advisory Services Organisation wieder und sind nicht als Tatsachenbehauptungen zu verstehen. Aragon Research stellt seine Forschungspublikationen und die darin enthaltenen Informationen im ver\u00f6ffentlichen Zustand und ohne jegliche Gew\u00e4hrleistung zur Verf\u00fcgung.<\/em><br \/>\n<\/sub><\/p>\n<hr \/>\n<p><strong>Erfahren Sie mehr \u00fcber die neuesten Innovationen von Cisco im Bereich der Intelligenz zur Verbesserung von Gesch\u00e4ftsergebnissen f\u00fcr Contact Centers Finden Sie weitere Informationen dazu, wo Cisco als Eines der Marktf\u00fchrer f\u00fcr<\/strong>  <a href=\"https:\/\/blogs.cisco.com\/collaboration\/ciscos-latest-innovations-in-artificial-intelligence-improve-contact-center-performance-and-enrich-customer-experiences\"><\/a>  <a href=\"https:\/\/blogs.cisco.com\/tag\/AragonLeader\">Ihr<\/a>  <a href=\"https:\/\/blogs.cisco.com\/collaboration\/is-your-contact-center-in-the-zone\">Contact Center &#8222;In der Zone&#8220; benannt wurde?<\/a><\/p>\n<p><a href=\"https:\/\/blogs.cisco.com\/collaboration\/join-our-live-webinar-introducing-webex-contact-center-enterprise\">Einf\u00fchrung in Webex Contact Center Enterprise [Webinar]<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cisco Contact Center wurde auf Grundlage der Strategie und Leistungsf\u00e4higkeit des weltweit anerkannten Branchenanalystenunternehmens Cisco Contact Research bewertet<\/p>\n","protected":false},"author":5452,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[1564,5263],"tags":[5829,4421,5266,6214,5264,4644,3851,5676,7987,4733],"class_list":["post-386148","post","type-post","status-publish","format-standard","hentry","category-kundenerfahrungen","category-zusammenarbeit","tag-auszeichnungen","tag-awards","tag-callcenter","tag-callcenter-as-a-service","tag-cisco-live-de","tag-cloud-kommunikation","tag-collaboration-solutions","tag-collaboration-losungen","tag-enterprise-contact-center-de","tag-kunstliche-intelligenz"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cisco wird im Aragon Globe als f\u00fchrendes Unternehmen f\u00fcr intelligente Contact Center eingestuft. | Webex Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.webex.com\/customer-experience\/cisco-is-identified-as-a-leader-in-aragons-globe-for-intelligent-contact-center\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cisco wird im Aragon Globe als f\u00fchrendes Unternehmen f\u00fcr intelligente Contact Center eingestuft. | Webex Blog\" \/>\n<meta property=\"og:description\" content=\"Cisco Contact Center wurde auf Grundlage der Strategie und Leistungsf\u00e4higkeit des weltweit anerkannten Branchenanalystenunternehmens Cisco Contact Research bewertet\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.webex.com\/customer-experience\/cisco-is-identified-as-a-leader-in-aragons-globe-for-intelligent-contact-center\/\" \/>\n<meta property=\"og:site_name\" content=\"Webex Blog\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-17T23:32:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.webex.com\/wp-content\/uploads\/2019\/07\/5d2f4d4aebaed-1.png\" \/>\n<meta name=\"author\" content=\"Vasili Triant\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Vasili Triant\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.webex.com\\\/customer-experience\\\/cisco-is-identified-as-a-leader-in-aragons-globe-for-intelligent-contact-center\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/customer-experience\\\/cisco-is-identified-as-a-leader-in-aragons-globe-for-intelligent-contact-center\\\/\"},\"author\":{\"name\":\"Vasili Triant\",\"@id\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/#\\\/schema\\\/person\\\/73aa49648cf49321d846ed086c28e471\"},\"headline\":\"Cisco wird im Aragon Globe als f\u00fchrendes Unternehmen f\u00fcr ...\",\"datePublished\":\"2019-07-17T23:32:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/customer-experience\\\/cisco-is-identified-as-a-leader-in-aragons-globe-for-intelligent-contact-center\\\/\"},\"wordCount\":965,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/customer-experience\\\/cisco-is-identified-as-a-leader-in-aragons-globe-for-intelligent-contact-center\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.webex.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/5d2f4d4aebaed-1.png\",\"keywords\":[\"Auszeichnungen\",\"Awards\",\"Callcenter\",\"Callcenter as a Service\",\"Cisco Live\",\"Cloud-Kommunikation\",\"Collaboration Solutions\",\"Collaboration-L\u00f6sungen\",\"Enterprise Contact Center\",\"k\u00fcnstliche Intelligenz\"],\"articleSection\":[\"Kundenerfahrungen\u00a0\",\"Zusammenarbeit\"],\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.webex.com\\\/customer-experience\\\/cisco-is-identified-as-a-leader-in-aragons-globe-for-intelligent-contact-center\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.webex.com\\\/customer-experience\\\/cisco-is-identified-as-a-leader-in-aragons-globe-for-intelligent-contact-center\\\/\",\"url\":\"https:\\\/\\\/blog.webex.com\\\/customer-experience\\\/cisco-is-identified-as-a-leader-in-aragons-globe-for-intelligent-contact-center\\\/\",\"name\":\"Cisco wird im Aragon Globe als f\u00fchrendes Unternehmen f\u00fcr intelligente Contact Center eingestuft. | Webex Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/customer-experience\\\/cisco-is-identified-as-a-leader-in-aragons-globe-for-intelligent-contact-center\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/customer-experience\\\/cisco-is-identified-as-a-leader-in-aragons-globe-for-intelligent-contact-center\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.webex.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/5d2f4d4aebaed-1.png\",\"datePublished\":\"2019-07-17T23:32:41+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/#\\\/schema\\\/person\\\/73aa49648cf49321d846ed086c28e471\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/customer-experience\\\/cisco-is-identified-as-a-leader-in-aragons-globe-for-intelligent-contact-center\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.webex.com\\\/customer-experience\\\/cisco-is-identified-as-a-leader-in-aragons-globe-for-intelligent-contact-center\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/blog.webex.com\\\/customer-experience\\\/cisco-is-identified-as-a-leader-in-aragons-globe-for-intelligent-contact-center\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.webex.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/5d2f4d4aebaed-1.png\",\"contentUrl\":\"https:\\\/\\\/blog.webex.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/5d2f4d4aebaed-1.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.webex.com\\\/customer-experience\\\/cisco-is-identified-as-a-leader-in-aragons-globe-for-intelligent-contact-center\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.webex.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cisco wird im Aragon Globe als f\u00fchrendes Unternehmen f\u00fcr ...\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/\",\"name\":\"Webex Blog\",\"description\":\"Webex by Cisco powers collaboration through industry-leading video conferencing, cloud calling and contact center solutions\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/#\\\/schema\\\/person\\\/73aa49648cf49321d846ed086c28e471\",\"name\":\"Vasili Triant\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/91eff3738b5932b14c3da1fe3ef7732ce1845d9979c2fbdc600dadd35b68cc69?s=96&d=wp_user_avatar&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/91eff3738b5932b14c3da1fe3ef7732ce1845d9979c2fbdc600dadd35b68cc69?s=96&d=wp_user_avatar&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/91eff3738b5932b14c3da1fe3ef7732ce1845d9979c2fbdc600dadd35b68cc69?s=96&d=wp_user_avatar&r=g\",\"caption\":\"Vasili Triant\"},\"description\":\"A customer service and telecommunications veteran and visionary, Vasili has tremendous experience as a 20-year customer service and telecommunications veteran. Vasili resides in Austin, Texas with his wife and blended family of eight kids. He volunteers with the Lake Travis Youth Sports Association where he is a Board Member and has coached football and baseball for the past six years. Vasili has a Bachelor in Business Administration from the University of San Diego.\",\"url\":\"https:\\\/\\\/blog.webex.com\\\/de\\\/contributors\\\/vasilitriant\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cisco wird im Aragon Globe als f\u00fchrendes Unternehmen f\u00fcr intelligente Contact Center eingestuft. | Webex Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.webex.com\/customer-experience\/cisco-is-identified-as-a-leader-in-aragons-globe-for-intelligent-contact-center\/","og_locale":"de_DE","og_type":"article","og_title":"Cisco wird im Aragon Globe als f\u00fchrendes Unternehmen f\u00fcr intelligente Contact Center eingestuft. | Webex Blog","og_description":"Cisco Contact Center wurde auf Grundlage der Strategie und Leistungsf\u00e4higkeit des weltweit anerkannten Branchenanalystenunternehmens Cisco Contact Research bewertet","og_url":"https:\/\/blog.webex.com\/customer-experience\/cisco-is-identified-as-a-leader-in-aragons-globe-for-intelligent-contact-center\/","og_site_name":"Webex Blog","article_published_time":"2019-07-17T23:32:41+00:00","og_image":[{"url":"https:\/\/blog.webex.com\/wp-content\/uploads\/2019\/07\/5d2f4d4aebaed-1.png","type":"","width":"","height":""}],"author":"Vasili Triant","twitter_misc":{"Verfasst von":"Vasili Triant","Gesch\u00e4tzte Lesezeit":"5 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.webex.com\/customer-experience\/cisco-is-identified-as-a-leader-in-aragons-globe-for-intelligent-contact-center\/#article","isPartOf":{"@id":"https:\/\/blog.webex.com\/customer-experience\/cisco-is-identified-as-a-leader-in-aragons-globe-for-intelligent-contact-center\/"},"author":{"name":"Vasili Triant","@id":"https:\/\/blog.webex.com\/es\/#\/schema\/person\/73aa49648cf49321d846ed086c28e471"},"headline":"Cisco wird im Aragon Globe als f\u00fchrendes Unternehmen f\u00fcr ...","datePublished":"2019-07-17T23:32:41+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.webex.com\/customer-experience\/cisco-is-identified-as-a-leader-in-aragons-globe-for-intelligent-contact-center\/"},"wordCount":965,"commentCount":0,"image":{"@id":"https:\/\/blog.webex.com\/customer-experience\/cisco-is-identified-as-a-leader-in-aragons-globe-for-intelligent-contact-center\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.webex.com\/wp-content\/uploads\/2019\/07\/5d2f4d4aebaed-1.png","keywords":["Auszeichnungen","Awards","Callcenter","Callcenter as a Service","Cisco Live","Cloud-Kommunikation","Collaboration Solutions","Collaboration-L\u00f6sungen","Enterprise Contact Center","k\u00fcnstliche Intelligenz"],"articleSection":["Kundenerfahrungen\u00a0","Zusammenarbeit"],"inLanguage":"de-DE","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.webex.com\/customer-experience\/cisco-is-identified-as-a-leader-in-aragons-globe-for-intelligent-contact-center\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.webex.com\/customer-experience\/cisco-is-identified-as-a-leader-in-aragons-globe-for-intelligent-contact-center\/","url":"https:\/\/blog.webex.com\/customer-experience\/cisco-is-identified-as-a-leader-in-aragons-globe-for-intelligent-contact-center\/","name":"Cisco wird im Aragon Globe als f\u00fchrendes Unternehmen f\u00fcr intelligente Contact Center eingestuft. | Webex Blog","isPartOf":{"@id":"https:\/\/blog.webex.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.webex.com\/customer-experience\/cisco-is-identified-as-a-leader-in-aragons-globe-for-intelligent-contact-center\/#primaryimage"},"image":{"@id":"https:\/\/blog.webex.com\/customer-experience\/cisco-is-identified-as-a-leader-in-aragons-globe-for-intelligent-contact-center\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.webex.com\/wp-content\/uploads\/2019\/07\/5d2f4d4aebaed-1.png","datePublished":"2019-07-17T23:32:41+00:00","author":{"@id":"https:\/\/blog.webex.com\/es\/#\/schema\/person\/73aa49648cf49321d846ed086c28e471"},"breadcrumb":{"@id":"https:\/\/blog.webex.com\/customer-experience\/cisco-is-identified-as-a-leader-in-aragons-globe-for-intelligent-contact-center\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.webex.com\/customer-experience\/cisco-is-identified-as-a-leader-in-aragons-globe-for-intelligent-contact-center\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/blog.webex.com\/customer-experience\/cisco-is-identified-as-a-leader-in-aragons-globe-for-intelligent-contact-center\/#primaryimage","url":"https:\/\/blog.webex.com\/wp-content\/uploads\/2019\/07\/5d2f4d4aebaed-1.png","contentUrl":"https:\/\/blog.webex.com\/wp-content\/uploads\/2019\/07\/5d2f4d4aebaed-1.png"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.webex.com\/customer-experience\/cisco-is-identified-as-a-leader-in-aragons-globe-for-intelligent-contact-center\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.webex.com\/de\/"},{"@type":"ListItem","position":2,"name":"Cisco wird im Aragon Globe als f\u00fchrendes Unternehmen f\u00fcr ..."}]},{"@type":"WebSite","@id":"https:\/\/blog.webex.com\/es\/#website","url":"https:\/\/blog.webex.com\/es\/","name":"Webex Blog","description":"Webex by Cisco powers collaboration through industry-leading video conferencing, cloud calling and contact center solutions","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.webex.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Person","@id":"https:\/\/blog.webex.com\/es\/#\/schema\/person\/73aa49648cf49321d846ed086c28e471","name":"Vasili Triant","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/secure.gravatar.com\/avatar\/91eff3738b5932b14c3da1fe3ef7732ce1845d9979c2fbdc600dadd35b68cc69?s=96&d=wp_user_avatar&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/91eff3738b5932b14c3da1fe3ef7732ce1845d9979c2fbdc600dadd35b68cc69?s=96&d=wp_user_avatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/91eff3738b5932b14c3da1fe3ef7732ce1845d9979c2fbdc600dadd35b68cc69?s=96&d=wp_user_avatar&r=g","caption":"Vasili Triant"},"description":"A customer service and telecommunications veteran and visionary, Vasili has tremendous experience as a 20-year customer service and telecommunications veteran. Vasili resides in Austin, Texas with his wife and blended family of eight kids. He volunteers with the Lake Travis Youth Sports Association where he is a Board Member and has coached football and baseball for the past six years. Vasili has a Bachelor in Business Administration from the University of San Diego.","url":"https:\/\/blog.webex.com\/de\/contributors\/vasilitriant\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.webex.com\/de\/wp-json\/wp\/v2\/posts\/386148","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.webex.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.webex.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.webex.com\/de\/wp-json\/wp\/v2\/users\/5452"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.webex.com\/de\/wp-json\/wp\/v2\/comments?post=386148"}],"version-history":[{"count":0,"href":"https:\/\/blog.webex.com\/de\/wp-json\/wp\/v2\/posts\/386148\/revisions"}],"wp:attachment":[{"href":"https:\/\/blog.webex.com\/de\/wp-json\/wp\/v2\/media?parent=386148"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.webex.com\/de\/wp-json\/wp\/v2\/categories?post=386148"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.webex.com\/de\/wp-json\/wp\/v2\/tags?post=386148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}