{"id":16289,"date":"2020-08-18T13:20:16","date_gmt":"2020-08-18T20:20:16","guid":{"rendered":"https:\/\/cisco2393.wpengine.com\/uncategorized\/novedades-de-webex-meetings-agosto-2020-mayor-seguridad-y-mejora-de-los-elementos-multimedia-fondos-personalizados-y-modo-musica\/"},"modified":"2021-10-15T13:42:29","modified_gmt":"2021-10-15T20:42:29","slug":"novedades-de-webex-meetings-agosto-2020-mayor-seguridad-y-mejora-de-los-elementos-multimedia-fondos-personalizados-y-modo-musica","status":"publish","type":"post","link":"https:\/\/blog.webex.com\/es\/colaboracion\/videoconferencias\/novedades-de-webex-meetings-agosto-2020-mayor-seguridad-y-mejora-de-los-elementos-multimedia-fondos-personalizados-y-modo-musica\/","title":{"rendered":"Novedades de Webex Meetings Agosto 2020 Mayor seguridad y mejora ..."},"content":{"rendered":"<p><strong>Agosto: mientras esperamos la llegada de una nueva estaci\u00f3n, lanzamos nuevas caracter\u00edsticas de Webex Meetings. Se est\u00e1n preparando grandes cosas para Webex, y estamos muy contentos de compartirlas con ustedes. En los pr\u00f3ximos meses, ver\u00e1 mejoras importantes. Este mes, las actualizaciones de caracter\u00edsticas incluyen mayor seguridad, vista de cuadr\u00edcula, modo m\u00fasica y mucho m\u00e1s. Le ofrece m\u00e1s flexibilidad para trabajar desde cualquier lugar.<\/strong><\/p>\n<h2><strong>Mejora de la seguridad y de los elementos multimedia <\/strong><\/h2>\n<p><strong>Cifrado CipherSuite: <\/strong>con la actualizaci\u00f3n de este mes, estamos actualizando el cifrado de Webex Meetings de AES-128-CBC a AES-256-GCM. AES-256-GCM es el mejor cifrado disponible y proporciona una mayor protecci\u00f3n de los datos de las reuniones y resistencia a la manipulaci\u00f3n.<\/p>\n<p><strong>Modo m\u00fasica en Meetings y Events: <\/strong>ahora puede reproducir m\u00fasica durante su reuni\u00f3n y transmitir la riqueza de las melod\u00edas a todos los participantes. Esto es especialmente importante cuando se ofrece un concierto virtual o clases de m\u00fasica a trav\u00e9s de Webex. Para habilitar esta caracter\u00edstica, solo tiene que pulsar Ctrl+Shift+M para activar el modo m\u00fasica o hacer clic en \u201caudio\u201d en la barra de men\u00fas y marcar \u201cmodo m\u00fasica\u201d. \u00a1Si\u00e9ntese, rel\u00e1jese y disfrute!<\/p>\n<p><strong>V\u00eddeo fluido de alta resoluci\u00f3n incluso con un 50% de p\u00e9rdida de paquetes: <\/strong>la actualizaci\u00f3n de caracter\u00edsticas de este mes mantiene el flujo de v\u00eddeo en alta resoluci\u00f3n incluso si la red experimenta repentinamente una p\u00e9rdida significativa de paquetes. Por ejemplo, cuando sus hijos empiezan a jugar a los videojuegos o cuando empiezan las clases remotas para todos los miembros de la familia. Antes, cuando las condiciones de la red empeoraban considerablemente, el v\u00eddeo mostraba la imagen en miniatura. Ahora, con las mejoras de los elementos multimedia de Webex, ya no tendr\u00e1 que interrumpir sus reuniones si tiene una mala conexi\u00f3n.<\/p>\n<p><strong>Escritorio<\/strong><\/p>\n<p><strong>Fondo virtual personalizado: <\/strong>en Windows y Mac, al seleccionar un fondo virtual, ahora puede elegir su propia imagen del escritorio para utilizarla. Esta caracter\u00edstica a\u00f1ade un nivel adicional de personalizaci\u00f3n a sus reuniones. \u00bfTiene un lugar de vacaciones favorito? A\u00f1\u00e1dalo a sus fondos virtuales y mu\u00e9strelo en sus reuniones. Los fondos personalizados ya son compatibles con iOS y Android.<\/p>\n<p><a href=\"https:\/\/blog.webex.com\/wp-content\/uploads\/2020\/08\/Feature-Planning-Meeting-e1597774568761.png\"><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-7238\" src=\"https:\/\/blog.webex.com\/wp-content\/uploads\/2020\/08\/Feature-Planning-Meeting-e1597774568761.png\" alt=\"Fondo virtual personalizado con Webex Meetings\" width=\"470\" height=\"390\" srcset=\"https:\/\/blog.webex.com\/wp-content\/uploads\/2020\/08\/Feature-Planning-Meeting-e1597774568761.png 470w, https:\/\/blog.webex.com\/wp-content\/uploads\/2020\/08\/Feature-Planning-Meeting-e1597774568761-300x249.png 300w\" sizes=\"auto, (max-width: 470px) 100vw, 470px\" \/><br \/>\n<\/a><\/p>\n<p><strong>Vista de cuadr\u00edcula predeterminada: <\/strong>ahora, en Webex Meetings, la vista de cuadr\u00edcula es la configuraci\u00f3n predeterminada cuando nadie est\u00e1 compartiendo contenido, lo que hace que los participantes de la reuni\u00f3n aparezcan por igual. Esto crea una mayor sensaci\u00f3n de colaboraci\u00f3n. Si prefiere ver al orador activo, puede cambiar la vista a Vista de v\u00eddeo del orador activo u Orador activo y Vista de v\u00eddeo en miniatura desde los controles de la parte superior derecha.<\/p>\n<p><a href=\"https:\/\/blog.webex.com\/wp-content\/uploads\/2020\/08\/Grid-View-by-default-in-Webex-Meetings.png\"><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-7239\" src=\"https:\/\/blog.webex.com\/wp-content\/uploads\/2020\/08\/Grid-View-by-default-in-Webex-Meetings.png\" alt=\"Vista de cuadr\u00edcula predeterminada en Webex Meetings\" width=\"720\" height=\"406\" srcset=\"https:\/\/blog.webex.com\/wp-content\/uploads\/2020\/08\/Grid-View-by-default-in-Webex-Meetings.png 720w, https:\/\/blog.webex.com\/wp-content\/uploads\/2020\/08\/Grid-View-by-default-in-Webex-Meetings-300x169.png 300w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><br \/>\n<\/a><\/p>\n<p><strong>Mejora de la autovisualizaci\u00f3n: <\/strong>ahora su autovisualizaci\u00f3n se muestra de forma predeterminada en la cuadr\u00edcula de v\u00eddeo con los v\u00eddeos de los dem\u00e1s participantes. Su v\u00eddeo aparecer\u00e1 a la par de sus colegas en lugar de flotar en la esquina. Esto crea una experiencia de reuni\u00f3n m\u00e1s natural. Sin embargo, si prefiere hacer flotar la autovisualizaci\u00f3n, simplemente haga clic en \u201cMostrar mi autovisualizaci\u00f3n en una ventana flotante\u201d.<\/p>\n<p><a href=\"https:\/\/blog.webex.com\/wp-content\/uploads\/2020\/08\/Screen-Shot-2020-08-18-at-11.38.05-AM-e1597776028589.png\"><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-7240\" src=\"https:\/\/blog.webex.com\/wp-content\/uploads\/2020\/08\/Screen-Shot-2020-08-18-at-11.38.05-AM-e1597776028589.png\" alt=\"Mejora de la autovisualizaci\u00f3n\" width=\"1880\" height=\"536\" srcset=\"https:\/\/blog.webex.com\/wp-content\/uploads\/2020\/08\/Screen-Shot-2020-08-18-at-11.38.05-AM-e1597776028589.png 980w, https:\/\/blog.webex.com\/wp-content\/uploads\/2020\/08\/Screen-Shot-2020-08-18-at-11.38.05-AM-e1597776028589-300x86.png 300w, https:\/\/blog.webex.com\/wp-content\/uploads\/2020\/08\/Screen-Shot-2020-08-18-at-11.38.05-AM-e1597776028589-1024x292.png 1024w, https:\/\/blog.webex.com\/wp-content\/uploads\/2020\/08\/Screen-Shot-2020-08-18-at-11.38.05-AM-e1597776028589-1536x438.png 1536w, https:\/\/blog.webex.com\/wp-content\/uploads\/2020\/08\/Screen-Shot-2020-08-18-at-11.38.05-AM-e1597776028589-768x219.png 768w\" sizes=\"auto, (max-width: 1880px) 100vw, 1880px\" \/><br \/>\n<\/a><\/p>\n<p><strong>Ocultar a los participantes que no tienen v\u00eddeo: <\/strong>ahora, puede ocultar a los participantes de la reuni\u00f3n que tienen el v\u00eddeo desactivado y optar por centrar la reuni\u00f3n en los que tienen el v\u00eddeo activado. Esto crea una experiencia de reuni\u00f3n m\u00e1s atractiva y le permite ver a los participantes a trav\u00e9s del v\u00eddeo en su reuni\u00f3n.<\/p>\n<p><a href=\"https:\/\/blog.webex.com\/wp-content\/uploads\/2020\/08\/Hide-non-video-Participants-e1597776185126.png\"><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-7242\" src=\"https:\/\/blog.webex.com\/wp-content\/uploads\/2020\/08\/Hide-non-video-Participants-e1597776185126.png\" alt=\"Ocultar a los participantes que no tienen v\u00eddeo\" width=\"470\" height=\"250\" srcset=\"https:\/\/blog.webex.com\/wp-content\/uploads\/2020\/08\/Hide-non-video-Participants-e1597776185126.png 470w, https:\/\/blog.webex.com\/wp-content\/uploads\/2020\/08\/Hide-non-video-Participants-e1597776185126-300x160.png 300w\" sizes=\"auto, (max-width: 470px) 100vw, 470px\" \/><br \/>\n<\/a><\/p>\n<p><strong>Pulsar para hablar:<\/strong> cuando tenga el audio desactivado, ahora puede mantener pulsada la barra espaciadora para reactivarlo moment\u00e1neamente. En lugar de dar vueltas tratando de reactivar el audio, solo tiene que mantener pulsada la barra espaciadora cuando quiera hablar. Suelte la barra espaciadora para volver a desactivarlo. La flexibilidad de trabajar desde cualquier lugar puede conllevar m\u00e1s ruidos de fondo. A veces, es mejor permanecer con el audio desactivado hasta que sea necesario hablar. Con la nueva caracter\u00edstica de pulsar para hablar, puede permanecer silenciado, limitar el ruido de fondo y simplemente intervenir cuando sea necesario.<\/p>\n<p><a href=\"https:\/\/blog.webex.com\/wp-content\/uploads\/2020\/08\/push-to-talk--e1597776337444.png\"><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-7243\" src=\"https:\/\/blog.webex.com\/wp-content\/uploads\/2020\/08\/push-to-talk--e1597776337444.png\" alt=\"Pulsar para hablar\" width=\"614\" height=\"328\" srcset=\"https:\/\/blog.webex.com\/wp-content\/uploads\/2020\/08\/push-to-talk--e1597776337444.png 614w, https:\/\/blog.webex.com\/wp-content\/uploads\/2020\/08\/push-to-talk--e1597776337444-300x160.png 300w\" sizes=\"auto, (max-width: 614px) 100vw, 614px\" \/><br \/>\n<\/a><\/p>\n<h2><strong>Integraci\u00f3n del escritorio virtual <\/strong><\/h2>\n<p><strong>Compatibilidad con doble monitor: <\/strong>ahora, Webex admite una configuraci\u00f3n de doble monitor para Windows y Linux (Ubuntu + eLux) en escritorios virtuales. Si utiliza un monitor doble, podr\u00e1 ampliar la visualizaci\u00f3n de su sesi\u00f3n para poder utilizar ambos monitores.<\/p>\n<p><strong>Dispositivos m\u00f3viles <\/strong><\/p>\n<p><strong>IOS<\/strong>: ahora, es a\u00fan m\u00e1s f\u00e1cil y r\u00e1pido acceder a Webex Meetings desde sus dispositivos iOS. Solo tiene que utilizar su ID de Apple. Una contrase\u00f1a menos que recordar.<\/p>\n<p>Y por \u00faltimo, pero no menos importante&#8230;<\/p>\n<p><strong>Android<\/strong>: Webex Meetings es el PRIMER servicio de conferencias que ofrece transmisi\u00f3n en directo para Android. Al igual que en la aplicaci\u00f3n de escritorio, puede iniciar una transmisi\u00f3n en directo desde una fuente externa como Facebook, YouTube o IBM directamente desde su dispositivo m\u00f3vil y expandir significativamente el alcance de su audiencia.<\/p>\n<blockquote><p>Para obtener m\u00e1s informaci\u00f3n sobre estas caracter\u00edsticas, visite el <a href=\"https:\/\/help.webex.com\/en-us\/xcwws1\/What-s-New-for-the-Latest-Versions-of-Webex-Meetings#id_137328\">portal de ayuda de Webex<\/a><\/p><\/blockquote>\n<p><strong>M\u00e1s informaci\u00f3n<\/strong><\/p>\n<p><a href=\"\/?tag=MeetingsUpdates\">Vea todas las actualizaciones de Webex Meetings aqu\u00ed<\/a><\/p>\n<p><a href=\"https:\/\/blog.webex.com\/video-conferencing\/secure-first-party-recording-transcripts-in-webex-meetings\/\">Transcripciones de grabaciones seguras y de primera mano en Webex Meetings<\/a><\/p>\n<p><a href=\"https:\/\/blog.webex.com\/es\/videoconferencias\/novedades-de-webex-meetings-fondos-virtuales-en-windows-mac-android-y-mas-julio-2020\/\">Actualizaci\u00f3n de julio de 2020 de Webex Meetings: Fondos virtuales en Windows, Mac, Android y m\u00e1s: Julio 2020<\/a><\/p>\n<p><a href=\"https:\/\/blogs.cisco.com\/collaboration\/webex-meetings-june-2020-update-transcriptions-background-blur-and-mobile-grid-view\">Actualizaci\u00f3n de junio de 2020 de Webex Meetings: Transcripciones, desenfoque del fondo y vista de cuadr\u00edcula<\/a><\/p>\n<p><strong>\u00bfNecesita m\u00e1s ayuda?<\/strong><\/p>\n<p>\u00bfQu\u00e9 le gustar\u00eda hacer?<\/p>\n<p><a href=\"https:\/\/globalpage-prod.webex.com\/join?surl=https%3A%2F%2Fsignin.webex.com%2Fcollabs%2F%23%2Fmeetings%2Fjoinbynumber%3F\">\u00danase a una reuni\u00f3n en l\u00ednea de Webex<\/a><\/p>\n<p><a href=\"https:\/\/www.webex.com\/video-conferencing\">Obtenga m\u00e1s informaci\u00f3n sobre las reuniones web y las videoconferencias<\/a><\/p>\n<p><a href=\"https:\/\/www.webex.com\/video-conferencing\">Reg\u00edstrese en Webex<\/a><\/p>\n<p>Visite <a href=\"https:\/\/www.webex.com\/\">nuestra p\u00e1gina de inicio<\/a> o <a href=\"https:\/\/www.webex.com\/contact-us.html\">p\u00f3ngase en contacto<\/a> con nosotros directamente para obtener ayuda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Agosto: mientras esperamos la llegada de una nueva estaci\u00f3n, lanzamos nuevas caracter\u00edsticas de Webex Meetings. Se est\u00e1n preparando grandes cosas para Webex, y estamos muy contentos de compartirlas con ustedes.<\/p>\n","protected":false},"author":5379,"featured_media":417370,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[1497],"tags":[3851,1415,5448],"class_list":["post-16289","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-videoconferencias","tag-collaboration-solutions","tag-herramientas-de-colaboracion","tag-soluciones-de-colaboracion"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Novedades de Webex Meetings Agosto 2020 Mayor seguridad y mejora de los elementos multimedia, fondos personalizados y modo m\u00fasica | Webex Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.webex.com\/collaboration\/video-conferencing\/webex-meetings-august-2020-update-increased-security-and-media-enhancement-custom-backgrounds-and-music-mode\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Novedades de Webex Meetings Agosto 2020 Mayor seguridad y mejora de los elementos multimedia, fondos personalizados y modo m\u00fasica | Webex Blog\" \/>\n<meta property=\"og:description\" content=\"Agosto: mientras esperamos la llegada de una nueva estaci\u00f3n, lanzamos nuevas caracter\u00edsticas de Webex Meetings. Se est\u00e1n preparando grandes cosas para Webex, y estamos muy contentos de compartirlas con ustedes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.webex.com\/collaboration\/video-conferencing\/webex-meetings-august-2020-update-increased-security-and-media-enhancement-custom-backgrounds-and-music-mode\/\" \/>\n<meta property=\"og:site_name\" content=\"Webex Blog\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-18T20:20:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-15T20:42:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.webex.com\/wp-content\/uploads\/2020\/04\/woman-in-home-office-directly-facing-the-camera-and-smiling-feature.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"980\" \/>\n\t<meta property=\"og:image:height\" content=\"520\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Connie Tang\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Connie Tang\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.webex.com\\\/collaboration\\\/video-conferencing\\\/webex-meetings-august-2020-update-increased-security-and-media-enhancement-custom-backgrounds-and-music-mode\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/collaboration\\\/video-conferencing\\\/webex-meetings-august-2020-update-increased-security-and-media-enhancement-custom-backgrounds-and-music-mode\\\/\"},\"author\":{\"name\":\"Connie Tang\",\"@id\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/#\\\/schema\\\/person\\\/618264681e2ca0a8a9be532ba4c55d9e\"},\"headline\":\"Novedades de Webex Meetings Agosto 2020 Mayor seguridad y mejora ...\",\"datePublished\":\"2020-08-18T20:20:16+00:00\",\"dateModified\":\"2021-10-15T20:42:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/collaboration\\\/video-conferencing\\\/webex-meetings-august-2020-update-increased-security-and-media-enhancement-custom-backgrounds-and-music-mode\\\/\"},\"wordCount\":1009,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/collaboration\\\/video-conferencing\\\/webex-meetings-august-2020-update-increased-security-and-media-enhancement-custom-backgrounds-and-music-mode\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.webex.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/woman-in-home-office-directly-facing-the-camera-and-smiling-feature.jpg\",\"keywords\":[\"Collaboration Solutions\",\"herramientas de colaboraci\u00f3n\",\"Soluciones de colaboraci\u00f3n\"],\"articleSection\":[\"Videoconferencias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.webex.com\\\/collaboration\\\/video-conferencing\\\/webex-meetings-august-2020-update-increased-security-and-media-enhancement-custom-backgrounds-and-music-mode\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.webex.com\\\/collaboration\\\/video-conferencing\\\/webex-meetings-august-2020-update-increased-security-and-media-enhancement-custom-backgrounds-and-music-mode\\\/\",\"url\":\"https:\\\/\\\/blog.webex.com\\\/collaboration\\\/video-conferencing\\\/webex-meetings-august-2020-update-increased-security-and-media-enhancement-custom-backgrounds-and-music-mode\\\/\",\"name\":\"Novedades de Webex Meetings Agosto 2020 Mayor seguridad y mejora de los elementos multimedia, fondos personalizados y modo m\u00fasica | Webex Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/collaboration\\\/video-conferencing\\\/webex-meetings-august-2020-update-increased-security-and-media-enhancement-custom-backgrounds-and-music-mode\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/collaboration\\\/video-conferencing\\\/webex-meetings-august-2020-update-increased-security-and-media-enhancement-custom-backgrounds-and-music-mode\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.webex.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/woman-in-home-office-directly-facing-the-camera-and-smiling-feature.jpg\",\"datePublished\":\"2020-08-18T20:20:16+00:00\",\"dateModified\":\"2021-10-15T20:42:29+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/#\\\/schema\\\/person\\\/618264681e2ca0a8a9be532ba4c55d9e\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/collaboration\\\/video-conferencing\\\/webex-meetings-august-2020-update-increased-security-and-media-enhancement-custom-backgrounds-and-music-mode\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.webex.com\\\/collaboration\\\/video-conferencing\\\/webex-meetings-august-2020-update-increased-security-and-media-enhancement-custom-backgrounds-and-music-mode\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/blog.webex.com\\\/collaboration\\\/video-conferencing\\\/webex-meetings-august-2020-update-increased-security-and-media-enhancement-custom-backgrounds-and-music-mode\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.webex.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/woman-in-home-office-directly-facing-the-camera-and-smiling-feature.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.webex.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/woman-in-home-office-directly-facing-the-camera-and-smiling-feature.jpg\",\"width\":980,\"height\":520,\"caption\":\"Woman In Home Office Directly Facing The Camera And Smiling | Feature\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.webex.com\\\/collaboration\\\/video-conferencing\\\/webex-meetings-august-2020-update-increased-security-and-media-enhancement-custom-backgrounds-and-music-mode\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Novedades de Webex Meetings Agosto 2020 Mayor seguridad y mejora ...\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/\",\"name\":\"Webex Blog\",\"description\":\"Webex by Cisco powers collaboration through industry-leading video conferencing, cloud calling and contact center solutions\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/#\\\/schema\\\/person\\\/618264681e2ca0a8a9be532ba4c55d9e\",\"name\":\"Connie Tang\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/522be562ef749beca5ff70ed64aac78c4b104dddd2b57c4bdc506f537daedce2?s=96&d=wp_user_avatar&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/522be562ef749beca5ff70ed64aac78c4b104dddd2b57c4bdc506f537daedce2?s=96&d=wp_user_avatar&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/522be562ef749beca5ff70ed64aac78c4b104dddd2b57c4bdc506f537daedce2?s=96&d=wp_user_avatar&r=g\",\"caption\":\"Connie Tang\"},\"description\":\"Connie Tang is Senior Director of Product Management with Contact Center, Developer Platform and Integrations at Cisco. She drives the product direction of Contact Center AI automation and developer experiences so that third party developers can easily leverage the Webex platform to simplify work flows and adapt to hybrid work. Connie and her team work to extend the reach of Webex Meetings, Calling, Contact Center, Messaging and Devices through integrations with strategic partners such as Microsoft, Google, and Salesforce. She holds a number of patents in video and conferencing technologies, and has received Cisco awards for Excellence in Collaboration. Connie has a Master of Science degree in Management Science and Engineering, as well as a Bachelor of Arts and Science degree in Economics and Management Science and Engineering from Stanford University.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/connie-tang-1504a7\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/home?lang=en\"],\"url\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/contributors\\\/connietang-2\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Novedades de Webex Meetings Agosto 2020 Mayor seguridad y mejora de los elementos multimedia, fondos personalizados y modo m\u00fasica | Webex Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.webex.com\/collaboration\/video-conferencing\/webex-meetings-august-2020-update-increased-security-and-media-enhancement-custom-backgrounds-and-music-mode\/","og_locale":"es_ES","og_type":"article","og_title":"Novedades de Webex Meetings Agosto 2020 Mayor seguridad y mejora de los elementos multimedia, fondos personalizados y modo m\u00fasica | Webex Blog","og_description":"Agosto: mientras esperamos la llegada de una nueva estaci\u00f3n, lanzamos nuevas caracter\u00edsticas de Webex Meetings. Se est\u00e1n preparando grandes cosas para Webex, y estamos muy contentos de compartirlas con ustedes.","og_url":"https:\/\/blog.webex.com\/collaboration\/video-conferencing\/webex-meetings-august-2020-update-increased-security-and-media-enhancement-custom-backgrounds-and-music-mode\/","og_site_name":"Webex Blog","article_published_time":"2020-08-18T20:20:16+00:00","article_modified_time":"2021-10-15T20:42:29+00:00","og_image":[{"width":980,"height":520,"url":"https:\/\/blog.webex.com\/wp-content\/uploads\/2020\/04\/woman-in-home-office-directly-facing-the-camera-and-smiling-feature.jpg","type":"image\/jpeg"}],"author":"Connie Tang","twitter_misc":{"Escrito por":"Connie Tang","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.webex.com\/collaboration\/video-conferencing\/webex-meetings-august-2020-update-increased-security-and-media-enhancement-custom-backgrounds-and-music-mode\/#article","isPartOf":{"@id":"https:\/\/blog.webex.com\/collaboration\/video-conferencing\/webex-meetings-august-2020-update-increased-security-and-media-enhancement-custom-backgrounds-and-music-mode\/"},"author":{"name":"Connie Tang","@id":"https:\/\/blog.webex.com\/es\/#\/schema\/person\/618264681e2ca0a8a9be532ba4c55d9e"},"headline":"Novedades de Webex Meetings Agosto 2020 Mayor seguridad y mejora ...","datePublished":"2020-08-18T20:20:16+00:00","dateModified":"2021-10-15T20:42:29+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.webex.com\/collaboration\/video-conferencing\/webex-meetings-august-2020-update-increased-security-and-media-enhancement-custom-backgrounds-and-music-mode\/"},"wordCount":1009,"commentCount":0,"image":{"@id":"https:\/\/blog.webex.com\/collaboration\/video-conferencing\/webex-meetings-august-2020-update-increased-security-and-media-enhancement-custom-backgrounds-and-music-mode\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.webex.com\/wp-content\/uploads\/2020\/04\/woman-in-home-office-directly-facing-the-camera-and-smiling-feature.jpg","keywords":["Collaboration Solutions","herramientas de colaboraci\u00f3n","Soluciones de colaboraci\u00f3n"],"articleSection":["Videoconferencias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.webex.com\/collaboration\/video-conferencing\/webex-meetings-august-2020-update-increased-security-and-media-enhancement-custom-backgrounds-and-music-mode\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.webex.com\/collaboration\/video-conferencing\/webex-meetings-august-2020-update-increased-security-and-media-enhancement-custom-backgrounds-and-music-mode\/","url":"https:\/\/blog.webex.com\/collaboration\/video-conferencing\/webex-meetings-august-2020-update-increased-security-and-media-enhancement-custom-backgrounds-and-music-mode\/","name":"Novedades de Webex Meetings Agosto 2020 Mayor seguridad y mejora de los elementos multimedia, fondos personalizados y modo m\u00fasica | Webex Blog","isPartOf":{"@id":"https:\/\/blog.webex.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.webex.com\/collaboration\/video-conferencing\/webex-meetings-august-2020-update-increased-security-and-media-enhancement-custom-backgrounds-and-music-mode\/#primaryimage"},"image":{"@id":"https:\/\/blog.webex.com\/collaboration\/video-conferencing\/webex-meetings-august-2020-update-increased-security-and-media-enhancement-custom-backgrounds-and-music-mode\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.webex.com\/wp-content\/uploads\/2020\/04\/woman-in-home-office-directly-facing-the-camera-and-smiling-feature.jpg","datePublished":"2020-08-18T20:20:16+00:00","dateModified":"2021-10-15T20:42:29+00:00","author":{"@id":"https:\/\/blog.webex.com\/es\/#\/schema\/person\/618264681e2ca0a8a9be532ba4c55d9e"},"breadcrumb":{"@id":"https:\/\/blog.webex.com\/collaboration\/video-conferencing\/webex-meetings-august-2020-update-increased-security-and-media-enhancement-custom-backgrounds-and-music-mode\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.webex.com\/collaboration\/video-conferencing\/webex-meetings-august-2020-update-increased-security-and-media-enhancement-custom-backgrounds-and-music-mode\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blog.webex.com\/collaboration\/video-conferencing\/webex-meetings-august-2020-update-increased-security-and-media-enhancement-custom-backgrounds-and-music-mode\/#primaryimage","url":"https:\/\/blog.webex.com\/wp-content\/uploads\/2020\/04\/woman-in-home-office-directly-facing-the-camera-and-smiling-feature.jpg","contentUrl":"https:\/\/blog.webex.com\/wp-content\/uploads\/2020\/04\/woman-in-home-office-directly-facing-the-camera-and-smiling-feature.jpg","width":980,"height":520,"caption":"Woman In Home Office Directly Facing The Camera And Smiling | Feature"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.webex.com\/collaboration\/video-conferencing\/webex-meetings-august-2020-update-increased-security-and-media-enhancement-custom-backgrounds-and-music-mode\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.webex.com\/es\/"},{"@type":"ListItem","position":2,"name":"Novedades de Webex Meetings Agosto 2020 Mayor seguridad y mejora ..."}]},{"@type":"WebSite","@id":"https:\/\/blog.webex.com\/es\/#website","url":"https:\/\/blog.webex.com\/es\/","name":"Webex Blog","description":"Webex by Cisco powers collaboration through industry-leading video conferencing, cloud calling and contact center solutions","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.webex.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/blog.webex.com\/es\/#\/schema\/person\/618264681e2ca0a8a9be532ba4c55d9e","name":"Connie Tang","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/522be562ef749beca5ff70ed64aac78c4b104dddd2b57c4bdc506f537daedce2?s=96&d=wp_user_avatar&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/522be562ef749beca5ff70ed64aac78c4b104dddd2b57c4bdc506f537daedce2?s=96&d=wp_user_avatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/522be562ef749beca5ff70ed64aac78c4b104dddd2b57c4bdc506f537daedce2?s=96&d=wp_user_avatar&r=g","caption":"Connie Tang"},"description":"Connie Tang is Senior Director of Product Management with Contact Center, Developer Platform and Integrations at Cisco. She drives the product direction of Contact Center AI automation and developer experiences so that third party developers can easily leverage the Webex platform to simplify work flows and adapt to hybrid work. Connie and her team work to extend the reach of Webex Meetings, Calling, Contact Center, Messaging and Devices through integrations with strategic partners such as Microsoft, Google, and Salesforce. She holds a number of patents in video and conferencing technologies, and has received Cisco awards for Excellence in Collaboration. Connie has a Master of Science degree in Management Science and Engineering, as well as a Bachelor of Arts and Science degree in Economics and Management Science and Engineering from Stanford University.","sameAs":["https:\/\/www.linkedin.com\/in\/connie-tang-1504a7\/","https:\/\/x.com\/https:\/\/twitter.com\/home?lang=en"],"url":"https:\/\/blog.webex.com\/es\/contributors\/connietang-2\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.webex.com\/es\/wp-json\/wp\/v2\/posts\/16289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.webex.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.webex.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.webex.com\/es\/wp-json\/wp\/v2\/users\/5379"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.webex.com\/es\/wp-json\/wp\/v2\/comments?post=16289"}],"version-history":[{"count":0,"href":"https:\/\/blog.webex.com\/es\/wp-json\/wp\/v2\/posts\/16289\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.webex.com\/es\/wp-json\/wp\/v2\/media\/417370"}],"wp:attachment":[{"href":"https:\/\/blog.webex.com\/es\/wp-json\/wp\/v2\/media?parent=16289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.webex.com\/es\/wp-json\/wp\/v2\/categories?post=16289"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.webex.com\/es\/wp-json\/wp\/v2\/tags?post=16289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}