{"id":374111,"date":"2021-09-28T15:00:15","date_gmt":"2021-09-28T22:00:15","guid":{"rendered":"https:\/\/blog.webex.com\/uncategorized-es\/novedades-en-roomos-septiembre\/"},"modified":"2021-10-31T05:26:09","modified_gmt":"2021-10-31T12:26:09","slug":"novedades-en-roomos-septiembre","status":"publish","type":"post","link":"https:\/\/blog.webex.com\/es\/espacios-de-trabajo\/novedades-en-roomos-septiembre\/","title":{"rendered":"Novedades en RoomOS: Septiembre"},"content":{"rendered":"<p>\u00a1Oficialmente es oto\u00f1o! Las hojas est\u00e1n cambiando de color, y aqu\u00ed en Webex seguimos trabajando duro para que su experiencia con los dispositivos sea la mejor posible. Siga leyendo para ver lo que lanzamos en RoomOS en septiembre.<\/p>\n<h2><strong>Reconocimiento de gestos en Webex Desk Pro<\/strong><\/h2>\n<p>Un gesto puede decir m\u00e1s que mil palabras. Bueno, no tanto, pero seguro que hace que sea mucho m\u00e1s f\u00e1cil que otras personas sepan lo que piensa en una reuni\u00f3n grande. Hace un tiempo que puede levantar la mano en Webex Desk Pro haciendo el gesto f\u00edsico, pero ahora lo estamos ampliando para incluir los pulgares hacia arriba y hacia abajo. Esto hace que sea muy f\u00e1cil reaccionar a algo que se est\u00e1 diciendo o mostrando sin interrumpir el flujo de la reuni\u00f3n. Consulte el <a href=\"https:\/\/help.webex.com\/nck1fap\/\">art\u00edculo de ayuda<\/a> para obtener m\u00e1s informaci\u00f3n.<\/p>\n<p><a href=\"https:\/\/blog.webex.com\/wp-content\/uploads\/2021\/09\/Gesture-recognition.png\"><br \/>\n  <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-373656 size-full\" src=\"https:\/\/blog.webex.com\/wp-content\/uploads\/2021\/09\/Gesture-recognition.png\" alt=\"Reconocimiento de gestos\" width=\"480\" height=\"272\" srcset=\"https:\/\/blog.webex.com\/wp-content\/uploads\/2021\/09\/Gesture-recognition.png 480w, https:\/\/blog.webex.com\/wp-content\/uploads\/2021\/09\/Gesture-recognition-300x170.png 300w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><br \/>\n<\/a><\/p>\n<h2><strong>Compatibilidad de Webex Room Navigator con 802.1X<\/strong><\/h2>\n<p>La seguridad es fundamental para todo lo que hacemos aqu\u00ed en Cisco. Por eso estamos habilitando una conexi\u00f3n segura para Webex Room Navigator con 802.1X. La mayor\u00eda de las empresas se preocupan por la seguridad y quieren tener una forma de autenticar sus dispositivos en su red. Pues bien, 802.1X es una caracter\u00edstica de seguridad com\u00fan implementada por muchas organizaciones, \u00a1y ahora es compatible con Webex Room Navigator! Haga clic <a href=\"https:\/\/help.webex.com\/q6pgjeb\/\">aqu\u00ed<\/a> para obtener m\u00e1s informaci\u00f3n.<\/p>\n<h2><strong>Sincronizaci\u00f3n en la nube para Webex Edge for Devices<\/strong><\/h2>\n<p>Webex Edge for Devices ahora permite que los dispositivos conectados utilicen las opciones de sincronizaci\u00f3n en la nube para mejorar la facilidad de uso y la seguridad. De esta manera, puede detectar los dispositivos de Webex cercanos, y conectarse a ellos, a trav\u00e9s de se\u00f1ales de ultrasonido, detecci\u00f3n de Wi-Fi o de forma manual, buscando el nombre de la sala. Adem\u00e1s, los visitantes pueden conectarse con un c\u00f3digo de invitado y compartir contenidos directamente desde el navegador www.share.webex.com, sin necesidad de usar una aplicaci\u00f3n o un cable.<\/p>\n<h2><strong>Compartir directamente desde Webex<\/strong><\/h2>\n<p>Estamos siempre comprometidos a mejorar la calidad de su experiencia con los dispositivos. Una de las formas en las que lo hacemos es ofreciendo im\u00e1genes m\u00e1s n\u00edtidas y con menor demora cuando se comparten contenidos desde la aplicaci\u00f3n Webex directamente a un dispositivo de Webex. En las configuraciones en las que el uso compartido directo no est\u00e1 disponible, la aplicaci\u00f3n Webex dirigir\u00e1 los medios de uso compartido de contenido a trav\u00e9s de la nube.<\/p>\n<blockquote><p>Esto es todo por el mes de septiembre, pero \u00a1est\u00e9 atento!<\/p><\/blockquote>\n<p><strong>M\u00e1s informaci\u00f3n<\/strong><\/p>\n<p><a href=\"\/?tag=Webex-RoomOS-Release\">Todas las novedades de las actualizaciones de RoomOS<\/a><\/p>\n<p><a href=\"https:\/\/blog.webex.com\/es\/dispositivos-de-colaboracion\/volver-al-trabajo-con-capacidad-de-sala-inteligente\/\">Regresar al trabajo con la capacidad de la sala inteligente<\/a><\/p>\n<p><a href=\"https:\/\/blog.webex.com\/collaboration-devices\/webex-device-management-the-power-of-search\/\">Administraci\u00f3n de dispositivos Webex: \u00a1el poder de la b\u00fasqueda!<\/a><\/p>\n<p><strong>\u00bfTodav\u00eda necesita ayuda?<\/strong><\/p>\n<p>\u00bfQu\u00e9 le gustar\u00eda hacer?<\/p>\n<p><a href=\"https:\/\/globalpage-prod.webex.com\/join?surl=https%3A%2F%2Fsignin.webex.com%2Fcollabs%2F%23%2Fmeetings%2Fjoinbynumber%3F\">Entre a una reuni\u00f3n en l\u00ednea de Webex.<\/a><\/p>\n<p><a href=\"https:\/\/www.webex.com\/video-conferencing\">Obtenga m\u00e1s informaci\u00f3n sobre las reuniones web y las videoconferencias.<\/a><\/p>\n<p><a href=\"https:\/\/www.webex.com\/video-conferencing\">Inscr\u00edbase en Webex.<\/a><\/p>\n<p>Visite nuestra <a href=\"https:\/\/www.webex.com\/\">p\u00e1gina de inicio<\/a> o <a href=\"https:\/\/www.webex.com\/contact-us.html\">p\u00f3ngase en contacto con nosotros<\/a> directamente para obtener ayuda.<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1Oficialmente es oto\u00f1o! Las hojas est\u00e1n cambiando de color, y aqu\u00ed en Webex seguimos trabajando duro para que su experiencia [&hellip;]<\/p>\n","protected":false},"author":5362,"featured_media":373675,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[1525],"tags":[4126],"class_list":["post-374111","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espacios-de-trabajo","tag-webex-roomos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Novedades en RoomOS: Septiembre | Webex Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.webex.com\/es\/uncategorized-es\/novedades-en-roomos-septiembre\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Novedades en RoomOS: Septiembre | Webex Blog\" \/>\n<meta property=\"og:description\" content=\"\u00a1Oficialmente es oto\u00f1o! Las hojas est\u00e1n cambiando de color, y aqu\u00ed en Webex seguimos trabajando duro para que su experiencia [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.webex.com\/es\/uncategorized-es\/novedades-en-roomos-septiembre\/\" \/>\n<meta property=\"og:site_name\" content=\"Webex Blog\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-28T22:00:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-31T12:26:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.webex.com\/wp-content\/uploads\/2021\/09\/team.png\" \/>\n\t<meta property=\"og:image:width\" content=\"975\" \/>\n\t<meta property=\"og:image:height\" content=\"554\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Juan Gallardo\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Juan Gallardo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/uncategorized-es\\\/novedades-en-roomos-septiembre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/uncategorized-es\\\/novedades-en-roomos-septiembre\\\/\"},\"author\":{\"name\":\"Juan Gallardo\",\"@id\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/#\\\/schema\\\/person\\\/d9361489e23ba84351a0f94691609771\"},\"headline\":\"Novedades en RoomOS: Septiembre\",\"datePublished\":\"2021-09-28T22:00:15+00:00\",\"dateModified\":\"2021-10-31T12:26:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/uncategorized-es\\\/novedades-en-roomos-septiembre\\\/\"},\"wordCount\":528,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/uncategorized-es\\\/novedades-en-roomos-septiembre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.webex.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/team.png\",\"keywords\":[\"Webex RoomOS\"],\"articleSection\":[\"Espacios de trabajo\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.webex.com\\\/es\\\/uncategorized-es\\\/novedades-en-roomos-septiembre\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/uncategorized-es\\\/novedades-en-roomos-septiembre\\\/\",\"url\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/uncategorized-es\\\/novedades-en-roomos-septiembre\\\/\",\"name\":\"Novedades en RoomOS: Septiembre | Webex Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/uncategorized-es\\\/novedades-en-roomos-septiembre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/uncategorized-es\\\/novedades-en-roomos-septiembre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.webex.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/team.png\",\"datePublished\":\"2021-09-28T22:00:15+00:00\",\"dateModified\":\"2021-10-31T12:26:09+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/#\\\/schema\\\/person\\\/d9361489e23ba84351a0f94691609771\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/uncategorized-es\\\/novedades-en-roomos-septiembre\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.webex.com\\\/es\\\/uncategorized-es\\\/novedades-en-roomos-septiembre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/uncategorized-es\\\/novedades-en-roomos-septiembre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.webex.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/team.png\",\"contentUrl\":\"https:\\\/\\\/blog.webex.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/team.png\",\"width\":975,\"height\":554},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/uncategorized-es\\\/novedades-en-roomos-septiembre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Novedades en RoomOS: Septiembre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/\",\"name\":\"Webex Blog\",\"description\":\"Webex by Cisco powers collaboration through industry-leading video conferencing, cloud calling and contact center solutions\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/#\\\/schema\\\/person\\\/d9361489e23ba84351a0f94691609771\",\"name\":\"Juan Gallardo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ae0b66fd8874e5623534f05986300d8ad28a5fef84dbd6fc33948c385816a8a7?s=96&d=wp_user_avatar&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ae0b66fd8874e5623534f05986300d8ad28a5fef84dbd6fc33948c385816a8a7?s=96&d=wp_user_avatar&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ae0b66fd8874e5623534f05986300d8ad28a5fef84dbd6fc33948c385816a8a7?s=96&d=wp_user_avatar&r=g\",\"caption\":\"Juan Gallardo\"},\"url\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/contributors\\\/juangallardo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Novedades en RoomOS: Septiembre | Webex Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.webex.com\/es\/uncategorized-es\/novedades-en-roomos-septiembre\/","og_locale":"es_ES","og_type":"article","og_title":"Novedades en RoomOS: Septiembre | Webex Blog","og_description":"\u00a1Oficialmente es oto\u00f1o! Las hojas est\u00e1n cambiando de color, y aqu\u00ed en Webex seguimos trabajando duro para que su experiencia [&hellip;]","og_url":"https:\/\/blog.webex.com\/es\/uncategorized-es\/novedades-en-roomos-septiembre\/","og_site_name":"Webex Blog","article_published_time":"2021-09-28T22:00:15+00:00","article_modified_time":"2021-10-31T12:26:09+00:00","og_image":[{"width":975,"height":554,"url":"https:\/\/blog.webex.com\/wp-content\/uploads\/2021\/09\/team.png","type":"image\/png"}],"author":"Juan Gallardo","twitter_misc":{"Escrito por":"Juan Gallardo","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.webex.com\/es\/uncategorized-es\/novedades-en-roomos-septiembre\/#article","isPartOf":{"@id":"https:\/\/blog.webex.com\/es\/uncategorized-es\/novedades-en-roomos-septiembre\/"},"author":{"name":"Juan Gallardo","@id":"https:\/\/blog.webex.com\/es\/#\/schema\/person\/d9361489e23ba84351a0f94691609771"},"headline":"Novedades en RoomOS: Septiembre","datePublished":"2021-09-28T22:00:15+00:00","dateModified":"2021-10-31T12:26:09+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.webex.com\/es\/uncategorized-es\/novedades-en-roomos-septiembre\/"},"wordCount":528,"commentCount":0,"image":{"@id":"https:\/\/blog.webex.com\/es\/uncategorized-es\/novedades-en-roomos-septiembre\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.webex.com\/wp-content\/uploads\/2021\/09\/team.png","keywords":["Webex RoomOS"],"articleSection":["Espacios de trabajo"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.webex.com\/es\/uncategorized-es\/novedades-en-roomos-septiembre\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.webex.com\/es\/uncategorized-es\/novedades-en-roomos-septiembre\/","url":"https:\/\/blog.webex.com\/es\/uncategorized-es\/novedades-en-roomos-septiembre\/","name":"Novedades en RoomOS: Septiembre | Webex Blog","isPartOf":{"@id":"https:\/\/blog.webex.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.webex.com\/es\/uncategorized-es\/novedades-en-roomos-septiembre\/#primaryimage"},"image":{"@id":"https:\/\/blog.webex.com\/es\/uncategorized-es\/novedades-en-roomos-septiembre\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.webex.com\/wp-content\/uploads\/2021\/09\/team.png","datePublished":"2021-09-28T22:00:15+00:00","dateModified":"2021-10-31T12:26:09+00:00","author":{"@id":"https:\/\/blog.webex.com\/es\/#\/schema\/person\/d9361489e23ba84351a0f94691609771"},"breadcrumb":{"@id":"https:\/\/blog.webex.com\/es\/uncategorized-es\/novedades-en-roomos-septiembre\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.webex.com\/es\/uncategorized-es\/novedades-en-roomos-septiembre\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blog.webex.com\/es\/uncategorized-es\/novedades-en-roomos-septiembre\/#primaryimage","url":"https:\/\/blog.webex.com\/wp-content\/uploads\/2021\/09\/team.png","contentUrl":"https:\/\/blog.webex.com\/wp-content\/uploads\/2021\/09\/team.png","width":975,"height":554},{"@type":"BreadcrumbList","@id":"https:\/\/blog.webex.com\/es\/uncategorized-es\/novedades-en-roomos-septiembre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.webex.com\/es\/"},{"@type":"ListItem","position":2,"name":"Novedades en RoomOS: Septiembre"}]},{"@type":"WebSite","@id":"https:\/\/blog.webex.com\/es\/#website","url":"https:\/\/blog.webex.com\/es\/","name":"Webex Blog","description":"Webex by Cisco powers collaboration through industry-leading video conferencing, cloud calling and contact center solutions","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.webex.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/blog.webex.com\/es\/#\/schema\/person\/d9361489e23ba84351a0f94691609771","name":"Juan Gallardo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ae0b66fd8874e5623534f05986300d8ad28a5fef84dbd6fc33948c385816a8a7?s=96&d=wp_user_avatar&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ae0b66fd8874e5623534f05986300d8ad28a5fef84dbd6fc33948c385816a8a7?s=96&d=wp_user_avatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ae0b66fd8874e5623534f05986300d8ad28a5fef84dbd6fc33948c385816a8a7?s=96&d=wp_user_avatar&r=g","caption":"Juan Gallardo"},"url":"https:\/\/blog.webex.com\/es\/contributors\/juangallardo\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.webex.com\/es\/wp-json\/wp\/v2\/posts\/374111","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.webex.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.webex.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.webex.com\/es\/wp-json\/wp\/v2\/users\/5362"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.webex.com\/es\/wp-json\/wp\/v2\/comments?post=374111"}],"version-history":[{"count":0,"href":"https:\/\/blog.webex.com\/es\/wp-json\/wp\/v2\/posts\/374111\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.webex.com\/es\/wp-json\/wp\/v2\/media\/373675"}],"wp:attachment":[{"href":"https:\/\/blog.webex.com\/es\/wp-json\/wp\/v2\/media?parent=374111"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.webex.com\/es\/wp-json\/wp\/v2\/categories?post=374111"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.webex.com\/es\/wp-json\/wp\/v2\/tags?post=374111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}