{"id":386123,"date":"2019-06-27T10:30:17","date_gmt":"2019-06-27T17:30:17","guid":{"rendered":"https:\/\/blog.webex.com\/uncategorized-es\/webex-teams-dispositivos-locales\/"},"modified":"2019-06-27T10:30:17","modified_gmt":"2019-06-27T17:30:17","slug":"webex-teams-dispositivos-locales","status":"publish","type":"post","link":"https:\/\/blog.webex.com\/es\/espacios-de-trabajo\/webex-teams-dispositivos-locales\/","title":{"rendered":"Webex Teams dispositivos locales"},"content":{"rendered":"<h2>Cisco Webex Teams: cada sala, cada dispositivo, cada reuni\u00f3n<\/h2>\n<p>La inal\u00e1mbrica es la nueva aplicaci\u00f3n. Me encanta que mis productos de consumidor tengan tecnolog\u00eda inal\u00e1mbrica incorporada que los facilita el uso, no necesito enredados en cables escuchando m\u00fasica sobre la marcha o enchufando un cable para mantener mi tel\u00e9fono cargado. La inal\u00e1mbrica tambi\u00e9n es la nueva aplicaci\u00f3n en el trabajo. Todos los d\u00edas, me conecto de forma inal\u00e1mbrica a los dispositivos de conferencia de Webex desde Webex Teams compartir <a href=\"https:\/\/www.webex.com\/video-conferencing.html\" target=\"_blank\" rel=\"noopener\">contenido e iniciar<\/a>  <a href=\"https:\/\/www.webex.com\/team-collaboration.html\" target=\"_blank\" rel=\"noopener\"> <\/a>reuniones. No estoy solo, muchos Webex Teams usuarios optan por conectarse de forma inal\u00e1mbrica a los dispositivos. Me encanta entrar en una sala de reuniones que tiene un dispositivo de Webex, mi computadora port\u00e1til se conecta sin problemas al dispositivo de Webex utilizando la tecnolog\u00eda inal\u00e1mbrica de Cisco con mis dispositivos locales. Hola, ya estoy listo para compartir contenido y entrar a reuniones, eliminando la molestia de conectar cables y adaptadores. Muchos de nuestros clientes a\u00fan tienen grandes implementaciones de dispositivos Webex locales y la tecnolog\u00eda inal\u00e1mbrica antes solo era compatible con los dispositivos registrados en la nube. Me complace anunciar que cambiar\u00e1 en nuestra versi\u00f3n de junio de Webex Teams ya que ahora puede compartir contenido y entrar a reuniones de forma inal\u00e1mbrica en todos los dispositivos de Webex, tanto en la nube como en las instalaciones.<\/p>\n<h2>Webex Devices \u00a1Hasta cables de vista!<\/h2>\n<p>\u00a1Adi\u00f3s a los cables! Hola, presentaciones y reuniones autom\u00e1ticas e instant\u00e1neas mediante su dispositivo local o en la nube. Comparta de forma inal\u00e1mbrica con un dispositivo de Webex con todos reunidos en la misma sala o inicie una reuni\u00f3n y comparta contenido de forma inal\u00e1mbrica con participantes remotos. Si estoy compartiendo contenido de v\u00eddeo, incluso puedo activar la compartici\u00f3n de fotogramas de alta velocidad para que no haya retrasos y tambi\u00e9n puedo compartir audio. Con la tecnolog\u00eda inal\u00e1mbrica de Cisco, todas las personas de la reuni\u00f3n pueden conectarse al dispositivo de Webex al mismo tiempo para que cualquiera pueda tomar el control del uso compartido en cualquier momento. Ya no necesita cambiar cables ni tener que saltar a la silla. Ahora tiene experiencias de reuniones totalmente inclusivas y con flujo libre de cables.<\/p>\n<h2>Estar en el control (remoto) de la reuni\u00f3n con Webex Teams<\/h2>\n<p>Webex Teams le da un gran bot\u00f3n verde para entrar a todas sus reuniones y llamadas. Si est\u00e1 en una sala con un dispositivo local o en la nube, tambi\u00e9n puede entrar a la reuni\u00f3n desde Webex Teams en su computadora y controlar la experiencia de la reuni\u00f3n de forma <a href=\"https:\/\/www.webex.com\/team-collaboration.html\" target=\"_blank\" rel=\"noopener\"><\/a> remota desde su computadora. Entrar a una reuni\u00f3n tarda segundos, ingresar al sala de reuniones al comienzo de la reuni\u00f3n, conectarse autom\u00e1ticamente al dispositivo y luego seleccionar el gran bot\u00f3n verde para la reuni\u00f3n. Ahora que Webex Teams funciona con dispositivos locales y en la nube, funciona con cada sala de reuniones y le ofrece una experiencia similar a los dispositivos registrados <a href=\"https:\/\/www.webex.com\/team-collaboration.html\" target=\"_blank\" rel=\"noopener\"><\/a> en la nube. Durante la reuni\u00f3n, todos pueden conectarse al dispositivo y controlar la reuni\u00f3n. Si alguien habla con demasiada tranquilidad, cualquiera puede subir el volumen de forma remota en el dispositivo de Webex desde su computadora. Si el dispositivo est\u00e1 silenciado y alguien quiere hablar, cualquiera puede activar el sonido del dispositivo de Webex desde su computadora. Es como si todos disponen de sus propios televisores control remoto TV, todos deciden qu\u00e9 mirar. Desafortunadamente, a menos que tenga varias reuniones de Webex en curso, no hay saltos de canal.<\/p>\n<h2>Con\u00e9ctese<\/h2>\n<p>Con todas estas excelentes caracter\u00edsticas, incluso puede obtener m\u00e1s valor de sus dispositivos locales existentes. Las reuniones se transforman a medida que comienzan m\u00e1s r\u00e1pido, la compartici\u00f3n no requiere ning\u00fan cable o adaptador y todos pueden participar de manera equitativa en la reuni\u00f3n. Para comenzar a compartir y entrar a reuniones en sus dispositivos locales, aprenda todo lo que necesita saber <a href=\"https:\/\/help.webex.com\/en-us\/poqjhk\/Configure-On-Premises-Devices-for-Cisco-Webex-Teams-Users\">aqu\u00ed.<\/a><br \/>\nPronto agregaremos a\u00fan m\u00e1s caracter\u00edsticas, como Mover llamada, donde puede iniciar la llamada en su computadora y luego mover la llamada a un dispositivo de Webex. Y, si prefiere no enviar v\u00eddeo, pronto ser\u00e1 posible silenciar de forma remota el v\u00eddeo que se env\u00eda desde el dispositivo de Webex. Con todas estas mejoras para compartir y reuniones, Teams es la mejor manera de disfrutar de sus reuniones. <a href=\"https:\/\/www.cisco.com\/c\/en\/us\/solutions\/collaboration\/webinars.html\">Webex Teams y los dispositivos de Webex juntos hacen que todas sus reuniones mejoren, pueden comenzar descargando Webex Teams<\/a>  <a href=\"https:\/\/www.cisco.com\/c\/en\/us\/solutions\/collaboration\/webinars.html\">reuniones www.webex.com\/downloads.html hoy<\/a>  <a href=\"https:\/\/www.webex.com\/downloads.html\"><\/a> mismo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1Adi\u00f3s a los cables! Hola, presentaciones y reuniones autom\u00e1ticas e instant\u00e1neas mediante sus Webex Teams dispositivos locales&#8230;<\/p>\n","protected":false},"author":5458,"featured_media":386124,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[5293,1525],"tags":[10136,5302,8140,6340],"class_list":["post-386123","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-colaboracion","category-espacios-de-trabajo","tag-administradores-de-webex","tag-blogs-de-cisco","tag-on-premise-devices-es","tag-webex-teams-es-2"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Webex Teams dispositivos locales | Webex Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.webex.com\/es\/espacios-de-trabajo\/webex-teams-dispositivos-locales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Webex Teams dispositivos locales | Webex Blog\" \/>\n<meta property=\"og:description\" content=\"\u00a1Adi\u00f3s a los cables! Hola, presentaciones y reuniones autom\u00e1ticas e instant\u00e1neas mediante sus Webex Teams dispositivos locales...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.webex.com\/es\/espacios-de-trabajo\/webex-teams-dispositivos-locales\/\" \/>\n<meta property=\"og:site_name\" content=\"Webex Blog\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-27T17:30:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.webex.com\/wp-content\/uploads\/2019\/06\/5d0bb19d5b765-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1516\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Andrew Henderson\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andrew Henderson\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/blog.webex.com\/es\/espacios-de-trabajo\/webex-teams-dispositivos-locales\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/blog.webex.com\/es\/espacios-de-trabajo\/webex-teams-dispositivos-locales\/\"},\"author\":{\"name\":\"Andrew Henderson\",\"@id\":\"https:\/\/blog.webex.com\/es\/#\/schema\/person\/981e7aee85d9f4191ddcc185eb15dbc5\"},\"headline\":\"Webex Teams dispositivos locales\",\"datePublished\":\"2019-06-27T17:30:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/blog.webex.com\/es\/espacios-de-trabajo\/webex-teams-dispositivos-locales\/\"},\"wordCount\":792,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/blog.webex.com\/es\/espacios-de-trabajo\/webex-teams-dispositivos-locales\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/blog.webex.com\/wp-content\/uploads\/2019\/06\/5d0bb19d5b765-1-scaled.jpg\",\"keywords\":[\"Administradores de Webex\",\"Blogs de Cisco\",\"on-premise devices\",\"webex teams\"],\"articleSection\":[\"Colaboraci\u00f3n\",\"Espacios de trabajo\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/blog.webex.com\/es\/espacios-de-trabajo\/webex-teams-dispositivos-locales\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/blog.webex.com\/es\/espacios-de-trabajo\/webex-teams-dispositivos-locales\/\",\"url\":\"https:\/\/blog.webex.com\/es\/espacios-de-trabajo\/webex-teams-dispositivos-locales\/\",\"name\":\"Webex Teams dispositivos locales | Webex Blog\",\"isPartOf\":{\"@id\":\"https:\/\/blog.webex.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/blog.webex.com\/es\/espacios-de-trabajo\/webex-teams-dispositivos-locales\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/blog.webex.com\/es\/espacios-de-trabajo\/webex-teams-dispositivos-locales\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/blog.webex.com\/wp-content\/uploads\/2019\/06\/5d0bb19d5b765-1-scaled.jpg\",\"datePublished\":\"2019-06-27T17:30:17+00:00\",\"author\":{\"@id\":\"https:\/\/blog.webex.com\/es\/#\/schema\/person\/981e7aee85d9f4191ddcc185eb15dbc5\"},\"breadcrumb\":{\"@id\":\"https:\/\/blog.webex.com\/es\/espacios-de-trabajo\/webex-teams-dispositivos-locales\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/blog.webex.com\/es\/espacios-de-trabajo\/webex-teams-dispositivos-locales\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/blog.webex.com\/es\/espacios-de-trabajo\/webex-teams-dispositivos-locales\/#primaryimage\",\"url\":\"https:\/\/blog.webex.com\/wp-content\/uploads\/2019\/06\/5d0bb19d5b765-1-scaled.jpg\",\"contentUrl\":\"https:\/\/blog.webex.com\/wp-content\/uploads\/2019\/06\/5d0bb19d5b765-1-scaled.jpg\",\"width\":2560,\"height\":1516},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blog.webex.com\/es\/espacios-de-trabajo\/webex-teams-dispositivos-locales\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/blog.webex.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Webex Teams dispositivos locales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blog.webex.com\/es\/#website\",\"url\":\"https:\/\/blog.webex.com\/es\/\",\"name\":\"Webex Blog\",\"description\":\"Webex by Cisco powers collaboration through industry-leading video conferencing, cloud calling and contact center solutions\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blog.webex.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/blog.webex.com\/es\/#\/schema\/person\/981e7aee85d9f4191ddcc185eb15dbc5\",\"name\":\"Andrew Henderson\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/blog.webex.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e4753d704e622f6e662d47b47955bb2f672a6d3243ca4bbf294ce1314b3b03d3?s=96&d=wp_user_avatar&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e4753d704e622f6e662d47b47955bb2f672a6d3243ca4bbf294ce1314b3b03d3?s=96&d=wp_user_avatar&r=g\",\"caption\":\"Andrew Henderson\"},\"description\":\"Andrew Henderson is Product Manager for the Webex Teams device &amp; content experiences, working on features such as Proximity pairing that help users share content effortlessly with Webex Devices. Prior to joining the Product Management team, Andrew was Design Manager for the Cisco Jabber collaboration app and he brings a lot of that Design experience into the Product Management Team Andrew has an MSc in Computer Science &amp; Psychology and a BA in Industrial Design and has been awarded 6 patents for design work. Andrew lives in Ireland and is based out of the Cisco offices in Galway city.\",\"url\":\"https:\/\/blog.webex.com\/es\/contributors\/andrewhenderson\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Webex Teams dispositivos locales | Webex Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.webex.com\/es\/espacios-de-trabajo\/webex-teams-dispositivos-locales\/","og_locale":"es_ES","og_type":"article","og_title":"Webex Teams dispositivos locales | Webex Blog","og_description":"\u00a1Adi\u00f3s a los cables! Hola, presentaciones y reuniones autom\u00e1ticas e instant\u00e1neas mediante sus Webex Teams dispositivos locales...","og_url":"https:\/\/blog.webex.com\/es\/espacios-de-trabajo\/webex-teams-dispositivos-locales\/","og_site_name":"Webex Blog","article_published_time":"2019-06-27T17:30:17+00:00","og_image":[{"width":2560,"height":1516,"url":"https:\/\/blog.webex.com\/wp-content\/uploads\/2019\/06\/5d0bb19d5b765-1-scaled.jpg","type":"image\/jpeg"}],"author":"Andrew Henderson","twitter_misc":{"Escrito por":"Andrew Henderson","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.webex.com\/es\/espacios-de-trabajo\/webex-teams-dispositivos-locales\/#article","isPartOf":{"@id":"https:\/\/blog.webex.com\/es\/espacios-de-trabajo\/webex-teams-dispositivos-locales\/"},"author":{"name":"Andrew Henderson","@id":"https:\/\/blog.webex.com\/es\/#\/schema\/person\/981e7aee85d9f4191ddcc185eb15dbc5"},"headline":"Webex Teams dispositivos locales","datePublished":"2019-06-27T17:30:17+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.webex.com\/es\/espacios-de-trabajo\/webex-teams-dispositivos-locales\/"},"wordCount":792,"commentCount":0,"image":{"@id":"https:\/\/blog.webex.com\/es\/espacios-de-trabajo\/webex-teams-dispositivos-locales\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.webex.com\/wp-content\/uploads\/2019\/06\/5d0bb19d5b765-1-scaled.jpg","keywords":["Administradores de Webex","Blogs de Cisco","on-premise devices","webex teams"],"articleSection":["Colaboraci\u00f3n","Espacios de trabajo"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.webex.com\/es\/espacios-de-trabajo\/webex-teams-dispositivos-locales\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.webex.com\/es\/espacios-de-trabajo\/webex-teams-dispositivos-locales\/","url":"https:\/\/blog.webex.com\/es\/espacios-de-trabajo\/webex-teams-dispositivos-locales\/","name":"Webex Teams dispositivos locales | Webex Blog","isPartOf":{"@id":"https:\/\/blog.webex.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.webex.com\/es\/espacios-de-trabajo\/webex-teams-dispositivos-locales\/#primaryimage"},"image":{"@id":"https:\/\/blog.webex.com\/es\/espacios-de-trabajo\/webex-teams-dispositivos-locales\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.webex.com\/wp-content\/uploads\/2019\/06\/5d0bb19d5b765-1-scaled.jpg","datePublished":"2019-06-27T17:30:17+00:00","author":{"@id":"https:\/\/blog.webex.com\/es\/#\/schema\/person\/981e7aee85d9f4191ddcc185eb15dbc5"},"breadcrumb":{"@id":"https:\/\/blog.webex.com\/es\/espacios-de-trabajo\/webex-teams-dispositivos-locales\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.webex.com\/es\/espacios-de-trabajo\/webex-teams-dispositivos-locales\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blog.webex.com\/es\/espacios-de-trabajo\/webex-teams-dispositivos-locales\/#primaryimage","url":"https:\/\/blog.webex.com\/wp-content\/uploads\/2019\/06\/5d0bb19d5b765-1-scaled.jpg","contentUrl":"https:\/\/blog.webex.com\/wp-content\/uploads\/2019\/06\/5d0bb19d5b765-1-scaled.jpg","width":2560,"height":1516},{"@type":"BreadcrumbList","@id":"https:\/\/blog.webex.com\/es\/espacios-de-trabajo\/webex-teams-dispositivos-locales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.webex.com\/es\/"},{"@type":"ListItem","position":2,"name":"Webex Teams dispositivos locales"}]},{"@type":"WebSite","@id":"https:\/\/blog.webex.com\/es\/#website","url":"https:\/\/blog.webex.com\/es\/","name":"Webex Blog","description":"Webex by Cisco powers collaboration through industry-leading video conferencing, cloud calling and contact center solutions","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.webex.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/blog.webex.com\/es\/#\/schema\/person\/981e7aee85d9f4191ddcc185eb15dbc5","name":"Andrew Henderson","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blog.webex.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e4753d704e622f6e662d47b47955bb2f672a6d3243ca4bbf294ce1314b3b03d3?s=96&d=wp_user_avatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e4753d704e622f6e662d47b47955bb2f672a6d3243ca4bbf294ce1314b3b03d3?s=96&d=wp_user_avatar&r=g","caption":"Andrew Henderson"},"description":"Andrew Henderson is Product Manager for the Webex Teams device &amp; content experiences, working on features such as Proximity pairing that help users share content effortlessly with Webex Devices. Prior to joining the Product Management team, Andrew was Design Manager for the Cisco Jabber collaboration app and he brings a lot of that Design experience into the Product Management Team Andrew has an MSc in Computer Science &amp; Psychology and a BA in Industrial Design and has been awarded 6 patents for design work. Andrew lives in Ireland and is based out of the Cisco offices in Galway city.","url":"https:\/\/blog.webex.com\/es\/contributors\/andrewhenderson\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.webex.com\/es\/wp-json\/wp\/v2\/posts\/386123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.webex.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.webex.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.webex.com\/es\/wp-json\/wp\/v2\/users\/5458"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.webex.com\/es\/wp-json\/wp\/v2\/comments?post=386123"}],"version-history":[{"count":0,"href":"https:\/\/blog.webex.com\/es\/wp-json\/wp\/v2\/posts\/386123\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.webex.com\/es\/wp-json\/wp\/v2\/media\/386124"}],"wp:attachment":[{"href":"https:\/\/blog.webex.com\/es\/wp-json\/wp\/v2\/media?parent=386123"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.webex.com\/es\/wp-json\/wp\/v2\/categories?post=386123"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.webex.com\/es\/wp-json\/wp\/v2\/tags?post=386123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}