{"id":19181,"date":"2021-06-23T13:21:46","date_gmt":"2021-06-23T20:21:46","guid":{"rendered":"https:\/\/cisco2393.wpengine.com\/cisco-est-nomme-leader-du-classement-aragon-globe-pour-les-communications-unifiees-et-la-collaboration-en-2021\/"},"modified":"2024-09-17T23:37:04","modified_gmt":"2024-09-18T06:37:04","slug":"cisco-est-nomme-leader-du-classement-aragon-globe-pour-les-communications-unifiees-et-la-collaboration-en-2021","status":"publish","type":"post","link":"https:\/\/blog.webex.com\/fr\/collaboration-fr\/visioconferences\/cisco-est-nomme-leader-du-classement-aragon-globe-pour-les-communications-unifiees-et-la-collaboration-en-2021\/","title":{"rendered":"Cisco est nomm\u00e9 leader du classement Aragon Globe&#x2122; pour ..."},"content":{"rendered":"<h2>Travail hybride : d&rsquo;une r\u00e9ponse temporaire \u00e0 une strat\u00e9gie durable<\/h2>\n<p>L&rsquo;influent cabinet d&rsquo;analystes sectoriels Aragon Research a publi\u00e9 cette semaine son cinqui\u00e8me rapport annuel Research Globe&#x2122; consacr\u00e9 aux communications unifi\u00e9es et \u00e0 la collaboration (UCC). Cisco y a une nouvelle fois \u00e9t\u00e9 identifi\u00e9 comme un leader et nous en sommes fiers.<\/p>\n<p>Le rapport d&rsquo;Aragon contient une foule de renseignements utiles aux d\u00e9cideurs d&rsquo;entreprise pour \u00e9laborer une strat\u00e9gie UCC adapt\u00e9e \u00e0 leurs besoins. Je soulignerai quelques points marquants, mais j&rsquo;encourage tout le monde \u00e0 lire le rapport complet.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-15327\" src=\"https:\/\/blog.webex.com\/wp-content\/uploads\/2021\/06\/Blog_Aragon-1.jpeg\" alt=\"Aragon  \" width=\"440\" height=\"454\" srcset=\"https:\/\/blog.webex.com\/wp-content\/uploads\/2021\/06\/Blog_Aragon-1.jpeg 440w, https:\/\/blog.webex.com\/wp-content\/uploads\/2021\/06\/Blog_Aragon-1-291x300.jpeg 291w\" sizes=\"auto, (max-width: 440px) 100vw, 440px\" \/><\/p>\n<h2><strong>La cl\u00e9 du travail hybride : une exp\u00e9rience de collaboration int\u00e9gr\u00e9e <\/strong><\/h2>\n<p>Aragon avance un argument de poids : dans un monde du travail hybride, les outils de collaboration en \u00e9quipe occuperont d\u00e9sormais une place centrale et viendrontdansune large mesure renforcer les communications et les proc\u00e9dures des employ\u00e9s. Les outils de collaboration d&rsquo;\u00e9quipe sont en passe de devenir l&rsquo;environnement privil\u00e9gi\u00e9 pour les communications individuelles et collectives, et s&rsquo;imposent de fait comme une alternative au courrier \u00e9lectronique pour accomplir un travail.<\/p>\n<p>Compte tenu de leur r\u00f4le central dans le travail quotidien des employ\u00e9s, les outils de collaboration doivent, pour \u00eatre r\u00e9ellement efficaces, int\u00e9grer la voix, la vid\u00e9o, les r\u00e9unions, la messagerie et le partage au sein d&rsquo;une exp\u00e9rience utilisateur \u00e0 la fois fluide et homog\u00e8ne.<\/p>\n<p>Aragon a tenu compte de notre volont\u00e9 d&rsquo;innovation constante ainsi que des progr\u00e8s significatifs que nous avons accomplis gr\u00e2ce \u00e0 Webex au cours de l&rsquo;ann\u00e9e pass\u00e9e, et d\u00e9clar\u00e9 :<\/p>\n<blockquote><p><em>\u00ab Cisco a mis au point une exp\u00e9rience applicative Webex enti\u00e8rement nouvelle, qui permet aux gens de se concentrer sur leur travail avec des processus d&rsquo;appel, de messagerie, de r\u00e9union et de collaboration d&rsquo;\u00e9quipe totalement transparents, le tout dans une application unique \u00bb. <\/em><\/p><\/blockquote>\n<p>Aragon souligne \u00e9galement la valeur apport\u00e9e par notre centre de contact int\u00e9gr\u00e9 Webex et notre gamme de dispositifs collaboratifs. Webex Contact Center est une solution compl\u00e8te de centre de contact dans le cloud, int\u00e9gr\u00e9e \u00e0 la suite de collaboration Webex qui vise \u00e0 am\u00e9liorer l&rsquo;efficacit\u00e9 des employ\u00e9s des centres de contact et la satisfaction des clients. Nous offrons \u00e9galement une gamme compl\u00e8te de dispositifs de collaboration sp\u00e9cialis\u00e9s, qui sont enti\u00e8rement int\u00e9gr\u00e9s \u00e0 l&rsquo;exp\u00e9rience de gestion des utilisateurs et des services Webex.<\/p>\n<p>De nombreuses autres am\u00e9liorations ont \u00e9t\u00e9 apport\u00e9es \u00e0 l&rsquo;exp\u00e9rience utilisateur int\u00e9gr\u00e9e de Webex au cours de l&rsquo;ann\u00e9e \u00e9coul\u00e9e, notamment gr\u00e2ce \u00e0 l&rsquo;int\u00e9gration compl\u00e8te des appels et \u00e0 la gestion consolid\u00e9e des services au sein de Control Hub, qu&rsquo;Aragon d\u00e9taille plus loin dans son rapport.<\/p>\n<h2><strong>L&rsquo;essor de l&rsquo;intelligence collaborative <\/strong><\/h2>\n<p>Les utilisateurs consacrent une grande part de leur temps \u00e0 interagir dans un environnement de collaboration d&rsquo;\u00e9quipe. En jeu : la productivit\u00e9 globale, et m\u00eame le bien-\u00eatre des employ\u00e9s. Il est essentiel que les plateformes collaboratives disposent d&rsquo;une intelligence \u00e0 m\u00eame de r\u00e9duire la complexit\u00e9, les distractions et la lassitude, tout en am\u00e9liorant l&rsquo;accessibilit\u00e9 pour tous.<\/p>\n<p>a meilleure r\u00e9ponse au d\u00e9fi que repr\u00e9sente la cr\u00e9ation d&rsquo;une collaboration v\u00e9ritablement centr\u00e9e sur l&rsquo;utilisateur est d&rsquo;exploiter des technologies telles que l&rsquo;IA, la reconnaissance vocale, la compr\u00e9hension des images, la suppression du bruit et l&rsquo;automatisation, de mani\u00e8re \u00e0 \u00e9liminer les t\u00e2ches banales et am\u00e9liorer le bien-\u00eatre des utilisateurs.<\/p>\n<p>Aragon a conscience des vastes capacit\u00e9s en mati\u00e8re d&rsquo;intelligence qu&rsquo;offre Webex :<\/p>\n<blockquote><p><em>\u00ab <\/em><em>La nouvelle version de Webex Assistant, qui est capable de prendre des notes et d&rsquo;assigner des actions, est une fonction majeure de l&rsquo;ensemble de la plateforme UC&#038;C de Cisco. Associ\u00e9e aux autres fonctions Webex que sont la connaissance approfondie des individus, la reconnaissance gestuelle, la r\u00e9duction du bruit int\u00e9gr\u00e9e, les nouveaux modes de participation s\u00e9curis\u00e9s aux r\u00e9unions, l&rsquo;am\u00e9lioration de la qualit\u00e9 sonore et vid\u00e9o et la traduction en temps r\u00e9el dans plus de 100 langues, cette offre Webex diff\u00e9re de ce qu&rsquo;elle \u00e9tait d\u00e9but 2020 \u00bb.<\/em><\/p><\/blockquote>\n<p>Sachant que l&rsquo;ajout de fonctionnalit\u00e9s plus riches et une int\u00e9gration renforc\u00e9e des flux d&rsquo;op\u00e9ration peuvent \u00e9galement conduire \u00e0 une complexit\u00e9 accrue, nous nous engageons \u00e0 mettre l&rsquo;accent en permanence sur la simplicit\u00e9 afin de maintenir et d\u00e9velopper notre leadership en mati\u00e8re d&rsquo;intelligence collaborative.<\/p>\n<h2><strong>L&rsquo;\u00e9tablissement d&rsquo;une strat\u00e9gie durable <\/strong><\/h2>\n<p>Confront\u00e9es \u00e0 des perturbations sans pr\u00e9c\u00e9dent au cours des 18 derniers mois, les entreprises et les utilisateurs ont r\u00e9agi en r\u00e9unissant rapidement tous les outils de collaboration \u00e0 leur disposition afin de maintenir la continuit\u00e9 de leur activit\u00e9 et la communication entre les \u00e9quipes.<\/p>\n<p>Maintenant que le travail hybride s&rsquo;impose comme une r\u00e9alit\u00e9 appel\u00e9e \u00e0 durer, il est essentiel d&rsquo;\u00e9laborer une strat\u00e9gie collaborative d&rsquo;entreprise durable sur le long terme, qui offre une exp\u00e9rience totalement int\u00e9gr\u00e9e.<\/p>\n<p>Comme le d\u00e9clare Jim Lundy, analyste sp\u00e9cialis\u00e9 chez Aragon :<\/p>\n<blockquote><p><em>\u00ab\u00a0Compte tenu de la demande et des n\u00e9cessit\u00e9s, de nombreuses entreprises font appel \u00e0 une pluralit\u00e9 d&rsquo;applications de communications et de contr\u00f4les autonomes. Elles s&#8217;emploient d\u00e9sormais \u00e0 opter pour un fournisseur UC&#038;C unique afin de b\u00e9n\u00e9ficier d&rsquo;une exp\u00e9rience de collaboration totalement int\u00e9gr\u00e9e<\/em>\u00a0\u00bb.<\/p><\/blockquote>\n<p>Ces d\u00e9cisions \u00e0 venir auront un impact significatif \u00e0 long terme sur la productivit\u00e9, l&rsquo;agilit\u00e9 et la satisfaction tant des employ\u00e9s que des clients de l&rsquo;entreprise.<\/p>\n<p>L&rsquo;ann\u00e9e \u00e9coul\u00e9e a vu la collaboration \u00e9voluer. Pour r\u00e9pondre \u00e0 cette \u00e9volution, Webex a \u00e9galement \u00e9volu\u00e9 \u00e0 un rythme sans pr\u00e9c\u00e9dent, avec plus de 700 perfectionnements apport\u00e9s au cours des huit derniers mois. Nous restons attach\u00e9s \u00e0 une feuille de route ambitieuse et \u00e0 notre volont\u00e9 d&rsquo;offrir continuellement \u00e0 nos clients la meilleure exp\u00e9rience de collaboration possible.<\/p>\n<p><strong><br \/>\n  <a href=\"https:\/\/www.webex.com\/analyst-reports\/aragon-how-intelligent-ucc-platforms-power-team-collaboration.html\"><br \/>\n    <u>Prenez connaissance du rapport complet d&rsquo;Aragon<\/u><br \/>\n  <\/a> pour \u00e9laborer la strat\u00e9gie qui r\u00e9pond le mieux \u00e0 vos besoins individuels.<\/strong><\/p>\n<h3><\/h3>\n<h3><strong>En savoir plus<\/strong><\/h3>\n<p><a href=\"https:\/\/blog.webex.com\/fr\/visioconferences\/quoi-de-neuf-dans-webex-juin-2021\/\">Nouveaut\u00e9s Webex\u00a0: Juin 2021<\/a><\/p>\n<p><a href=\"https:\/\/blog.webex.com\/fr\/visioconferences\/de-nouvelles-innovations-a-lere-du-travail-hybride\/\">Lancement d&rsquo;innovations in\u00e9dites \u00e0 l&rsquo;\u00e8re du travail hybride\u00a0<\/a><\/p>\n<p><a href=\"https:\/\/blog.webex.com\/fr\/visioconferences\/une-nouvelle-marque-pour-une-nouvelle-ere-de-travail-hybride-inclusif\/\">Une nouvelle marque pour une nouvelle \u00e8re du travail hybride inclusif<\/a><\/p>\n<h5><em>D\u00e9claration de responsabilit\u00e9 d&rsquo;Aragon Research : <\/em><em>Aragon Research ne cautionne nullement les fournisseurs r\u00e9f\u00e9renc\u00e9s dans ses publications de recherche, ni leurs produits ou services, et ne conseille pas aux utilisateurs de s\u00e9lectionner les fournisseurs les mieux not\u00e9s. Les publications d&rsquo;Aragon Research refl\u00e8tent uniquement les opinions de ses r\u00e9dacteurs et services d&rsquo;\u00e9valuation, et elles ne doivent en aucun cas \u00eatre consid\u00e9r\u00e9es comme des arguments irr\u00e9futables. Aragon Research publie ses travaux de recherche et les informations qu&rsquo;elles contiennent \u00ab\u00a0TELLES QUELLES\u00a0\u00bb, sans garantie d&rsquo;aucune sorte.<\/em><\/h5>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;influent cabinet d&rsquo;analystes sectoriels Aragon Research a publi\u00e9 cette semaine son cinqui\u00e8me rapport annuel Research Globe&#x2122; consacr\u00e9 aux communications unifi\u00e9es et \u00e0 la collaboration (UCC). Cisco y a une nouvelle fois \u00e9t\u00e9 identifi\u00e9 comme un leader et nous en sommes fiers.<\/p>\n","protected":false},"author":5416,"featured_media":15340,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[5253,1518,1563,1493],"tags":[5825,1612,2066,5825,5672,2393],"class_list":["post-19181","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-collaboration-fr","category-espaces-de-travail","category-experience-client","category-visioconferences","tag-recompensesprix","tag-meilleur-equipement-de-visioconference","tag-outils-de-collaboration","tag-solutions-de-collaboration","tag-travail-hybride"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cisco est nomm\u00e9 leader du classement Aragon Globe&#x2122; pour les communications unifi\u00e9es et la collaboration en 2021. | Webex Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.webex.com\/fr\/uncategorized-fr\/cisco-est-nomme-leader-du-classement-aragon-globe-pour-les-communications-unifiees-et-la-collaboration-en-2021\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cisco est nomm\u00e9 leader du classement Aragon Globe&#x2122; pour les communications unifi\u00e9es et la collaboration en 2021. | Webex Blog\" \/>\n<meta property=\"og:description\" content=\"L&#039;influent cabinet d&#039;analystes sectoriels Aragon Research a publi\u00e9 cette semaine son cinqui\u00e8me rapport annuel Research Globe&#x2122; consacr\u00e9 aux communications unifi\u00e9es et \u00e0 la collaboration (UCC). Cisco y a une nouvelle fois \u00e9t\u00e9 identifi\u00e9 comme un leader et nous en sommes fiers.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.webex.com\/fr\/uncategorized-fr\/cisco-est-nomme-leader-du-classement-aragon-globe-pour-les-communications-unifiees-et-la-collaboration-en-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"Webex Blog\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-23T20:21:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-18T06:37:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.webex.com\/wp-content\/uploads\/2021\/06\/Blog_hybrid_work_2021.06.23-975x554-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"975\" \/>\n\t<meta property=\"og:image:height\" content=\"554\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Angus Norton\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Angus Norton\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.webex.com\\\/fr\\\/uncategorized-fr\\\/cisco-est-nomme-leader-du-classement-aragon-globe-pour-les-communications-unifiees-et-la-collaboration-en-2021\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/fr\\\/uncategorized-fr\\\/cisco-est-nomme-leader-du-classement-aragon-globe-pour-les-communications-unifiees-et-la-collaboration-en-2021\\\/\"},\"author\":{\"name\":\"Angus Norton\",\"@id\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/#\\\/schema\\\/person\\\/5d3e95974e2a531a5de603e84de483b1\"},\"headline\":\"Cisco est nomm\u00e9 leader du classement Aragon Globe&#x2122; pour ...\",\"datePublished\":\"2021-06-23T20:21:46+00:00\",\"dateModified\":\"2024-09-18T06:37:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/fr\\\/uncategorized-fr\\\/cisco-est-nomme-leader-du-classement-aragon-globe-pour-les-communications-unifiees-et-la-collaboration-en-2021\\\/\"},\"wordCount\":1118,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/fr\\\/uncategorized-fr\\\/cisco-est-nomme-leader-du-classement-aragon-globe-pour-les-communications-unifiees-et-la-collaboration-en-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.webex.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Blog_hybrid_work_2021.06.23-975x554-1.jpg\",\"keywords\":[\"r\u00e9compensesPrix\",\"meilleur \u00e9quipement de visioconf\u00e9rence\",\"outils de collaboration\",\"r\u00e9compensesPrix\",\"Solutions de collaboration\",\"travail hybride\"],\"articleSection\":[\"Collaboration\",\"Espaces de travail\",\"Exp\u00e9rience client\u00a0\",\"Visioconf\u00e9rences\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.webex.com\\\/fr\\\/uncategorized-fr\\\/cisco-est-nomme-leader-du-classement-aragon-globe-pour-les-communications-unifiees-et-la-collaboration-en-2021\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.webex.com\\\/fr\\\/uncategorized-fr\\\/cisco-est-nomme-leader-du-classement-aragon-globe-pour-les-communications-unifiees-et-la-collaboration-en-2021\\\/\",\"url\":\"https:\\\/\\\/blog.webex.com\\\/fr\\\/uncategorized-fr\\\/cisco-est-nomme-leader-du-classement-aragon-globe-pour-les-communications-unifiees-et-la-collaboration-en-2021\\\/\",\"name\":\"Cisco est nomm\u00e9 leader du classement Aragon Globe&#x2122; pour les communications unifi\u00e9es et la collaboration en 2021. | Webex Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/fr\\\/uncategorized-fr\\\/cisco-est-nomme-leader-du-classement-aragon-globe-pour-les-communications-unifiees-et-la-collaboration-en-2021\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/fr\\\/uncategorized-fr\\\/cisco-est-nomme-leader-du-classement-aragon-globe-pour-les-communications-unifiees-et-la-collaboration-en-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.webex.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Blog_hybrid_work_2021.06.23-975x554-1.jpg\",\"datePublished\":\"2021-06-23T20:21:46+00:00\",\"dateModified\":\"2024-09-18T06:37:04+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/#\\\/schema\\\/person\\\/5d3e95974e2a531a5de603e84de483b1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/fr\\\/uncategorized-fr\\\/cisco-est-nomme-leader-du-classement-aragon-globe-pour-les-communications-unifiees-et-la-collaboration-en-2021\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.webex.com\\\/fr\\\/uncategorized-fr\\\/cisco-est-nomme-leader-du-classement-aragon-globe-pour-les-communications-unifiees-et-la-collaboration-en-2021\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.webex.com\\\/fr\\\/uncategorized-fr\\\/cisco-est-nomme-leader-du-classement-aragon-globe-pour-les-communications-unifiees-et-la-collaboration-en-2021\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.webex.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Blog_hybrid_work_2021.06.23-975x554-1.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.webex.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Blog_hybrid_work_2021.06.23-975x554-1.jpg\",\"width\":975,\"height\":554,\"caption\":\"Woman at her desk wearing Cisco headset and waving hello\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.webex.com\\\/fr\\\/uncategorized-fr\\\/cisco-est-nomme-leader-du-classement-aragon-globe-pour-les-communications-unifiees-et-la-collaboration-en-2021\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.webex.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cisco est nomm\u00e9 leader du classement Aragon Globe&#x2122; pour ...\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/\",\"name\":\"Webex Blog\",\"description\":\"Webex by Cisco powers collaboration through industry-leading video conferencing, cloud calling and contact center solutions\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/#\\\/schema\\\/person\\\/5d3e95974e2a531a5de603e84de483b1\",\"name\":\"Angus Norton\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5676f7d16391cd6f073f01a2a158b3627f6234a60705fc279d742b551fbe166a?s=96&d=wp_user_avatar&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5676f7d16391cd6f073f01a2a158b3627f6234a60705fc279d742b551fbe166a?s=96&d=wp_user_avatar&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5676f7d16391cd6f073f01a2a158b3627f6234a60705fc279d742b551fbe166a?s=96&d=wp_user_avatar&r=g\",\"caption\":\"Angus Norton\"},\"description\":\"Angus Norton is the Vice President of Product and Solution Marketing for Webex. Angus has been an active leader in the Technology sector for 28 years. Previous to Cisco, Angus held executive positions at Microsoft, where he was a Vice President of marketing for Office 365 in North America, at Amazon Web Services where he was the General Manager of Engineering and Design for Amazons Productivity Applications division, and at Xero, where he was the Chief Product Officer responsible for Engineering, Design and Strategy\",\"url\":\"https:\\\/\\\/blog.webex.com\\\/fr\\\/contributors\\\/annorton\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cisco est nomm\u00e9 leader du classement Aragon Globe&#x2122; pour les communications unifi\u00e9es et la collaboration en 2021. | Webex Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.webex.com\/fr\/uncategorized-fr\/cisco-est-nomme-leader-du-classement-aragon-globe-pour-les-communications-unifiees-et-la-collaboration-en-2021\/","og_locale":"fr_FR","og_type":"article","og_title":"Cisco est nomm\u00e9 leader du classement Aragon Globe&#x2122; pour les communications unifi\u00e9es et la collaboration en 2021. | Webex Blog","og_description":"L'influent cabinet d'analystes sectoriels Aragon Research a publi\u00e9 cette semaine son cinqui\u00e8me rapport annuel Research Globe&#x2122; consacr\u00e9 aux communications unifi\u00e9es et \u00e0 la collaboration (UCC). Cisco y a une nouvelle fois \u00e9t\u00e9 identifi\u00e9 comme un leader et nous en sommes fiers.","og_url":"https:\/\/blog.webex.com\/fr\/uncategorized-fr\/cisco-est-nomme-leader-du-classement-aragon-globe-pour-les-communications-unifiees-et-la-collaboration-en-2021\/","og_site_name":"Webex Blog","article_published_time":"2021-06-23T20:21:46+00:00","article_modified_time":"2024-09-18T06:37:04+00:00","og_image":[{"width":975,"height":554,"url":"https:\/\/blog.webex.com\/wp-content\/uploads\/2021\/06\/Blog_hybrid_work_2021.06.23-975x554-1.jpg","type":"image\/jpeg"}],"author":"Angus Norton","twitter_misc":{"\u00c9crit par":"Angus Norton","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.webex.com\/fr\/uncategorized-fr\/cisco-est-nomme-leader-du-classement-aragon-globe-pour-les-communications-unifiees-et-la-collaboration-en-2021\/#article","isPartOf":{"@id":"https:\/\/blog.webex.com\/fr\/uncategorized-fr\/cisco-est-nomme-leader-du-classement-aragon-globe-pour-les-communications-unifiees-et-la-collaboration-en-2021\/"},"author":{"name":"Angus Norton","@id":"https:\/\/blog.webex.com\/es\/#\/schema\/person\/5d3e95974e2a531a5de603e84de483b1"},"headline":"Cisco est nomm\u00e9 leader du classement Aragon Globe&#x2122; pour ...","datePublished":"2021-06-23T20:21:46+00:00","dateModified":"2024-09-18T06:37:04+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.webex.com\/fr\/uncategorized-fr\/cisco-est-nomme-leader-du-classement-aragon-globe-pour-les-communications-unifiees-et-la-collaboration-en-2021\/"},"wordCount":1118,"commentCount":0,"image":{"@id":"https:\/\/blog.webex.com\/fr\/uncategorized-fr\/cisco-est-nomme-leader-du-classement-aragon-globe-pour-les-communications-unifiees-et-la-collaboration-en-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.webex.com\/wp-content\/uploads\/2021\/06\/Blog_hybrid_work_2021.06.23-975x554-1.jpg","keywords":["r\u00e9compensesPrix","meilleur \u00e9quipement de visioconf\u00e9rence","outils de collaboration","r\u00e9compensesPrix","Solutions de collaboration","travail hybride"],"articleSection":["Collaboration","Espaces de travail","Exp\u00e9rience client\u00a0","Visioconf\u00e9rences"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.webex.com\/fr\/uncategorized-fr\/cisco-est-nomme-leader-du-classement-aragon-globe-pour-les-communications-unifiees-et-la-collaboration-en-2021\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.webex.com\/fr\/uncategorized-fr\/cisco-est-nomme-leader-du-classement-aragon-globe-pour-les-communications-unifiees-et-la-collaboration-en-2021\/","url":"https:\/\/blog.webex.com\/fr\/uncategorized-fr\/cisco-est-nomme-leader-du-classement-aragon-globe-pour-les-communications-unifiees-et-la-collaboration-en-2021\/","name":"Cisco est nomm\u00e9 leader du classement Aragon Globe&#x2122; pour les communications unifi\u00e9es et la collaboration en 2021. | Webex Blog","isPartOf":{"@id":"https:\/\/blog.webex.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.webex.com\/fr\/uncategorized-fr\/cisco-est-nomme-leader-du-classement-aragon-globe-pour-les-communications-unifiees-et-la-collaboration-en-2021\/#primaryimage"},"image":{"@id":"https:\/\/blog.webex.com\/fr\/uncategorized-fr\/cisco-est-nomme-leader-du-classement-aragon-globe-pour-les-communications-unifiees-et-la-collaboration-en-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.webex.com\/wp-content\/uploads\/2021\/06\/Blog_hybrid_work_2021.06.23-975x554-1.jpg","datePublished":"2021-06-23T20:21:46+00:00","dateModified":"2024-09-18T06:37:04+00:00","author":{"@id":"https:\/\/blog.webex.com\/es\/#\/schema\/person\/5d3e95974e2a531a5de603e84de483b1"},"breadcrumb":{"@id":"https:\/\/blog.webex.com\/fr\/uncategorized-fr\/cisco-est-nomme-leader-du-classement-aragon-globe-pour-les-communications-unifiees-et-la-collaboration-en-2021\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.webex.com\/fr\/uncategorized-fr\/cisco-est-nomme-leader-du-classement-aragon-globe-pour-les-communications-unifiees-et-la-collaboration-en-2021\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.webex.com\/fr\/uncategorized-fr\/cisco-est-nomme-leader-du-classement-aragon-globe-pour-les-communications-unifiees-et-la-collaboration-en-2021\/#primaryimage","url":"https:\/\/blog.webex.com\/wp-content\/uploads\/2021\/06\/Blog_hybrid_work_2021.06.23-975x554-1.jpg","contentUrl":"https:\/\/blog.webex.com\/wp-content\/uploads\/2021\/06\/Blog_hybrid_work_2021.06.23-975x554-1.jpg","width":975,"height":554,"caption":"Woman at her desk wearing Cisco headset and waving hello"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.webex.com\/fr\/uncategorized-fr\/cisco-est-nomme-leader-du-classement-aragon-globe-pour-les-communications-unifiees-et-la-collaboration-en-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.webex.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Cisco est nomm\u00e9 leader du classement Aragon Globe&#x2122; pour ..."}]},{"@type":"WebSite","@id":"https:\/\/blog.webex.com\/es\/#website","url":"https:\/\/blog.webex.com\/es\/","name":"Webex Blog","description":"Webex by Cisco powers collaboration through industry-leading video conferencing, cloud calling and contact center solutions","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.webex.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/blog.webex.com\/es\/#\/schema\/person\/5d3e95974e2a531a5de603e84de483b1","name":"Angus Norton","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/5676f7d16391cd6f073f01a2a158b3627f6234a60705fc279d742b551fbe166a?s=96&d=wp_user_avatar&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5676f7d16391cd6f073f01a2a158b3627f6234a60705fc279d742b551fbe166a?s=96&d=wp_user_avatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5676f7d16391cd6f073f01a2a158b3627f6234a60705fc279d742b551fbe166a?s=96&d=wp_user_avatar&r=g","caption":"Angus Norton"},"description":"Angus Norton is the Vice President of Product and Solution Marketing for Webex. Angus has been an active leader in the Technology sector for 28 years. Previous to Cisco, Angus held executive positions at Microsoft, where he was a Vice President of marketing for Office 365 in North America, at Amazon Web Services where he was the General Manager of Engineering and Design for Amazons Productivity Applications division, and at Xero, where he was the Chief Product Officer responsible for Engineering, Design and Strategy","url":"https:\/\/blog.webex.com\/fr\/contributors\/annorton\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.webex.com\/fr\/wp-json\/wp\/v2\/posts\/19181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.webex.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.webex.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.webex.com\/fr\/wp-json\/wp\/v2\/users\/5416"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.webex.com\/fr\/wp-json\/wp\/v2\/comments?post=19181"}],"version-history":[{"count":0,"href":"https:\/\/blog.webex.com\/fr\/wp-json\/wp\/v2\/posts\/19181\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.webex.com\/fr\/wp-json\/wp\/v2\/media\/15340"}],"wp:attachment":[{"href":"https:\/\/blog.webex.com\/fr\/wp-json\/wp\/v2\/media?parent=19181"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.webex.com\/fr\/wp-json\/wp\/v2\/categories?post=19181"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.webex.com\/fr\/wp-json\/wp\/v2\/tags?post=19181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}