{"id":384411,"date":"2020-03-31T05:49:04","date_gmt":"2020-03-31T12:49:04","guid":{"rendered":"https:\/\/blog.webex.com\/uncategorized-fr\/de-la-conference-numerique-au-travail-depuis-chez-vous-la-collaboration-cisco-vous-aide\/"},"modified":"2024-09-17T23:37:38","modified_gmt":"2024-09-18T06:37:38","slug":"de-la-conference-numerique-au-travail-depuis-chez-vous-la-collaboration-cisco-vous-aide","status":"publish","type":"post","link":"https:\/\/blog.webex.com\/fr\/collaboration-fr\/visioconferences\/de-la-conference-numerique-au-travail-depuis-chez-vous-la-collaboration-cisco-vous-aide\/","title":{"rendered":"De la conf\u00e9rence num\u00e9rique au travail depuis chez vous, la ..."},"content":{"rendered":"<h2><span><br \/>\n  <strong>Cisco + NVIDIA Utilisez AI &#038; Machine Learning pour cr\u00e9er des exp\u00e9riences extraordinaires pour travailler o\u00f9 que vous soyez<\/strong><br \/>\n<\/span><\/h2>\n<p>Nous sommes fi\u00e8res de dire que nous avons fait un partenariat avec NVIDIA depuis un certain temps maintenant. Le processeur NVIDIA permet de faire la puissance de Cisco Webex Ensemble, s\u00e9rie de salles, s\u00e9ries de kits de salles, Webex Boards le DeskPro. Le chipset permet d\u2019activer l\u2019intelligence du syst\u00e8me Assistant Webex, la reconnaissance faciale, la suppression du bruit et le meilleur affichage pour cadrer les participants de la r\u00e9union. Ces fonctionnalit\u00e9s restent essentielles pour s\u2019adapter au travail \u00e0 distance.<\/p>\n<p>Pour ceux d\u2019entre nous qui ont l\u2019habitude de travailler dans un bureau dans lequel nous rencontrons nos coll\u00e8gues face \u00e0 face et r\u00e9unissent nos \u00e9quipes dans le m\u00eame espace physique pour collaborer pour travailler et travailler \u00e0 distance, le travail \u00e0 distance peut \u00eatre un ajustement.<\/p>\n<p>Mais les technologies de la marque Cisco et NVIDIA peuvent faciliter l\u2019ajustement et rendre le travail \u00e0 distance plus confortable et plus productif.<\/p>\n<h2><span><br \/>\n  <strong>La vid\u00e9o et l\u2019audio de qualit\u00e9 sont essentiels pour la participation au travail \u00e0 domicile.<\/strong><br \/>\n<\/span><\/h2>\n<p>La semaine derni\u00e8re, Jason Jason Jason, Directeur de la croissance &#038;strategic Communication pour Webex Rooms chez Cisco, a publi\u00e9 Workplace Turn On Video &#8211; Ce n\u2019est plus facultatif, d\u00e9crivant comment la vid\u00e9oconf\u00e9rence est le moyen le plus efficace d\u2019activer la communication face \u00e0 face lors du travail \u00e0 <a href=\"https:\/\/blogs.cisco.com\/collaboration\/workplace-experiences-turnonvideo-its-no-longer-optional\"><\/a> distance. La vid\u00e9o nous permet de faire un contact visuel et d\u2019avoir des indications non verbales telles que les expressions faciales et le langage corporel. Les participants peuvent voir comment leurs commentaires sont re\u00e7us. Les dirigeants peuvent \u00e9valuer si et quand la discussion est en train de perdre l\u2019attention des participants.<\/p>\n<p>Dans un deuxi\u00e8me article, <a href=\"https:\/\/blogs.cisco.com\/collaboration\/workplace-experiences-how-remote-work-is-transforming-the-workplace\">Exp\u00e9riences du lieu de travail : Comment Le travail \u00e0 distance transforme le site Workplace Sandeep Meitude souligne qu\u2019en<\/a> 2024, Gartner estime que seules 25 % des r\u00e9unions d\u2019entreprise se d\u00e9rouleront en personne.<br \/>\nNous entendons beaucoup la part des dirigeants d\u2019organisations que l\u2019utilisation de la vid\u00e9o contribue au moral et \u00e0 la sant\u00e9 du personnel alors que les gens continuent de se sentir isol\u00e9s dans le travail \u00e0 distance.<\/p>\n<p>L\u2019utilisation d\u2019applications A\/V \u00e0 domicile peut ne pas \u00eatre imm\u00e9diatement intuitive ou naturelle pour certains travailleurs distants. Toutefois, Cisco Webex vid\u00e9o de qualit\u00e9 sont riches en ai\/PRINCIPAL con\u00e7us pour atteindre le but exact de faciliter la connexion avec les \u00e9quipes pour les formations professionnelles ou sociaux et leur exp\u00e9rience professionnelle et intuitive, avec l\u2019audio et la vid\u00e9o ad\u00e9quats pour une implication maximale. Cette intelligence est optimis\u00e9e par le chip Jetson de NVIDIA, ce qui all\u00e8ge beaucoup les g\u00eanes et aide les employ\u00e9s \u00e0 travailler \u00e0 domicile en tant que nouvelle nouveaut\u00e9.<\/p>\n<h2><span><br \/>\n  <strong>Fermeture social et Distancing physique avec Webex<\/strong><br \/>\n<\/span><\/h2>\n<p>Rester chez vous ne signifie pas que vous devez manquer des espaces de travail tels que l\u2019aptitude et socialiser avec des coll\u00e8gues. Notre \u00e9quipe Cisco Webex en Norv\u00e8ge a commenc\u00e9 \u00e0 diriger quotidiennement le web via un syst\u00e8me d\u2019visioconf\u00e9rence, qui en r\u00e9sulte de leur confort total avec la vid\u00e9o et l\u2019audio pour une collaboration un \u00e0 un, ou de groupe, et apporte l\u2019unit\u00e9 social m\u00eame lorsqu\u2019il est responsable du num\u00e9rique.<\/p>\n<p><a href=\"https:\/\/storage.googleapis.com\/blogs-images\/ciscoblogs\/1\/2020\/03\/6af8ad0a-screen-shot-2020-03-30-at-8.09.36-am.png\">   <img loading=\"lazy\" decoding=\"async\" class=\"wp-image-317311\" src=\"https:\/\/storage.googleapis.com\/blogs-images\/ciscoblogs\/1\/2020\/03\/6af8ad0a-screen-shot-2020-03-30-at-8.09.36-am.png\" alt=\"De la conf\u00e9rence num\u00e9rique au travail depuis chez vous, la collaboration Cisco vous aide \" width=\"800\" height=\"408\" \/> <\/a> <em>Notre \u00e9quipe bas\u00e9e en Angleterre utilise Webex pour un check-in en temps r\u00e9el pour rester connect\u00e9e. En outre, notre Cisco Webex en Norv\u00e8ge a commenc\u00e9 \u00e0 diriger le web quotidiennement via visioconf\u00e9rence.<\/em>[\/sous-titre]<\/p>\n<h2><span><br \/>\n  <strong>La technologie AI et999,QUI fonctionne en arri\u00e8re-plan pour que votre exp\u00e9rience de r\u00e9union soit confortable<\/strong><br \/>\n<\/span><\/h2>\n<p>Une vid\u00e9o peut \u00e9galement se r\u00e9v\u00e9ler inutile pour les employ\u00e9s distants qui ne souhaitent pas exposer l\u2019arri\u00e8re-plan de leur domicile \u00e0 leurs coll\u00e8gues. Avec le nouveau Cisco Webex Desk Pro, vous pouvez facilement flouter l\u2019arri\u00e8re-plan existant de votre bureau d\u2019accueil, ou choisir un environnement plus agr\u00e9able ou plus agr\u00e9able pour masquer le mess ou du trouble derri\u00e8re vous pour vous concentrer sur ce que vous essayez de faire.<\/p>\n<p>Une autre g\u00eane du travail \u00e0 domicile peut \u00eatre des bruits de fond impr\u00e9visibles. Avec l\u2019apprentissage de la machine via le chipset NVIDIA, nos p\u00e9riph\u00e9riques peuvent parler avec la voix dans d\u2019autres bruits de fond tels qu\u2019aboiement d\u2019un chien, d\u2019une fl\u00e8che d\u2019intonation ou de la faute de frappe bruyante.<\/p>\n<p>Et juste parce que vous travaillez de la maison, vous n\u2019avez pas besoin d\u2019\u00eatre attach\u00e9 \u00e0 votre chaise. Gr\u00e2ce \u00e0 notre cam\u00e9ra d\u2019auto-d\u00e9tection, vous pouvez vous \u00e9loigner de votre chaise, vous d\u00e9placer comme vous le souhaitez et laisser la technologie IA de votre p\u00e9riph\u00e9rique Webex mettre le focus sur la cam\u00e9ra avec nos fonctionnalit\u00e9s de d\u00e9tection faciale. Il vous rage la vid\u00e9o et les images automatiques pendant que vous d\u00e9couvrez une mani\u00e8re naturelle de collaborer comme vous le feriez en personne, peut-\u00eatre mieux qu\u2019en personne.<\/p>\n<p>Avec la reconnaissance faciale, vous pouvez \u00e9galement voir les \u00e9tiquettes des participants \u00e0 vos r\u00e9unions pour vous donner plus de contexte pour une exp\u00e9rience de r\u00e9union plus personnelle.<\/p>\n<p>Tout cet apprentissage machine et IA incroyables se d\u00e9roulent directement sur le p\u00e9riph\u00e9rique, ce qui augmente la vitesse de calcul tout en r\u00e9duisant la bande passante et la latence de travers\u00e9e vers le Cloud pour la fonctionnalit\u00e9 cognitive.<\/p>\n<p>Avec Cisco Collaboration et le chipset NVIDIA, nous contr\u00f4lons l\u2019exp\u00e9rience de bout en bout pour un confort maximum lorsque vous dirigez des r\u00e9unions d\u2019un domicile \u00e0 l\u2019autre car nous optimisons tout le parcours d\u2019un p\u00e9riph\u00e9rique vers un r\u00e9seau vers l\u2019application du Cloud vers l\u2019autre point de terminaison.<\/p>\n<h2><span><br \/>\n  <strong><br \/>\n    <span>collaboration en salle<\/span><br \/>\n  <\/strong><br \/>\n<\/span><\/h2>\n<p>Pour r\u00e9capituler, la meilleure exp\u00e9rience de collaboration \u00e0 domicile est activ\u00e9e avec :<\/p>\n<ul>\n<li>Vid\u00e9o et audio sup\u00e9rieurs<\/li>\n<li>Flout\u00e9 d\u2019arri\u00e8re-plan ou modification sur la vid\u00e9o<\/li>\n<li>D\u00e9tection intelligente de la voix pour tonalit\u00e9 d\u2019autres bruits de fond<\/li>\n<li>Cadrage vid\u00e9o automatique<\/li>\n<li>Noms des balises des participants de la r\u00e9union<\/li>\n<\/ul>\n<p>Que vous la rejoignez \u00e0 Webex Teams ou \u00e0 partir de Meetings, vous b\u00e9n\u00e9ficiez de la m\u00eame exp\u00e9rience et du m\u00eame confort. Ceci est activ\u00e9 sur presque tout le portefeuille des p\u00e9riph\u00e9riques Webex Rooms avec le chip NVIDIA Jetson int\u00e9gr\u00e9, qui inclut les s\u00e9ries Webex Board, RoomJet, Desk Pro, Room et Kit de salle.<\/p>\n<h2><span><br \/>\n  <strong>En conclusion<\/strong><br \/>\n<\/span><\/h2>\n<p>Webex est la plate-forme professionnelle n\u00b0 1 de la collaboration vid\u00e9o dans le monde, mais il ne s\u2019agit pas seulement de la vid\u00e9oconf\u00e9rence. Elle est plus int\u00e9gr\u00e9e. Elle est plus s\u00e9curis\u00e9e. Elle est plus fiable. Et encore plus important, elle est facile \u00e0 utiliser, ce qui signifie que les autorit\u00e9s, les universit\u00e9s, les entreprises et les personnes comme vous et moi-m\u00eame pouvons se mettre en ligne, \u00eatre sur la vid\u00e9o et collaborer \u00e0 distance plus rapidement et de mani\u00e8re fiable.\u00a0Plus l\u2019exp\u00e9rience est dirig\u00e9e vers une plus grande implication de collaborateurs et des exp\u00e9riences simplifi\u00e9es et intuitives qui am\u00e9liorent le confort et l\u2019adoption, si bien que le travail \u00e0 domicile est moins cher et plus productif. Alors que nous sommes tous en pr\u00e9paration de la gestion de la gestion de l\u2019environnement d\u2019aujourd\u2019hui, nous nous pr\u00e9parons \u00e0 une v\u00e9ritable transformation du lieu de travail, o\u00f9 les diff\u00e9rences de notre personnel, de notre travail et de nos espaces de travail reviennent \u00e0 des exp\u00e9riences collaboratives centr\u00e9es sur l\u2019environnement humain qui donnent un plus grand sens \u00e0 nos contributions.<\/p>\n<blockquote>\n<p><strong><br \/>\n  <a href=\"https:\/\/www.cisco.com\/c\/dam\/en\/us\/products\/collateral\/collaboration-endpoints\/designing-the-workplace-for-collaboration.pdf\">D\u00e9couvrez comment les p\u00e9riph\u00e9riques de collaboration peuvent prendre en charge la transformation de votre lieu de travail<\/a><br \/>\n<\/strong><\/p>\n<\/blockquote>\n<p>\u00a0<\/p>\n<p><a href=\"https:\/\/storage.googleapis.com\/blogs-images\/ciscoblogs\/1\/2020\/03\/87e0cf31-between-moving-to-the-cloud-and-unleashing-its-full-potential.png\"><br \/>\n  <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-317176\" src=\"https:\/\/storage.googleapis.com\/blogs-images\/ciscoblogs\/1\/2020\/03\/87e0cf31-between-moving-to-the-cloud-and-unleashing-its-full-potential.png\" alt=\"Des conf\u00e9rences num\u00e9riques au travail depuis chez vous, la collaboration Cisco vous aide. Une banni\u00e8re qui lit - Entre passer du cloud \u00e0 l\u2019autoportation de son plein potentiel, il y a une passerelle, Cisco, le pont jusqu\u2019au possible, en haut d\u2019une portrait en arri\u00e8re-plan d\u2019un gens qui passe sur un studio\" width=\"750\" height=\"420\" \/><br \/>\n<\/a><\/p>\n<p>\u00a0<\/p>\n<hr \/>\n<p><strong>En savoir plus<\/strong>  <a href=\"https:\/\/blogs.cisco.com\/collaboration\/work-from-home-best-practices\">sur le travail \u00e0 partir des Meilleures pratiques personnelles<\/a>  <a href=\"https:\/\/blogs.cisco.com\/collaboration\/workplace-experiences-turnonvideo-its-no-longer-optional\">Exp\u00e9riences sur le lieu de travail : #TurnOnVideo \u2013 Ce n\u2019est plus facultatif Pouvons-nous mettre en place un workflow de collaboration<\/a>  <a href=\"https:\/\/blogs.cisco.com\/collaboration\/can-we-get-on-with-a-distributed-collaborative-workflow-please\">distribu\u00e9, S\u2019il vous plait ?<\/a>  <a href=\"https:\/\/www.cisco.com\/c\/dam\/en\/us\/products\/collateral\/collaboration-endpoints\/designing-the-workplace-for-collaboration.pdf\">Ebook: Concevoir le lieu de travail pour la collaboration<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>NVIDIA et Cisco ont con\u00e7u une solution qui vous aide \u00e0 acc\u00e9l\u00e9rer vos charges de travail IA et CASA<\/p>\n","protected":false},"author":5462,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[5253,1493],"tags":[5672,4730,2393],"class_list":["post-384411","post","type-post","status-publish","format-standard","hentry","category-collaboration-fr","category-visioconferences","tag-solutions-de-collaboration","tag-intelligence-artificielle","tag-travail-hybride"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>De la conf\u00e9rence num\u00e9rique au travail depuis chez vous, la collaboration Cisco vous aide | Webex Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.webex.com\/collaboration\/video-conferencing\/from-digital-conferences-to-work-from-home-cisco-collaboration-has-got-your-back\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"De la conf\u00e9rence num\u00e9rique au travail depuis chez vous, la collaboration Cisco vous aide | Webex Blog\" \/>\n<meta property=\"og:description\" content=\"NVIDIA et Cisco ont con\u00e7u une solution qui vous aide \u00e0 acc\u00e9l\u00e9rer vos charges de travail IA et CASA\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.webex.com\/collaboration\/video-conferencing\/from-digital-conferences-to-work-from-home-cisco-collaboration-has-got-your-back\/\" \/>\n<meta property=\"og:site_name\" content=\"Webex Blog\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-31T12:49:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-18T06:37:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/storage.googleapis.com\/blogs-images\/ciscoblogs\/1\/2020\/03\/6af8ad0a-screen-shot-2020-03-30-at-8.09.36-am.png\" \/>\n<meta name=\"author\" content=\"Sonali Karnik\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sonali Karnik\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/blog.webex.com\/collaboration\/video-conferencing\/from-digital-conferences-to-work-from-home-cisco-collaboration-has-got-your-back\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/blog.webex.com\/collaboration\/video-conferencing\/from-digital-conferences-to-work-from-home-cisco-collaboration-has-got-your-back\/\"},\"author\":{\"name\":\"Sonali Karnik\",\"@id\":\"https:\/\/blog.webex.com\/es\/#\/schema\/person\/67978c5cfed6bf2762e5f2210e3c517f\"},\"headline\":\"De la conf\u00e9rence num\u00e9rique au travail depuis chez vous, la ...\",\"datePublished\":\"2020-03-31T12:49:04+00:00\",\"dateModified\":\"2024-09-18T06:37:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/blog.webex.com\/collaboration\/video-conferencing\/from-digital-conferences-to-work-from-home-cisco-collaboration-has-got-your-back\/\"},\"wordCount\":1402,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/blog.webex.com\/collaboration\/video-conferencing\/from-digital-conferences-to-work-from-home-cisco-collaboration-has-got-your-back\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/storage.googleapis.com\/blogs-images\/ciscoblogs\/1\/2020\/03\/6af8ad0a-screen-shot-2020-03-30-at-8.09.36-am.png\",\"keywords\":[\"Solutions de collaboration\",\"intelligence artificielle\",\"travail hybride\"],\"articleSection\":[\"Collaboration\",\"Visioconf\u00e9rences\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/blog.webex.com\/collaboration\/video-conferencing\/from-digital-conferences-to-work-from-home-cisco-collaboration-has-got-your-back\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/blog.webex.com\/collaboration\/video-conferencing\/from-digital-conferences-to-work-from-home-cisco-collaboration-has-got-your-back\/\",\"url\":\"https:\/\/blog.webex.com\/collaboration\/video-conferencing\/from-digital-conferences-to-work-from-home-cisco-collaboration-has-got-your-back\/\",\"name\":\"De la conf\u00e9rence num\u00e9rique au travail depuis chez vous, la collaboration Cisco vous aide | Webex Blog\",\"isPartOf\":{\"@id\":\"https:\/\/blog.webex.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/blog.webex.com\/collaboration\/video-conferencing\/from-digital-conferences-to-work-from-home-cisco-collaboration-has-got-your-back\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/blog.webex.com\/collaboration\/video-conferencing\/from-digital-conferences-to-work-from-home-cisco-collaboration-has-got-your-back\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/storage.googleapis.com\/blogs-images\/ciscoblogs\/1\/2020\/03\/6af8ad0a-screen-shot-2020-03-30-at-8.09.36-am.png\",\"datePublished\":\"2020-03-31T12:49:04+00:00\",\"dateModified\":\"2024-09-18T06:37:38+00:00\",\"author\":{\"@id\":\"https:\/\/blog.webex.com\/es\/#\/schema\/person\/67978c5cfed6bf2762e5f2210e3c517f\"},\"breadcrumb\":{\"@id\":\"https:\/\/blog.webex.com\/collaboration\/video-conferencing\/from-digital-conferences-to-work-from-home-cisco-collaboration-has-got-your-back\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/blog.webex.com\/collaboration\/video-conferencing\/from-digital-conferences-to-work-from-home-cisco-collaboration-has-got-your-back\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/blog.webex.com\/collaboration\/video-conferencing\/from-digital-conferences-to-work-from-home-cisco-collaboration-has-got-your-back\/#primaryimage\",\"url\":\"https:\/\/storage.googleapis.com\/blogs-images\/ciscoblogs\/1\/2020\/03\/6af8ad0a-screen-shot-2020-03-30-at-8.09.36-am.png\",\"contentUrl\":\"https:\/\/storage.googleapis.com\/blogs-images\/ciscoblogs\/1\/2020\/03\/6af8ad0a-screen-shot-2020-03-30-at-8.09.36-am.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blog.webex.com\/collaboration\/video-conferencing\/from-digital-conferences-to-work-from-home-cisco-collaboration-has-got-your-back\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/blog.webex.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"De la conf\u00e9rence num\u00e9rique au travail depuis chez vous, la ...\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blog.webex.com\/es\/#website\",\"url\":\"https:\/\/blog.webex.com\/es\/\",\"name\":\"Webex Blog\",\"description\":\"Webex by Cisco powers collaboration through industry-leading video conferencing, cloud calling and contact center solutions\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blog.webex.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/blog.webex.com\/es\/#\/schema\/person\/67978c5cfed6bf2762e5f2210e3c517f\",\"name\":\"Sonali Karnik\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/blog.webex.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1db95c5d8a59c0eea620a73455fccf85b4522095cf6e26c192be856c2822955c?s=96&d=wp_user_avatar&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1db95c5d8a59c0eea620a73455fccf85b4522095cf6e26c192be856c2822955c?s=96&d=wp_user_avatar&r=g\",\"caption\":\"Sonali Karnik\"},\"description\":\"Sonali Karnik is a Senior Manager in Cisco Cloud Calling Product Marketing, responsible for marketing cloud calling offers through the Service Provider and VAR channels. She has over 20 years of industry experience and was with BroadSoft for the past 18 years in Sales and Marketing roles. While in Sales for 15 years, she was Director of the North American Sales Engineering team, and then transitioned to BroadSoft Marketing working with the CMO on New Product Introduction and Awareness of cloud calling on the industry leading secure, reliable, and feature-rich platforms trusted by the Service Providers.\",\"url\":\"https:\/\/blog.webex.com\/fr\/contributors\/sonalikarnik\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"De la conf\u00e9rence num\u00e9rique au travail depuis chez vous, la collaboration Cisco vous aide | Webex Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.webex.com\/collaboration\/video-conferencing\/from-digital-conferences-to-work-from-home-cisco-collaboration-has-got-your-back\/","og_locale":"fr_FR","og_type":"article","og_title":"De la conf\u00e9rence num\u00e9rique au travail depuis chez vous, la collaboration Cisco vous aide | Webex Blog","og_description":"NVIDIA et Cisco ont con\u00e7u une solution qui vous aide \u00e0 acc\u00e9l\u00e9rer vos charges de travail IA et CASA","og_url":"https:\/\/blog.webex.com\/collaboration\/video-conferencing\/from-digital-conferences-to-work-from-home-cisco-collaboration-has-got-your-back\/","og_site_name":"Webex Blog","article_published_time":"2020-03-31T12:49:04+00:00","article_modified_time":"2024-09-18T06:37:38+00:00","og_image":[{"url":"https:\/\/storage.googleapis.com\/blogs-images\/ciscoblogs\/1\/2020\/03\/6af8ad0a-screen-shot-2020-03-30-at-8.09.36-am.png","type":"","width":"","height":""}],"author":"Sonali Karnik","twitter_misc":{"\u00c9crit par":"Sonali Karnik","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.webex.com\/collaboration\/video-conferencing\/from-digital-conferences-to-work-from-home-cisco-collaboration-has-got-your-back\/#article","isPartOf":{"@id":"https:\/\/blog.webex.com\/collaboration\/video-conferencing\/from-digital-conferences-to-work-from-home-cisco-collaboration-has-got-your-back\/"},"author":{"name":"Sonali Karnik","@id":"https:\/\/blog.webex.com\/es\/#\/schema\/person\/67978c5cfed6bf2762e5f2210e3c517f"},"headline":"De la conf\u00e9rence num\u00e9rique au travail depuis chez vous, la ...","datePublished":"2020-03-31T12:49:04+00:00","dateModified":"2024-09-18T06:37:38+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.webex.com\/collaboration\/video-conferencing\/from-digital-conferences-to-work-from-home-cisco-collaboration-has-got-your-back\/"},"wordCount":1402,"commentCount":0,"image":{"@id":"https:\/\/blog.webex.com\/collaboration\/video-conferencing\/from-digital-conferences-to-work-from-home-cisco-collaboration-has-got-your-back\/#primaryimage"},"thumbnailUrl":"https:\/\/storage.googleapis.com\/blogs-images\/ciscoblogs\/1\/2020\/03\/6af8ad0a-screen-shot-2020-03-30-at-8.09.36-am.png","keywords":["Solutions de collaboration","intelligence artificielle","travail hybride"],"articleSection":["Collaboration","Visioconf\u00e9rences"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.webex.com\/collaboration\/video-conferencing\/from-digital-conferences-to-work-from-home-cisco-collaboration-has-got-your-back\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.webex.com\/collaboration\/video-conferencing\/from-digital-conferences-to-work-from-home-cisco-collaboration-has-got-your-back\/","url":"https:\/\/blog.webex.com\/collaboration\/video-conferencing\/from-digital-conferences-to-work-from-home-cisco-collaboration-has-got-your-back\/","name":"De la conf\u00e9rence num\u00e9rique au travail depuis chez vous, la collaboration Cisco vous aide | Webex Blog","isPartOf":{"@id":"https:\/\/blog.webex.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.webex.com\/collaboration\/video-conferencing\/from-digital-conferences-to-work-from-home-cisco-collaboration-has-got-your-back\/#primaryimage"},"image":{"@id":"https:\/\/blog.webex.com\/collaboration\/video-conferencing\/from-digital-conferences-to-work-from-home-cisco-collaboration-has-got-your-back\/#primaryimage"},"thumbnailUrl":"https:\/\/storage.googleapis.com\/blogs-images\/ciscoblogs\/1\/2020\/03\/6af8ad0a-screen-shot-2020-03-30-at-8.09.36-am.png","datePublished":"2020-03-31T12:49:04+00:00","dateModified":"2024-09-18T06:37:38+00:00","author":{"@id":"https:\/\/blog.webex.com\/es\/#\/schema\/person\/67978c5cfed6bf2762e5f2210e3c517f"},"breadcrumb":{"@id":"https:\/\/blog.webex.com\/collaboration\/video-conferencing\/from-digital-conferences-to-work-from-home-cisco-collaboration-has-got-your-back\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.webex.com\/collaboration\/video-conferencing\/from-digital-conferences-to-work-from-home-cisco-collaboration-has-got-your-back\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.webex.com\/collaboration\/video-conferencing\/from-digital-conferences-to-work-from-home-cisco-collaboration-has-got-your-back\/#primaryimage","url":"https:\/\/storage.googleapis.com\/blogs-images\/ciscoblogs\/1\/2020\/03\/6af8ad0a-screen-shot-2020-03-30-at-8.09.36-am.png","contentUrl":"https:\/\/storage.googleapis.com\/blogs-images\/ciscoblogs\/1\/2020\/03\/6af8ad0a-screen-shot-2020-03-30-at-8.09.36-am.png"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.webex.com\/collaboration\/video-conferencing\/from-digital-conferences-to-work-from-home-cisco-collaboration-has-got-your-back\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.webex.com\/fr\/"},{"@type":"ListItem","position":2,"name":"De la conf\u00e9rence num\u00e9rique au travail depuis chez vous, la ..."}]},{"@type":"WebSite","@id":"https:\/\/blog.webex.com\/es\/#website","url":"https:\/\/blog.webex.com\/es\/","name":"Webex Blog","description":"Webex by Cisco powers collaboration through industry-leading video conferencing, cloud calling and contact center solutions","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.webex.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/blog.webex.com\/es\/#\/schema\/person\/67978c5cfed6bf2762e5f2210e3c517f","name":"Sonali Karnik","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.webex.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1db95c5d8a59c0eea620a73455fccf85b4522095cf6e26c192be856c2822955c?s=96&d=wp_user_avatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1db95c5d8a59c0eea620a73455fccf85b4522095cf6e26c192be856c2822955c?s=96&d=wp_user_avatar&r=g","caption":"Sonali Karnik"},"description":"Sonali Karnik is a Senior Manager in Cisco Cloud Calling Product Marketing, responsible for marketing cloud calling offers through the Service Provider and VAR channels. She has over 20 years of industry experience and was with BroadSoft for the past 18 years in Sales and Marketing roles. While in Sales for 15 years, she was Director of the North American Sales Engineering team, and then transitioned to BroadSoft Marketing working with the CMO on New Product Introduction and Awareness of cloud calling on the industry leading secure, reliable, and feature-rich platforms trusted by the Service Providers.","url":"https:\/\/blog.webex.com\/fr\/contributors\/sonalikarnik\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.webex.com\/fr\/wp-json\/wp\/v2\/posts\/384411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.webex.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.webex.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.webex.com\/fr\/wp-json\/wp\/v2\/users\/5462"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.webex.com\/fr\/wp-json\/wp\/v2\/comments?post=384411"}],"version-history":[{"count":0,"href":"https:\/\/blog.webex.com\/fr\/wp-json\/wp\/v2\/posts\/384411\/revisions"}],"wp:attachment":[{"href":"https:\/\/blog.webex.com\/fr\/wp-json\/wp\/v2\/media?parent=384411"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.webex.com\/fr\/wp-json\/wp\/v2\/categories?post=384411"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.webex.com\/fr\/wp-json\/wp\/v2\/tags?post=384411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}