{"id":384650,"date":"2020-05-06T16:34:40","date_gmt":"2020-05-06T23:34:40","guid":{"rendered":"https:\/\/blog.webex.com\/uncategorized-fr\/future-de-la-serie-de-marathons-travail-apercus-du-jour-tendances-sur-lavenir-du-travail\/"},"modified":"2024-09-17T23:37:35","modified_gmt":"2024-09-18T06:37:35","slug":"future-de-la-serie-de-marathons-travail-apercus-du-jour-tendances-sur-lavenir-du-travail","status":"publish","type":"post","link":"https:\/\/blog.webex.com\/fr\/collaboration-fr\/future-de-la-serie-de-marathons-travail-apercus-du-jour-tendances-sur-lavenir-du-travail\/","title":{"rendered":"Future de la s\u00e9rie de marathons travail \u2013 Aper\u00e7us du jour &#038; ..."},"content":{"rendered":"<h2><span><br \/>\n  <strong>Aper\u00e7u des experts &#038;tendances sur l\u2019avenir du travail<\/strong><br \/>\n<\/span><\/h2>\n<p>Notre quotidien et notre routine ont r\u00e9cemment beaucoup chang\u00e9, nous laissant nous demander ce qu\u2019il en est de la suite et \u00e0 quoi ressemblera le travail \u00e0 venir.\u00a0Pour aider les entreprises \u00e0 naviguer dans notre nouvelle normale, la s\u00e9rie de marathons De l\u2019avenir du travail s\u2019est lanc\u00e9 aujourd\u2019hui avec des aper\u00e7us experts et des tendances sur l\u2019avenir du travail.<\/p>\n<p>Mike Keynote, directeur g\u00e9n\u00e9ral de Tomorrow, s\u2019est lanc\u00e9 dans la conf\u00e9rence avec \u00ab\u00a0La r\u00e9volution du travail \u00e0 distance\u00a0\u00bb.\u00a0Il a fait le point sur notre situation actuelle de travail \u00e0 distance, en notant que l\u2019acc\u00e9l\u00e9ration de la virtualisation internationale changera la fa\u00e7on dont nous allons interagir avec nos clients, concevoir nos organisations et \u00e9quipes, et ce que signifie \u00eatre un leader efficace.\u00a0Il a notamment reconnu que, prochainement, il n\u2019y aura rien de tel que le travail \u00e0 distance: il suffit de travailler.<\/p>\n<p>Le deuxi\u00e8me animateur du jour, Michael George, directeur g\u00e9n\u00e9ral de Great Place to Work, est tr\u00e8s agr\u00e9able \u00e0 travailler avec des crit\u00e8res qui doivent \u00eatre un excellent endroit de travail. Bas\u00e9 sur des recherches men\u00e9es \u00e0 travers le monde avec des millions de personnes, il a parl\u00e9 des meilleures pratiques, des technologies et des changements de culture dont la transformation doit se transformer aujourd\u2019hui et \u00e0 l\u2019avenir.\u00a0Il y trouve toute l\u2019information dont il a besoin pour comprendre \u00ab o\u00f9 les gens travaillent<strong>   <em><\/em> <\/strong> n\u2019est pas aussi important que <strong>   <em>leur fa\u00e7on<\/em> <\/strong> de travailler. \u00bb<\/p>\n<h2><span><br \/>\n  <strong>Travaillez et acc\u00e9l\u00e9rant les initiatives de travail<\/strong><br \/>\n<\/span><\/h2>\n<p>L\u2019\u00e9quipe de direction de l\u2019\u00e9quipe de direction de l\u2019\u00e9quipe de direction de a ferm\u00e9 la journ\u00e9e par Lorr lcd, Partieda\u00efk, Timer la soci\u00e9t\u00e9 et Sandeep Me Cisco Webex phras.\u00a0 Ils ont fourni les meilleures pratiques et des outils pour se connecter, collaborer et travailler pendant cette nouvelle r\u00e9alit\u00e9.\u00a0Ils ont soulign\u00e9 que le travail \u00e0 distance ne se limite pas aux r\u00e9unions en ligne, mais la collaboration, les id\u00e9es d\u2019\u00e9quipes et la connexion s\u00e9curis\u00e9e, la continuit\u00e9 de l\u2019activit\u00e9 des clients et m\u00eame la gestion du moral et de la camaraderie se font de m\u00eame.<\/p>\n<p>N\u2019oubliez pas de nous accorder demain pour notre deuxi\u00e8me jour de cette s\u00e9rie Future of Work pr\u00e9sentant Aruna Ravichandran, CMO de Webex, qui va aller plus en d\u00e9tail dans les tendances de #RemoteWork et Model Johnston, SVP &#8211; Personnes &#038;communities, Cisco, qui innove sa culture pour s\u2019adapter \u00e0 ce nouveau normal. Regardez <a href=\"https:\/\/futureofwork.webex.com\/virtual-summit\">l\u2019affichage \u00e0<\/a> la demande recap pour plus d\u2019informations.<\/p>\n<blockquote><p><strong>Pour plus d\u2019informations, voir\u00a0:<\/strong>\u202f<u><br \/>\n  <a href=\"https:\/\/virtualsummit.webex.com\/\">https:\/\/virtualsummit.webex.com\/ afficher<\/a> <\/u> <strong>\u00e0 la demande<\/strong>:\u202f<u><br \/>\n  <a href=\"https:\/\/futureofwork.webex.com\/virtual-summit\">https:\/\/futureofwork.webex.com\/virtual-summit<\/a><br \/>\n<\/u>\u202f<u><\/u><\/p><\/blockquote>\n<hr \/>\n<p><strong>En savoir plus sur les marathons en direct s\u00e9rie \u2014 #RemoteWork l\u2019avenir<\/strong>  <a href=\"https:\/\/blogs.cisco.com\/collaboration\/marathon-live-series-remotework-the-future-of-work-is-now\">du travail se trouve \u00e0 pr\u00e9sent dans les<\/a>  <a href=\"https:\/\/blogs.cisco.com\/collaboration\/workplace-experiences-how-remote-work-is-transforming-the-workplace\">exp\u00e9riences en lieu de travail : Comment le travail \u00e0 distance transforme Workplace<\/a>  <a href=\"https:\/\/blogs.cisco.com\/collaboration\/cisco-samsung-powering-workplace-transformation-by-doubling-down-on-co-creation-and-huddle-spaces\">Cisco + Samsung : Alimenter la transformation du lieu de travail en bas-bas sur des espaces en ext\u00e9rieur et des id\u00e9es<\/a><\/p>\n<p>\u00a0    \t<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour vous #RemoteWork l\u2019avenir du travail, nous avons rassembl\u00e9 une s\u00e9rie de sessions d\u2019une heure avec des experts, clients et l\u2019\u00e9quipe de direction Webex du 11 au 15 mai 2020, d\u2019une heure.<\/p>\n","protected":false},"author":3805,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[5253],"tags":[2393,501],"class_list":["post-384650","post","type-post","status-publish","format-standard","hentry","category-collaboration-fr","tag-travail-hybride","tag-workplace-transformation"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Future de la s\u00e9rie de marathons travail \u2013 Aper\u00e7us du jour &amp; Tendances sur l\u2019avenir du travail | Webex Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.webex.com\/collaboration\/hybrid-work\/future-of-work-marathon-series-day-1-insights-trends-on-the-future-of-work\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Future de la s\u00e9rie de marathons travail \u2013 Aper\u00e7us du jour &amp; Tendances sur l\u2019avenir du travail | Webex Blog\" \/>\n<meta property=\"og:description\" content=\"Pour vous #RemoteWork l\u2019avenir du travail, nous avons rassembl\u00e9 une s\u00e9rie de sessions d\u2019une heure avec des experts, clients et l\u2019\u00e9quipe de direction Webex du 11 au 15 mai 2020, d\u2019une heure.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.webex.com\/collaboration\/hybrid-work\/future-of-work-marathon-series-day-1-insights-trends-on-the-future-of-work\/\" \/>\n<meta property=\"og:site_name\" content=\"Webex Blog\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-06T23:34:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-18T06:37:35+00:00\" \/>\n<meta name=\"author\" content=\"Scott Edwards\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Scott Edwards\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.webex.com\\\/collaboration\\\/hybrid-work\\\/future-of-work-marathon-series-day-1-insights-trends-on-the-future-of-work\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/collaboration\\\/hybrid-work\\\/future-of-work-marathon-series-day-1-insights-trends-on-the-future-of-work\\\/\"},\"author\":{\"name\":\"Scott Edwards\",\"@id\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/#\\\/schema\\\/person\\\/0325ede5f3b320f86526acd020e6f0ad\"},\"headline\":\"Future de la s\u00e9rie de marathons travail \u2013 Aper\u00e7us du jour &#038; ...\",\"datePublished\":\"2020-05-06T23:34:40+00:00\",\"dateModified\":\"2024-09-18T06:37:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/collaboration\\\/hybrid-work\\\/future-of-work-marathon-series-day-1-insights-trends-on-the-future-of-work\\\/\"},\"wordCount\":537,\"commentCount\":0,\"keywords\":[\"travail hybride\",\"Workplace Transformation\"],\"articleSection\":[\"Collaboration\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.webex.com\\\/collaboration\\\/hybrid-work\\\/future-of-work-marathon-series-day-1-insights-trends-on-the-future-of-work\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.webex.com\\\/collaboration\\\/hybrid-work\\\/future-of-work-marathon-series-day-1-insights-trends-on-the-future-of-work\\\/\",\"url\":\"https:\\\/\\\/blog.webex.com\\\/collaboration\\\/hybrid-work\\\/future-of-work-marathon-series-day-1-insights-trends-on-the-future-of-work\\\/\",\"name\":\"Future de la s\u00e9rie de marathons travail \u2013 Aper\u00e7us du jour & Tendances sur l\u2019avenir du travail | Webex Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/#website\"},\"datePublished\":\"2020-05-06T23:34:40+00:00\",\"dateModified\":\"2024-09-18T06:37:35+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/#\\\/schema\\\/person\\\/0325ede5f3b320f86526acd020e6f0ad\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/collaboration\\\/hybrid-work\\\/future-of-work-marathon-series-day-1-insights-trends-on-the-future-of-work\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.webex.com\\\/collaboration\\\/hybrid-work\\\/future-of-work-marathon-series-day-1-insights-trends-on-the-future-of-work\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.webex.com\\\/collaboration\\\/hybrid-work\\\/future-of-work-marathon-series-day-1-insights-trends-on-the-future-of-work\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.webex.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Future de la s\u00e9rie de marathons travail \u2013 Aper\u00e7us du jour &#038; ...\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/\",\"name\":\"Webex Blog\",\"description\":\"Webex by Cisco powers collaboration through industry-leading video conferencing, cloud calling and contact center solutions\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/#\\\/schema\\\/person\\\/0325ede5f3b320f86526acd020e6f0ad\",\"name\":\"Scott Edwards\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d0153a3b2a7d850fb12e0fd306a717949f370f3411e5b9011349438e789dfa37?s=96&d=wp_user_avatar&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d0153a3b2a7d850fb12e0fd306a717949f370f3411e5b9011349438e789dfa37?s=96&d=wp_user_avatar&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d0153a3b2a7d850fb12e0fd306a717949f370f3411e5b9011349438e789dfa37?s=96&d=wp_user_avatar&r=g\",\"caption\":\"Scott Edwards\"},\"description\":\"Scott Edwards is the Sr. Director of Product Marketing within the Cisco Webex marketing team, specifically overseeing marketing activities for Webex Meetings, Teams, and Devices. Scott is an expert marketer with enterprise IT experience in both hardware and software product lines. His experience ranges from Andreessen Horowitz and Sequoia Capital-backed startups to large enterprise teams like HPE, Juniper Networks, and CA Technologies. He has led product marketing and business development around continuous delivery, testing, application performance management and DevOps offerings. He\u2019s also led open source, cloud, SDN and community marketing efforts. Scott received his MBA from Brigham Young University and currently resides just outside of Park City, Utah (even though he hasn\u2019t skied in years). In his spare time, Scott acts as a jungle gym for his 5 kids ages 16-6 and 2 small dogs.\",\"url\":\"https:\\\/\\\/blog.webex.com\\\/fr\\\/contributors\\\/scottedwards\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Future de la s\u00e9rie de marathons travail \u2013 Aper\u00e7us du jour & Tendances sur l\u2019avenir du travail | Webex Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.webex.com\/collaboration\/hybrid-work\/future-of-work-marathon-series-day-1-insights-trends-on-the-future-of-work\/","og_locale":"fr_FR","og_type":"article","og_title":"Future de la s\u00e9rie de marathons travail \u2013 Aper\u00e7us du jour & Tendances sur l\u2019avenir du travail | Webex Blog","og_description":"Pour vous #RemoteWork l\u2019avenir du travail, nous avons rassembl\u00e9 une s\u00e9rie de sessions d\u2019une heure avec des experts, clients et l\u2019\u00e9quipe de direction Webex du 11 au 15 mai 2020, d\u2019une heure.","og_url":"https:\/\/blog.webex.com\/collaboration\/hybrid-work\/future-of-work-marathon-series-day-1-insights-trends-on-the-future-of-work\/","og_site_name":"Webex Blog","article_published_time":"2020-05-06T23:34:40+00:00","article_modified_time":"2024-09-18T06:37:35+00:00","author":"Scott Edwards","twitter_misc":{"\u00c9crit par":"Scott Edwards","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.webex.com\/collaboration\/hybrid-work\/future-of-work-marathon-series-day-1-insights-trends-on-the-future-of-work\/#article","isPartOf":{"@id":"https:\/\/blog.webex.com\/collaboration\/hybrid-work\/future-of-work-marathon-series-day-1-insights-trends-on-the-future-of-work\/"},"author":{"name":"Scott Edwards","@id":"https:\/\/blog.webex.com\/es\/#\/schema\/person\/0325ede5f3b320f86526acd020e6f0ad"},"headline":"Future de la s\u00e9rie de marathons travail \u2013 Aper\u00e7us du jour &#038; ...","datePublished":"2020-05-06T23:34:40+00:00","dateModified":"2024-09-18T06:37:35+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.webex.com\/collaboration\/hybrid-work\/future-of-work-marathon-series-day-1-insights-trends-on-the-future-of-work\/"},"wordCount":537,"commentCount":0,"keywords":["travail hybride","Workplace Transformation"],"articleSection":["Collaboration"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.webex.com\/collaboration\/hybrid-work\/future-of-work-marathon-series-day-1-insights-trends-on-the-future-of-work\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.webex.com\/collaboration\/hybrid-work\/future-of-work-marathon-series-day-1-insights-trends-on-the-future-of-work\/","url":"https:\/\/blog.webex.com\/collaboration\/hybrid-work\/future-of-work-marathon-series-day-1-insights-trends-on-the-future-of-work\/","name":"Future de la s\u00e9rie de marathons travail \u2013 Aper\u00e7us du jour & Tendances sur l\u2019avenir du travail | Webex Blog","isPartOf":{"@id":"https:\/\/blog.webex.com\/es\/#website"},"datePublished":"2020-05-06T23:34:40+00:00","dateModified":"2024-09-18T06:37:35+00:00","author":{"@id":"https:\/\/blog.webex.com\/es\/#\/schema\/person\/0325ede5f3b320f86526acd020e6f0ad"},"breadcrumb":{"@id":"https:\/\/blog.webex.com\/collaboration\/hybrid-work\/future-of-work-marathon-series-day-1-insights-trends-on-the-future-of-work\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.webex.com\/collaboration\/hybrid-work\/future-of-work-marathon-series-day-1-insights-trends-on-the-future-of-work\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/blog.webex.com\/collaboration\/hybrid-work\/future-of-work-marathon-series-day-1-insights-trends-on-the-future-of-work\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.webex.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Future de la s\u00e9rie de marathons travail \u2013 Aper\u00e7us du jour &#038; ..."}]},{"@type":"WebSite","@id":"https:\/\/blog.webex.com\/es\/#website","url":"https:\/\/blog.webex.com\/es\/","name":"Webex Blog","description":"Webex by Cisco powers collaboration through industry-leading video conferencing, cloud calling and contact center solutions","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.webex.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/blog.webex.com\/es\/#\/schema\/person\/0325ede5f3b320f86526acd020e6f0ad","name":"Scott Edwards","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/d0153a3b2a7d850fb12e0fd306a717949f370f3411e5b9011349438e789dfa37?s=96&d=wp_user_avatar&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d0153a3b2a7d850fb12e0fd306a717949f370f3411e5b9011349438e789dfa37?s=96&d=wp_user_avatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d0153a3b2a7d850fb12e0fd306a717949f370f3411e5b9011349438e789dfa37?s=96&d=wp_user_avatar&r=g","caption":"Scott Edwards"},"description":"Scott Edwards is the Sr. Director of Product Marketing within the Cisco Webex marketing team, specifically overseeing marketing activities for Webex Meetings, Teams, and Devices. Scott is an expert marketer with enterprise IT experience in both hardware and software product lines. His experience ranges from Andreessen Horowitz and Sequoia Capital-backed startups to large enterprise teams like HPE, Juniper Networks, and CA Technologies. He has led product marketing and business development around continuous delivery, testing, application performance management and DevOps offerings. He\u2019s also led open source, cloud, SDN and community marketing efforts. Scott received his MBA from Brigham Young University and currently resides just outside of Park City, Utah (even though he hasn\u2019t skied in years). In his spare time, Scott acts as a jungle gym for his 5 kids ages 16-6 and 2 small dogs.","url":"https:\/\/blog.webex.com\/fr\/contributors\/scottedwards\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.webex.com\/fr\/wp-json\/wp\/v2\/posts\/384650","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.webex.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.webex.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.webex.com\/fr\/wp-json\/wp\/v2\/users\/3805"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.webex.com\/fr\/wp-json\/wp\/v2\/comments?post=384650"}],"version-history":[{"count":0,"href":"https:\/\/blog.webex.com\/fr\/wp-json\/wp\/v2\/posts\/384650\/revisions"}],"wp:attachment":[{"href":"https:\/\/blog.webex.com\/fr\/wp-json\/wp\/v2\/media?parent=384650"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.webex.com\/fr\/wp-json\/wp\/v2\/categories?post=384650"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.webex.com\/fr\/wp-json\/wp\/v2\/tags?post=384650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}