{"id":382842,"date":"2022-02-02T09:00:04","date_gmt":"2022-02-02T17:00:04","guid":{"rendered":"https:\/\/blog.webex.com\/uncategorized-it\/come-sviluppare-una-strategia-di-transizione-vincente-alle-chiamate-cloud-aziendali-parte-2-trasformazione-aziendale\/"},"modified":"2021-02-03T09:00:04","modified_gmt":"2021-02-03T17:00:04","slug":"come-sviluppare-una-strategia-di-transizione-vincente-alle-chiamate-cloud-aziendali-parte-2-trasformazione-aziendale","status":"publish","type":"post","link":"https:\/\/blog.webex.com\/it\/collaborazione\/come-sviluppare-una-strategia-di-transizione-vincente-alle-chiamate-cloud-aziendali-parte-2-trasformazione-aziendale\/","title":{"rendered":"Come sviluppare una strategia di transizione vincente alle ..."},"content":{"rendered":"<p><em>La serie di blog <a href=\"https:\/\/blogs.cisco.com\/tag\/how-to-develop-a-winning-transition-strategy-for-enterprise-cloud-calling-blog-series\">Come sviluppare una strategia di transizione vincente per le chiamate cloud aziendali<\/a> illustra in quattro parti come portare la tua azienda verso un futuro di chiamate e collaborazioni cloud che offra tutti i vantaggi prevedibili di un servizio cloud di qualit\u00e0.<\/em><\/p>\n<h2><span><br \/>\n  <strong>Comprendere il valore del cloud<\/strong><br \/>\n<\/span><\/h2>\n<p>Quand&#8217;ero piccolo, mi piaceva andare alla fattoria dei miei nonni. Mia nonna aveva delle bellissime piante di lamponi.  Ci dava la zappa e ci mandava a togliere le erbacce dal campo: in cambio, alla fine di ogni filare, potevamo raccogliere e mangiare tutti i lamponi che volevamo. Di questa esperienza \u00e8 rimasto un detto di famiglia: &#8220;Zappa fino alla fine del filare&#8221;, che per me ha assunto un nuovo significato nel corso degli anni: per ottenere il massimo beneficio, devi portare a termine quello che hai iniziato.<\/p>\n<p>Comprendere il valore del cloud per la trasformazione della forza lavoro \u00e8 un po&#8217; come togliere le erbacce da quel vecchio campo di lamponi. La migrazione dei carichi di lavoro UC al cloud \u00e8 il primo passo di un&#8217;operazione di trasformazione della forza lavoro. La connessione di nuovi servizi e applicazioni cloud apporta valore all&#8217;azienda semplificando i flussi di lavoro collaborativi essenziali.<\/p>\n<p>Questa \u00e8 la seconda parte di una serie di blog sulla creazione e l&#8217;esecuzione di una strategia di successo per la transizione delle comunicazioni unificate (UC) e della collaborazione aziendali al cloud. Qui mi concentrer\u00f2 sulla trasformazione dell&#8217;ambiente di lavoro e sugli aspetti di integrazione della fornitura di soluzioni cloud. Continua a leggere per scoprire un importante annuncio di prodotto.<\/p>\n<h2><span><br \/>\n  <strong>Connettivit\u00e0 trasformativa<\/strong>\u00a0<\/span><\/h2>\n<p>Quando si portano i servizi UC e di collaborazione nel cloud, si espandano e al tempo stesso si semplificano le capacit\u00e0 di aggiungere funzionalit\u00e0 di collaborazione trasformativa nei processi, cos\u00ec da accelerare i flussi di lavoro sensibili al fattore tempo che aumentano la redditivit\u00e0 e ti differenziano dalla concorrenza.<\/p>\n<p>Facciamo un semplice esempio. Prendiamo uno scenario che si ripete ogni giorno tra i dipendenti che collaborano a un documento. \u00c8 possibile che utilizzino un repository di archiviazione condiviso, come Box o Microsoft SharePoint, per condividere, commentare e modificare i documenti. \u00c8 inevitabile che alcune modifiche necessitano di essere discusse.\u00a0\u00a0Quando si utilizza Cisco Webex con una soluzione di chiamate cloud Cisco, \u00e8 possibile aggiungere documenti a un ambiente o connettere l&#8217;ambiente al file archiviato in una posizione di archiviazione condivisa, inserendo tutti i partecipanti all&#8217;interno di quell&#8217;ambiente. Ogni volta che occorre analizzare una modifica o un commento nel documento originale, i partecipanti o alcuni soggetti specifici vengono informati in Webex. Il documento pu\u00f2 essere aperto direttamente dalla notifica e, soprattutto, le parti interessate possono connettersi in diretta tramite video, proprio l\u00ec nell&#8217;ambiente Webex, e risolvere insieme eventuali problemi.<\/p>\n<h2><span><br \/>\n  <strong>Integrazione di applicazioni e processi<\/strong><br \/>\n<\/span><\/h2>\n<p>Quanto ho appena descritto sembra semplice, ed \u00e8 cos\u00ec che dovrebbe essere la collaborazione. Ma trasferisci questo stesso processo all&#8217;interno della tua azienda oggi: potresti avere un documento condiviso in un&#8217;applicazione di condivisione file che avvisa i partecipanti via e-mail e richiede l&#8217;uso di un&#8217;applicazione UC separata per chiamate, messaggi e riunioni. Ci\u00f2 costringe i dipendenti a un ciclo infinito di cambio di contesto, tra tre o pi\u00f9 applicazioni, mentre collaborano attivamente a un documento.<\/p>\n<p>La ricerca mostra che il cambio di contesto tra pi\u00f9 attivit\u00e0 pu\u00f2 ridurre la produttivit\u00e0 fino al 40%, a seconda della complessit\u00e0 delle attivit\u00e0, del numero di attivit\u00e0 e della frequenza di passaggio da una all&#8217;altra. Moltiplicando questo calo di produttivit\u00e0 per tutta la tua forza lavoro, i vantaggi dell&#8217;integrazione delle applicazioni cloud sono evidenti.<\/p>\n<h2><span><br \/>\n  <strong>Accesso continuo a servizi innovativi<\/strong><br \/>\n<\/span><\/h2>\n<p>Se sei un cliente di Cisco Unified Communications Manager in locale e desideri passare al cloud con <a href=\"https:\/\/www.cisco.com\/c\/en\/us\/solutions\/collaboration\/unified-communications-manager-cloud\/index.html\">UCM Cloud<\/a>, il tuo ambiente UCM Cloud sar\u00e0 integrato nella suite di collaborazione Webex e <a href=\"https:\/\/www.cisco.com\/c\/en\/us\/products\/conferencing\/webex-control-hub\/index.html\">Webex Control Hub<\/a>, cos\u00ec avrai accesso a tutte le ultime innovazioni di Cisco. <strong>Avviso di annuncio!<\/strong> Questo mese stiamo introducendo integrazioni cloud pi\u00f9 profonde tra le chiamate di Cisco e i cloud Webex che ridurranno drasticamente i costi PSTN delle riunioni dei clienti, grazie al routing delle chiamate in rete consentito dall&#8217;architettura cloud di Cisco.<\/p>\n<p>Oltre alle integrazioni cloud Cisco, Cisco dispone di una solida community di sviluppatori che offre integrazioni in centinaia di applicazioni aziendali, per creare servizi innovativi dal cloud. Alcune delle principali integrazioni cloud dei fornitori supportate sono mostrate nella Figura 1.<\/p>\n<div id=\"attachment_353538\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-353538\" class=\"wp-image-353538 size-medium_large\" src=\"https:\/\/storage.googleapis.com\/blogs-images\/ciscoblogs\/1\/2021\/02\/Collaboration-enabled-Workflows-1-768x390.png\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" srcset=\"https:\/\/storage.googleapis.com\/blogs-images\/ciscoblogs\/1\/2021\/02\/Collaboration-enabled-Workflows-1-300x152.png 300w, https:\/\/storage.googleapis.com\/blogs-images\/ciscoblogs\/1\/2021\/02\/Collaboration-enabled-Workflows-1-768x390.png 768w\" alt=\"Flussi di lavoro abilitati per la collaborazione\" width=\"640\" height=\"325\" \/><p id=\"caption-attachment-353538\" class=\"wp-caption-text\"><br \/>\n<\/a> Figura 1: Flussi di lavoro abilitati per la collaborazione<\/p><\/div>\n<p>Se utilizzi gi\u00e0 Cisco Unified Communications Manager con una qualsiasi delle applicazioni dei partner sviluppatori autorizzati Cisco, con <a href=\"https:\/\/developer.cisco.com\/ecosystem\/solutions\/#technology=Collaboration\">Cisco Ecosystem Exchange<\/a> ti garantiamo il mantenimento delle integrazioni aziendali esistenti nella fase di transizione di utenti e siti al cloud con <a href=\"https:\/\/www.cisco.com\/c\/en\/us\/solutions\/collaboration\/unified-communications-manager-cloud\/index.html\">UCM Cloud<\/a> Dopodich\u00e9 aggiungi nuove integrazioni cloud per apportare valore aggiunto alla tua azienda.<\/p>\n<div id=\"attachment_353535\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-353535\" class=\"size-medium_large wp-image-353535\" src=\"https:\/\/storage.googleapis.com\/blogs-images\/ciscoblogs\/1\/2021\/02\/UCM-Cloud-Application-Integrations-768x435.png\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" srcset=\"https:\/\/storage.googleapis.com\/blogs-images\/ciscoblogs\/1\/2021\/02\/UCM-Cloud-Application-Integrations-300x170.png 300w, https:\/\/storage.googleapis.com\/blogs-images\/ciscoblogs\/1\/2021\/02\/UCM-Cloud-Application-Integrations-768x435.png 768w\" alt=\"Integrazioni di applicazioni cloud UCM\" width=\"640\" height=\"363\" \/><p id=\"caption-attachment-353535\" class=\"wp-caption-text\"><br \/>\n<\/a> Figura 2: Soluzioni per i partner Cisco Ecosystem Exchange per UCM e UCM Cloud<\/p><\/div>\n<h2><span><br \/>\n  <strong>Flussi di lavoro che potenziano il coinvolgimento della forza lavoro<\/strong><br \/>\n<\/span><\/h2>\n<p>Ci\u00f2 che conta \u00e8 che, man mano che ti sposti su una soluzione UC Cisco cloud, la tua forza lavoro sar\u00e0 connessa sempre meglio e operer\u00e0 all&#8217;interno di flussi di lavoro ottimizzati per l&#8217;accesso a persone, contenuti e informazioni, cos\u00ec da mantenere tutti coinvolti, con un vantaggio di produttivit\u00e0 per l&#8217;azienda.<\/p>\n<p>Quindi, nella prima fase di pianificazione, identifica i miglioramenti del flusso di lavoro da perseguire e individua nuove integrazioni cloud che aumenteranno la produttivit\u00e0.\u00a0Definisci i requisiti e i parametri che utilizzerai per misurare il successo. Confrontati con i leader aziendali per assicurarti che comprendano il valore in ballo e siano pronti a scendere in prima linea per questa operazione di trasformazione del cloud. Assicurati di comunicare spesso durante l&#8217;intero processo di pianificazione e implementazione, cos\u00ec da garantire il supporto ed evitare sorprese.\u00a0Come diceva mia nonna, &#8220;zappa fino alla fine del filare&#8221; con le integrazioni cloud e non limitarti alla semplice migrazione del carico di lavoro delle chiamate al cloud. Solo cos\u00ec raccoglierai i \u201cfrutti\u201d e trasformerai davvero la tua azienda.<\/p>\n<p>Ecco un <a href=\"https:\/\/youtu.be\/IxCFS3KUies\"> video informativo<\/a> che ti aiuter\u00e0 nella prima fase di pianificazione della transizione al cloud. La prossima settimana analizzeremo l&#8217;equazione TCO per l&#8217;UC cloud:<\/p>\n<p><iframe loading=\"lazy\" title=\"Enterprise Cloud Migration Success Video Series: Part 2\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/UubarXlA4EU?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p><strong>Ulteriori informazioni<\/strong><\/p>\n<p><a href=\"https:\/\/blog.webex.com\/it\/videoconferenze\/novita-in-webex-luglio-2021\/\">Novit\u00e0 di Webex: Febbraio 2021<\/a><\/p>\n<p><a href=\"https:\/\/blogs.cisco.com\/collaboration\/how-to-develop-a-winning-transition-strategy-for-enterprise-cloud-calling-step-1-business-agility\">Come sviluppare una strategia di transizione vincente alle chiamate cloud aziendali: Fase 1, Agilit\u00e0 aziendale<\/a><\/p>\n<p><a href=\"https:\/\/blogs.cisco.com\/tag\/how-to-develop-a-winning-transition-strategy-for-enterprise-cloud-calling-blog-series\">Leggi tutti i blog della serie<\/a><\/p>\n<p><strong>Link importanti<\/strong><\/p>\n<p>Abbiamo appena terminato un fantastico evento virtuale WebexOne con annunci e presentazioni di prodotti che hanno evidenziato la forza delle integrazioni cloud. Guarda questi link:<\/p>\n<p><a href=\"https:\/\/events.rainfocus.com\/widget\/cisco\/webexone20\/exhibitorpartner?\">Il partner per l&#8217;ecosistema WebexOne sponsorizza brevi video e panoramiche di prodotto<\/a><\/p>\n<p><a href=\"https:\/\/www.apa.org\/research\/action\/multitask\">Studio sugli impatti del cambio di contesto<\/a> dell&#8217;American Psychological Association.<\/p>\n<p><a href=\"https:\/\/www.cisco.com\/c\/en\/us\/products\/conferencing\/webex-control-hub\/index.html\">Home page di Webex Control Hub<\/a><\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Questa \u00e8 la seconda parte di una serie di blog sulla creazione e l&#8217;esecuzione di una strategia di successo per la transizione delle comunicazioni unificate (UC) e della collaborazione aziendali al cloud. <\/p>\n","protected":false},"author":5536,"featured_media":384987,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[15587,5273],"tags":[6640,456,5850],"class_list":["post-382842","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cloud-calling","category-collaborazione","tag-cisco-unified-communications-manager-it","tag-webex-calling","tag-webex-calling-it"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Come sviluppare una strategia di transizione vincente alle chiamate cloud aziendali: Parte 2, Trasformazione aziendale | Webex Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.webex.com\/collaboration\/how-to-develop-a-winning-transition-strategy-to-enterprise-cloud-calling-part-2-business-transformation\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Come sviluppare una strategia di transizione vincente alle chiamate cloud aziendali: Parte 2, Trasformazione aziendale | Webex Blog\" \/>\n<meta property=\"og:description\" content=\"Questa \u00e8 la seconda parte di una serie di blog sulla creazione e l&#039;esecuzione di una strategia di successo per la transizione delle comunicazioni unificate (UC) e della collaborazione aziendali al cloud.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.webex.com\/collaboration\/how-to-develop-a-winning-transition-strategy-to-enterprise-cloud-calling-part-2-business-transformation\/\" \/>\n<meta property=\"og:site_name\" content=\"Webex Blog\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-02T17:00:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.webex.com\/wp-content\/uploads\/2021\/02\/02_11_2021_SHOT_11_A_0310_ccexpress-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"975\" \/>\n\t<meta property=\"og:image:height\" content=\"554\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Trent Thomas\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Trent Thomas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.webex.com\\\/collaboration\\\/how-to-develop-a-winning-transition-strategy-to-enterprise-cloud-calling-part-2-business-transformation\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/collaboration\\\/how-to-develop-a-winning-transition-strategy-to-enterprise-cloud-calling-part-2-business-transformation\\\/\"},\"author\":{\"name\":\"Trent Thomas\",\"@id\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/#\\\/schema\\\/person\\\/378213580bd04504ed95b5dc3ca9cdee\"},\"headline\":\"Come sviluppare una strategia di transizione vincente alle ...\",\"datePublished\":\"2022-02-02T17:00:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/collaboration\\\/how-to-develop-a-winning-transition-strategy-to-enterprise-cloud-calling-part-2-business-transformation\\\/\"},\"wordCount\":1102,\"image\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/collaboration\\\/how-to-develop-a-winning-transition-strategy-to-enterprise-cloud-calling-part-2-business-transformation\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.webex.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/02_11_2021_SHOT_11_A_0310_ccexpress-1.jpeg\",\"keywords\":[\"Cisco Unified Communications Manager\",\"Webex Calling\",\"Webex calling\"],\"articleSection\":[\"Cloud Calling\",\"Collaborazione\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.webex.com\\\/collaboration\\\/how-to-develop-a-winning-transition-strategy-to-enterprise-cloud-calling-part-2-business-transformation\\\/\",\"url\":\"https:\\\/\\\/blog.webex.com\\\/collaboration\\\/how-to-develop-a-winning-transition-strategy-to-enterprise-cloud-calling-part-2-business-transformation\\\/\",\"name\":\"Come sviluppare una strategia di transizione vincente alle chiamate cloud aziendali: Parte 2, Trasformazione aziendale | Webex Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/collaboration\\\/how-to-develop-a-winning-transition-strategy-to-enterprise-cloud-calling-part-2-business-transformation\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/collaboration\\\/how-to-develop-a-winning-transition-strategy-to-enterprise-cloud-calling-part-2-business-transformation\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.webex.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/02_11_2021_SHOT_11_A_0310_ccexpress-1.jpeg\",\"datePublished\":\"2022-02-02T17:00:04+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/#\\\/schema\\\/person\\\/378213580bd04504ed95b5dc3ca9cdee\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/collaboration\\\/how-to-develop-a-winning-transition-strategy-to-enterprise-cloud-calling-part-2-business-transformation\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.webex.com\\\/collaboration\\\/how-to-develop-a-winning-transition-strategy-to-enterprise-cloud-calling-part-2-business-transformation\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/blog.webex.com\\\/collaboration\\\/how-to-develop-a-winning-transition-strategy-to-enterprise-cloud-calling-part-2-business-transformation\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.webex.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/02_11_2021_SHOT_11_A_0310_ccexpress-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/blog.webex.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/02_11_2021_SHOT_11_A_0310_ccexpress-1.jpeg\",\"width\":975,\"height\":554,\"caption\":\"medical worker using Webex Meetings to call a patient\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.webex.com\\\/collaboration\\\/how-to-develop-a-winning-transition-strategy-to-enterprise-cloud-calling-part-2-business-transformation\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.webex.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Come sviluppare una strategia di transizione vincente alle ...\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/\",\"name\":\"Webex Blog\",\"description\":\"Webex by Cisco powers collaboration through industry-leading video conferencing, cloud calling and contact center solutions\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/#\\\/schema\\\/person\\\/378213580bd04504ed95b5dc3ca9cdee\",\"name\":\"Trent Thomas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c555d2a6d8e5ba84763291ec248ecc2e9bd1d24882e9bc2659c833873913d8ea?s=96&d=wp_user_avatar&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c555d2a6d8e5ba84763291ec248ecc2e9bd1d24882e9bc2659c833873913d8ea?s=96&d=wp_user_avatar&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c555d2a6d8e5ba84763291ec248ecc2e9bd1d24882e9bc2659c833873913d8ea?s=96&d=wp_user_avatar&r=g\",\"caption\":\"Trent Thomas\"},\"description\":\"Trent Thomas is a Senior Product Manager at Cisco who leads a Cloud calling product management team. He is responsible for setting market direction for the Cisco\u2019s Unified Communications Manager Cloud product line and is focus on helping Cisco\u2019s on-premises calling customers make the transition to the cloud. Outside of work, Trent is an adrenaline junkie and attempts to stay young by keeping up with his kids on the slopes, the water, the trail and the rocks.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/gtrentthomas\"],\"url\":\"https:\\\/\\\/blog.webex.com\\\/it\\\/contributors\\\/trentthomas\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Come sviluppare una strategia di transizione vincente alle chiamate cloud aziendali: Parte 2, Trasformazione aziendale | Webex Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.webex.com\/collaboration\/how-to-develop-a-winning-transition-strategy-to-enterprise-cloud-calling-part-2-business-transformation\/","og_locale":"it_IT","og_type":"article","og_title":"Come sviluppare una strategia di transizione vincente alle chiamate cloud aziendali: Parte 2, Trasformazione aziendale | Webex Blog","og_description":"Questa \u00e8 la seconda parte di una serie di blog sulla creazione e l'esecuzione di una strategia di successo per la transizione delle comunicazioni unificate (UC) e della collaborazione aziendali al cloud.","og_url":"https:\/\/blog.webex.com\/collaboration\/how-to-develop-a-winning-transition-strategy-to-enterprise-cloud-calling-part-2-business-transformation\/","og_site_name":"Webex Blog","article_published_time":"2022-02-02T17:00:04+00:00","og_image":[{"width":975,"height":554,"url":"https:\/\/blog.webex.com\/wp-content\/uploads\/2021\/02\/02_11_2021_SHOT_11_A_0310_ccexpress-1.jpeg","type":"image\/jpeg"}],"author":"Trent Thomas","twitter_misc":{"Scritto da":"Trent Thomas","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.webex.com\/collaboration\/how-to-develop-a-winning-transition-strategy-to-enterprise-cloud-calling-part-2-business-transformation\/#article","isPartOf":{"@id":"https:\/\/blog.webex.com\/collaboration\/how-to-develop-a-winning-transition-strategy-to-enterprise-cloud-calling-part-2-business-transformation\/"},"author":{"name":"Trent Thomas","@id":"https:\/\/blog.webex.com\/es\/#\/schema\/person\/378213580bd04504ed95b5dc3ca9cdee"},"headline":"Come sviluppare una strategia di transizione vincente alle ...","datePublished":"2022-02-02T17:00:04+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.webex.com\/collaboration\/how-to-develop-a-winning-transition-strategy-to-enterprise-cloud-calling-part-2-business-transformation\/"},"wordCount":1102,"image":{"@id":"https:\/\/blog.webex.com\/collaboration\/how-to-develop-a-winning-transition-strategy-to-enterprise-cloud-calling-part-2-business-transformation\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.webex.com\/wp-content\/uploads\/2021\/02\/02_11_2021_SHOT_11_A_0310_ccexpress-1.jpeg","keywords":["Cisco Unified Communications Manager","Webex Calling","Webex calling"],"articleSection":["Cloud Calling","Collaborazione"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/blog.webex.com\/collaboration\/how-to-develop-a-winning-transition-strategy-to-enterprise-cloud-calling-part-2-business-transformation\/","url":"https:\/\/blog.webex.com\/collaboration\/how-to-develop-a-winning-transition-strategy-to-enterprise-cloud-calling-part-2-business-transformation\/","name":"Come sviluppare una strategia di transizione vincente alle chiamate cloud aziendali: Parte 2, Trasformazione aziendale | Webex Blog","isPartOf":{"@id":"https:\/\/blog.webex.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.webex.com\/collaboration\/how-to-develop-a-winning-transition-strategy-to-enterprise-cloud-calling-part-2-business-transformation\/#primaryimage"},"image":{"@id":"https:\/\/blog.webex.com\/collaboration\/how-to-develop-a-winning-transition-strategy-to-enterprise-cloud-calling-part-2-business-transformation\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.webex.com\/wp-content\/uploads\/2021\/02\/02_11_2021_SHOT_11_A_0310_ccexpress-1.jpeg","datePublished":"2022-02-02T17:00:04+00:00","author":{"@id":"https:\/\/blog.webex.com\/es\/#\/schema\/person\/378213580bd04504ed95b5dc3ca9cdee"},"breadcrumb":{"@id":"https:\/\/blog.webex.com\/collaboration\/how-to-develop-a-winning-transition-strategy-to-enterprise-cloud-calling-part-2-business-transformation\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.webex.com\/collaboration\/how-to-develop-a-winning-transition-strategy-to-enterprise-cloud-calling-part-2-business-transformation\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/blog.webex.com\/collaboration\/how-to-develop-a-winning-transition-strategy-to-enterprise-cloud-calling-part-2-business-transformation\/#primaryimage","url":"https:\/\/blog.webex.com\/wp-content\/uploads\/2021\/02\/02_11_2021_SHOT_11_A_0310_ccexpress-1.jpeg","contentUrl":"https:\/\/blog.webex.com\/wp-content\/uploads\/2021\/02\/02_11_2021_SHOT_11_A_0310_ccexpress-1.jpeg","width":975,"height":554,"caption":"medical worker using Webex Meetings to call a patient"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.webex.com\/collaboration\/how-to-develop-a-winning-transition-strategy-to-enterprise-cloud-calling-part-2-business-transformation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.webex.com\/it\/"},{"@type":"ListItem","position":2,"name":"Come sviluppare una strategia di transizione vincente alle ..."}]},{"@type":"WebSite","@id":"https:\/\/blog.webex.com\/es\/#website","url":"https:\/\/blog.webex.com\/es\/","name":"Webex Blog","description":"Webex by Cisco powers collaboration through industry-leading video conferencing, cloud calling and contact center solutions","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.webex.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/blog.webex.com\/es\/#\/schema\/person\/378213580bd04504ed95b5dc3ca9cdee","name":"Trent Thomas","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c555d2a6d8e5ba84763291ec248ecc2e9bd1d24882e9bc2659c833873913d8ea?s=96&d=wp_user_avatar&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c555d2a6d8e5ba84763291ec248ecc2e9bd1d24882e9bc2659c833873913d8ea?s=96&d=wp_user_avatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c555d2a6d8e5ba84763291ec248ecc2e9bd1d24882e9bc2659c833873913d8ea?s=96&d=wp_user_avatar&r=g","caption":"Trent Thomas"},"description":"Trent Thomas is a Senior Product Manager at Cisco who leads a Cloud calling product management team. He is responsible for setting market direction for the Cisco\u2019s Unified Communications Manager Cloud product line and is focus on helping Cisco\u2019s on-premises calling customers make the transition to the cloud. Outside of work, Trent is an adrenaline junkie and attempts to stay young by keeping up with his kids on the slopes, the water, the trail and the rocks.","sameAs":["https:\/\/www.linkedin.com\/in\/gtrentthomas"],"url":"https:\/\/blog.webex.com\/it\/contributors\/trentthomas\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.webex.com\/it\/wp-json\/wp\/v2\/posts\/382842","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.webex.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.webex.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.webex.com\/it\/wp-json\/wp\/v2\/users\/5536"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.webex.com\/it\/wp-json\/wp\/v2\/comments?post=382842"}],"version-history":[{"count":0,"href":"https:\/\/blog.webex.com\/it\/wp-json\/wp\/v2\/posts\/382842\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.webex.com\/it\/wp-json\/wp\/v2\/media\/384987"}],"wp:attachment":[{"href":"https:\/\/blog.webex.com\/it\/wp-json\/wp\/v2\/media?parent=382842"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.webex.com\/it\/wp-json\/wp\/v2\/categories?post=382842"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.webex.com\/it\/wp-json\/wp\/v2\/tags?post=382842"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}