{"id":392964,"date":"2022-03-29T08:14:04","date_gmt":"2022-03-29T15:14:04","guid":{"rendered":"https:\/\/blog.webex.com\/uncategorized-it\/tre-considerazioni-per-iniziare-il-percorso-di-messaggistica-digitale\/"},"modified":"2022-03-29T08:14:04","modified_gmt":"2022-03-29T15:14:04","slug":"tre-considerazioni-per-iniziare-il-percorso-di-messaggistica-digitale","status":"publish","type":"post","link":"https:\/\/blog.webex.com\/it\/customer-stories\/tre-considerazioni-per-iniziare-il-percorso-di-messaggistica-digitale\/","title":{"rendered":"Tre considerazioni per iniziare il percorso di messaggistica digitale"},"content":{"rendered":"<p>I clienti desiderano comunicare con le aziende attraverso i canali che usano ogni giorno. Utilizzano sempre pi\u00f9 la messaggistica e lo stesso deve fare la tua azienda per rimanere competitiva nel mondo dell&#8217;esperienza clienti (CX). Con la vasta e diversificata gamma di canali digitali disponibili oggi, le aziende sentono sempre pi\u00f9 l&#8217;esigenza di utilizzare i canali giusti e offrire un&#8217;esperienza completa e interattiva ai propri clienti.<\/p>\n<p>Con oltre un decennio di esperienza nell&#8217;ambito della messaggistica digitale, <a href=\"https:\/\/www.linkedin.com\/in\/ramy-riad\/\" target=\"_blank\" rel=\"noopener\">Ramy Riad<\/a>, Head of Future Digital Messaging, suggerisce tre considerazioni chiave per le aziende che stanno pensando a iniziare o migliorare l&#8217;uso di canali digitali per offrire percorsi end-to-end ai clienti.<\/p>\n<h2><strong>1. Scegli i canali che i tuoi clienti preferiscono<\/strong><\/h2>\n<p>I clienti vogliono parlare con le aziende con la stessa facilit\u00e0 e rapidit\u00e0 con cui parlano con amici e familiari. Il gran numero di canali ora disponibili pu\u00f2 essere abbastanza disorientante se la tua azienda \u00e8 all&#8217;inizio o sta considerando canali digitali alternativi. Per iniziare, \u00e8 fondamentale identificare i canali giusti in base alle preferenze dei tuoi clienti. Raccogliendo e valutando i dati dei clienti per identificare i canali che preferiscono e perch\u00e9 e comprendendo come le preferenze di canale variano tra regioni o diversi segmenti di clienti, otterrai le informazioni necessarie per scegliere il canale appropriato.<\/p>\n<p>Per raggiungere il successo, devi identificare i principali casi d&#8217;uso dei canali scelti dai clienti per interagire. Mentre gli <a href=\"https:\/\/live.imimobile.com\/l\/13622\/2022-03-07\/jh1xtp\" target=\"_blank\" rel=\"noopener\">SMS<\/a> possono essere ideali per richieste di autenticazione, canali digitali come <a href=\"https:\/\/live.imimobile.com\/l\/13622\/2022-03-07\/jh1xtr\" target=\"_blank\" rel=\"noopener\">WhatsApp<\/a>, <a href=\"https:\/\/live.imimobile.com\/l\/13622\/2022-03-07\/jh1xt7\" target=\"_blank\" rel=\"noopener\">Apple Messages for Business<\/a> e <a href=\"https:\/\/live.imimobile.com\/l\/13622\/2022-03-07\/jh1xt9\" target=\"_blank\" rel=\"noopener\">Google Business Messages<\/a> possono essere pi\u00f9 adatti al servizio clienti, in quanto consentono ai clienti di rispondere con i loro tempi. <a href=\"https:\/\/live.imimobile.com\/l\/13622\/2022-03-07\/jh1xtc\" target=\"_blank\" rel=\"noopener\">Rich Communication Services (RCS)<\/a> \u00e8 invece un canale di messaggistica che si presta bene alle notifiche proattive e alle comunicazioni correlate al marketing.<\/p>\n<p>Scegli i canali che soddisfano meglio i diversi requisiti della tua azienda. Inizia in piccolo e cresci in base alla partecipazione dei clienti e alle metriche pertinenti. \u00c8 importante consentire ai clienti di parlare con un agente in diretta, se lo desiderano, su questi canali. Il semplice passaggio da chatbot automatici a un agente in diretta come <a href=\"https:\/\/www.webex.com\/contact-center.html\" target=\"_blank\" rel=\"noopener\">Webex Contact Center<\/a>, mantenendo il contesto della conversazione, consente di offrire un&#8217;esperienza fluida e personalizzata al cliente.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-390101 aligncenter\" src=\"https:\/\/blog.webex.com\/wp-content\/uploads\/2022\/03\/mobile.jpg\" alt=\"\" width=\"904\" height=\"514\" \/><\/p>\n<p>\u00a0<\/p>\n<h2><strong>2. Valuta i vantaggi economici<\/strong><\/h2>\n<p>Come i canali di messaggistica digitale si evolvono, cos\u00ec fanno i modelli di prezzi che utilizzano. A differenza degli SMS, dove ciascun messaggio di 160 caratteri viene addebitato a una tariffa fissa, i canali digitali come WhatsApp usano un approccio diverso al modello di prezzi. Ad esempio, attualmente Google Business Messages non addebita una tariffa direttamente a un&#8217;azienda, ma se devi connetterti al canale dell&#8217;azienda tramite le relative societ\u00e0 partner, tale servizio verr\u00e0 addebitato. Nel caso di RCS, invece, paghi per un singolo messaggio come per gli SMS.<\/p>\n<p>Ci\u00f2 che rende i prezzi un argomento pi\u00f9 complesso \u00e8 che esistono molti fattori che li influenzano, come area geografica e uso. Ad esempio, il protocollo RCS \u00e8 gratuito nella maggior parte dei mercati al di fuori del Regno Unito, al momento. WhatsApp \u00e8 passato a un modello di prezzi conversazionale, dove una conversazione pu\u00f2 rimanere aperta per 24 ore. Le aziende possono avviare conversazioni entro un periodo di 24 ore se i relativi clienti hanno acconsentito e verr\u00e0 loro addebitato un costo per conversazione.<\/p>\n<p>Anche con i diversi modelli di prezzi, i canali digitali possono aiutare le aziende a offrire esperienze clienti pi\u00f9 complete a prezzi ridotti. Scegliendo un canale asincrono come WhatsApp, gli agenti possono avere pi\u00f9 conversazioni contemporaneamente anzich\u00e9 dover parlare con un cliente alla volta tramite una chiamata vocale o risolvere il problema con pi\u00f9 SMS. Ad esempio, una chiamata al servizio clienti che dura 5 minuti potrebbe costare circa 25 dollari in termini di tempo dell&#8217;agente. Per avere la stessa conversazione tramite SMS potrebbero essere necessari 25 messaggi scambiati tra cliente e azienda. Al costo di 2 centesimi a messaggio, il potenziale costo totale potrebbe essere 50 centesimi. Un vantaggio aggiunto \u00e8 il maggiore coinvolgimento che aiuta le aziende a migliorare il punteggio CSAT. Il nostro team Future Messaging ha aiutato <a href=\"https:\/\/live.imimobile.com\/l\/13622\/2022-03-02\/jgs5sw\" target=\"_blank\" rel=\"noopener\">Vodafone nelle prime campagne RCS di prova<\/a>, ottenendo un tasso di risposta del 25%, rispetto a SMS e MMS che hanno ottenuto un tasso di risposta dell&#8217;1%.<\/p>\n<h2><strong>3. Scegli un fornitore CPaaS che estrapola le complessit\u00e0<\/strong><\/h2>\n<p>Pi\u00f9 canali di messaggistica significa pi\u00f9 scelta per i tuoi clienti. Sebbene questo sia grandioso dal punto di vista dell&#8217;esperienza clienti, significa anche un ecosistema di canali complesso e frammentato per il tuo team IT da gestire. Ogni canale \u00e8 dotato di un proprio set di processi di onboarding e policy, che evolvono continuamente. Inoltre, esistono gli aspetti critici di assicurare privacy dei dati dei clienti e conformit\u00e0 alle normative, aspetti che possono sovraccaricare i tuoi team IT e possono avere impatto sulla velocit\u00e0 di commercializzazione della tua azienda.<\/p>\n<p>In tale scenario, una piattaforma centralizzata che pu\u00f2 estrapolare le complessit\u00e0 di ogni canale e accelerare la commercializzazione \u00e8 una soluzione efficace, come la piattaforma <a href=\"https:\/\/www.webex.com\/products\/cpaas.html\" target=\"_blank\" rel=\"noopener\">Webex Connect Communications Platform as a Service (CPaaS)<\/a>. I fornitori di soluzioni CPaaS hanno una comprovata esperienza nella gestione della complessit\u00e0 di diverse piattaforme di messaggistica e sono spesso coinvolti in programmi partner di fornitori di messaggistica digitali. Pertanto, sono nella posizione ideale per aiutarti a iniziare il tuo percorso di messaggistica digitale e rendere le interazioni con i clienti a prova di futuro adeguandosi a policy e normative di canale mutevoli. Possono misurare e bilanciare il rischio, i vantaggi e il prezzo per creare un business case per i casi d&#8217;uso che desideri distribuire e aiutarti a rimanere al passo con i cambiamenti dei canali futuri.<\/p>\n<p>Una soluzione CPaaS per aziende aumenta ulteriormente le funzionalit\u00e0 CPaaS tradizionali con coordinamento e automazione end-to-end dei percorsi dei clienti. Con funzionalit\u00e0 di integrazione avanzate, una piattaforma CPaaS per aziende pu\u00f2 aiutare i tuoi sistemi backend esistenti a integrarsi con applicazioni di terze parti per sfruttare i dati dei clienti e creare percorsi adatti alle specifiche esigenze dei clienti. Queste piattaforme possono supportare interazioni dei clienti su pi\u00f9 canali, consentendo ai clienti di spostarsi tra i canali durante la conversazione facilmente mantenendo il contesto e assicurando un&#8217;esperienza connessa e contestuale.<\/p>\n<p><a href=\"https:\/\/imimobile.com\/products\/webex-connect\" target=\"_blank\" rel=\"noopener\">Webex Connect<\/a><strong>, <\/strong>la nostra piattaforma CPaaS per aziende \u00e8 ideale quando si tratta di coordinare e consentire percorsi di clienti end-to-end su pi\u00f9 canali.<\/p>\n<blockquote><p>Migliora il tuo percorso di messaggistica digitale con noi come partner CPaaS. Esplora la nostra soluzione <a href=\"https:\/\/www.webex.com\/products\/cpaas.html\" target=\"_blank\" rel=\"noopener\">Webex CPaaS<\/a> per avviare la pianificazione della tua strategia di messaggistica digitale.<\/p><\/blockquote>\n<p><strong>Ulteriori informazioni<\/strong><\/p>\n<p><a href=\"https:\/\/blog.webex.com\/it\/esperienza-clienti\/webex-connect-come-i-provider-di-servizi-possono-sfruttare-lopportunita-cpaas\/\">Webex Connect: come i provider di servizi possono sfruttare l&#8217;opportunit\u00e0 CPaaS<\/a><\/p>\n<p><a href=\"https:\/\/blog.webex.com\/it\/esperienza-clienti\/ogni-interazione-conta-con-la-piattaforma-cpaas-per-aziende\/\">Ogni interazione conta con la piattaforma CPaaS per aziende<\/a><\/p>\n<p><a href=\"https:\/\/blog.webex.com\/it\/esperienza-clienti\/la-democratizzazione-di-cpaas-webex-connect-di-cisco\/\">La democratizzazione di CPaaS \u2013 Webex Connect di Cisco<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>I clienti desiderano comunicare con le aziende attraverso i canali che usano ogni giorno. Utilizzano sempre pi\u00f9 la messaggistica e [&hellip;]<\/p>\n","protected":false},"author":5574,"featured_media":409451,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[424,1504,1565],"tags":[7212],"class_list":["post-392964","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-customer-stories","category-customer-stories-it","category-esperienza-clienti","tag-webex-connect"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tre considerazioni per iniziare il percorso di messaggistica digitale | Webex Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.webex.com\/it\/customer-stories-it\/tre-considerazioni-per-iniziare-il-percorso-di-messaggistica-digitale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tre considerazioni per iniziare il percorso di messaggistica digitale | Webex Blog\" \/>\n<meta property=\"og:description\" content=\"I clienti desiderano comunicare con le aziende attraverso i canali che usano ogni giorno. Utilizzano sempre pi\u00f9 la messaggistica e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.webex.com\/it\/customer-stories-it\/tre-considerazioni-per-iniziare-il-percorso-di-messaggistica-digitale\/\" \/>\n<meta property=\"og:site_name\" content=\"Webex Blog\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-29T15:14:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.webex.com\/wp-content\/uploads\/2022\/03\/webex-contact-center-feature.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"980\" \/>\n\t<meta property=\"og:image:height\" content=\"520\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ramy Riad\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ramy Riad\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/blog.webex.com\/it\/customer-stories-it\/tre-considerazioni-per-iniziare-il-percorso-di-messaggistica-digitale\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/blog.webex.com\/it\/customer-stories-it\/tre-considerazioni-per-iniziare-il-percorso-di-messaggistica-digitale\/\"},\"author\":{\"name\":\"Ramy Riad\",\"@id\":\"https:\/\/blog.webex.com\/es\/#\/schema\/person\/968a4964a07597d6b704611fc92ab262\"},\"headline\":\"Tre considerazioni per iniziare il percorso di messaggistica digitale\",\"datePublished\":\"2022-03-29T15:14:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/blog.webex.com\/it\/customer-stories-it\/tre-considerazioni-per-iniziare-il-percorso-di-messaggistica-digitale\/\"},\"wordCount\":1091,\"image\":{\"@id\":\"https:\/\/blog.webex.com\/it\/customer-stories-it\/tre-considerazioni-per-iniziare-il-percorso-di-messaggistica-digitale\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/blog.webex.com\/wp-content\/uploads\/2022\/03\/webex-contact-center-feature.jpg\",\"keywords\":[\"Webex Connect\"],\"articleSection\":[\"Customer Stories\",\"Customer Stories\",\"Esperienza clienti\u00a0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/blog.webex.com\/it\/customer-stories-it\/tre-considerazioni-per-iniziare-il-percorso-di-messaggistica-digitale\/\",\"url\":\"https:\/\/blog.webex.com\/it\/customer-stories-it\/tre-considerazioni-per-iniziare-il-percorso-di-messaggistica-digitale\/\",\"name\":\"Tre considerazioni per iniziare il percorso di messaggistica digitale | Webex Blog\",\"isPartOf\":{\"@id\":\"https:\/\/blog.webex.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/blog.webex.com\/it\/customer-stories-it\/tre-considerazioni-per-iniziare-il-percorso-di-messaggistica-digitale\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/blog.webex.com\/it\/customer-stories-it\/tre-considerazioni-per-iniziare-il-percorso-di-messaggistica-digitale\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/blog.webex.com\/wp-content\/uploads\/2022\/03\/webex-contact-center-feature.jpg\",\"datePublished\":\"2022-03-29T15:14:04+00:00\",\"author\":{\"@id\":\"https:\/\/blog.webex.com\/es\/#\/schema\/person\/968a4964a07597d6b704611fc92ab262\"},\"breadcrumb\":{\"@id\":\"https:\/\/blog.webex.com\/it\/customer-stories-it\/tre-considerazioni-per-iniziare-il-percorso-di-messaggistica-digitale\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/blog.webex.com\/it\/customer-stories-it\/tre-considerazioni-per-iniziare-il-percorso-di-messaggistica-digitale\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/blog.webex.com\/it\/customer-stories-it\/tre-considerazioni-per-iniziare-il-percorso-di-messaggistica-digitale\/#primaryimage\",\"url\":\"https:\/\/blog.webex.com\/wp-content\/uploads\/2022\/03\/webex-contact-center-feature.jpg\",\"contentUrl\":\"https:\/\/blog.webex.com\/wp-content\/uploads\/2022\/03\/webex-contact-center-feature.jpg\",\"width\":980,\"height\":520,\"caption\":\"#image_title\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blog.webex.com\/it\/customer-stories-it\/tre-considerazioni-per-iniziare-il-percorso-di-messaggistica-digitale\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/blog.webex.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tre considerazioni per iniziare il percorso di messaggistica digitale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blog.webex.com\/es\/#website\",\"url\":\"https:\/\/blog.webex.com\/es\/\",\"name\":\"Webex Blog\",\"description\":\"Webex by Cisco powers collaboration through industry-leading video conferencing, cloud calling and contact center solutions\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blog.webex.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/blog.webex.com\/es\/#\/schema\/person\/968a4964a07597d6b704611fc92ab262\",\"name\":\"Ramy Riad\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/blog.webex.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6b0b2161f323aaea479f7b17b28928f0aa841e98fc26d2c25bddffda21402b95?s=96&d=wp_user_avatar&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6b0b2161f323aaea479f7b17b28928f0aa841e98fc26d2c25bddffda21402b95?s=96&d=wp_user_avatar&r=g\",\"caption\":\"Ramy Riad\"},\"description\":\"Ramy leads our global future digital messaging strategy for the Webex cloud communications platform (CPaaS) solution. Ramy is passionate about creating multi-channel customer experiences and ensuring richer, smarter customer interactions for customers. With more than a decades\u2019 experience in telecommunications, Ramy works with global operator groups and governing bodies as well as messaging providers to truly shape the future of business messaging.\",\"url\":\"https:\/\/blog.webex.com\/it\/contributors\/ramy_riad\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tre considerazioni per iniziare il percorso di messaggistica digitale | Webex Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.webex.com\/it\/customer-stories-it\/tre-considerazioni-per-iniziare-il-percorso-di-messaggistica-digitale\/","og_locale":"it_IT","og_type":"article","og_title":"Tre considerazioni per iniziare il percorso di messaggistica digitale | Webex Blog","og_description":"I clienti desiderano comunicare con le aziende attraverso i canali che usano ogni giorno. Utilizzano sempre pi\u00f9 la messaggistica e [&hellip;]","og_url":"https:\/\/blog.webex.com\/it\/customer-stories-it\/tre-considerazioni-per-iniziare-il-percorso-di-messaggistica-digitale\/","og_site_name":"Webex Blog","article_published_time":"2022-03-29T15:14:04+00:00","og_image":[{"width":980,"height":520,"url":"https:\/\/blog.webex.com\/wp-content\/uploads\/2022\/03\/webex-contact-center-feature.jpg","type":"image\/jpeg"}],"author":"Ramy Riad","twitter_misc":{"Scritto da":"Ramy Riad","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.webex.com\/it\/customer-stories-it\/tre-considerazioni-per-iniziare-il-percorso-di-messaggistica-digitale\/#article","isPartOf":{"@id":"https:\/\/blog.webex.com\/it\/customer-stories-it\/tre-considerazioni-per-iniziare-il-percorso-di-messaggistica-digitale\/"},"author":{"name":"Ramy Riad","@id":"https:\/\/blog.webex.com\/es\/#\/schema\/person\/968a4964a07597d6b704611fc92ab262"},"headline":"Tre considerazioni per iniziare il percorso di messaggistica digitale","datePublished":"2022-03-29T15:14:04+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.webex.com\/it\/customer-stories-it\/tre-considerazioni-per-iniziare-il-percorso-di-messaggistica-digitale\/"},"wordCount":1091,"image":{"@id":"https:\/\/blog.webex.com\/it\/customer-stories-it\/tre-considerazioni-per-iniziare-il-percorso-di-messaggistica-digitale\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.webex.com\/wp-content\/uploads\/2022\/03\/webex-contact-center-feature.jpg","keywords":["Webex Connect"],"articleSection":["Customer Stories","Customer Stories","Esperienza clienti\u00a0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/blog.webex.com\/it\/customer-stories-it\/tre-considerazioni-per-iniziare-il-percorso-di-messaggistica-digitale\/","url":"https:\/\/blog.webex.com\/it\/customer-stories-it\/tre-considerazioni-per-iniziare-il-percorso-di-messaggistica-digitale\/","name":"Tre considerazioni per iniziare il percorso di messaggistica digitale | Webex Blog","isPartOf":{"@id":"https:\/\/blog.webex.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.webex.com\/it\/customer-stories-it\/tre-considerazioni-per-iniziare-il-percorso-di-messaggistica-digitale\/#primaryimage"},"image":{"@id":"https:\/\/blog.webex.com\/it\/customer-stories-it\/tre-considerazioni-per-iniziare-il-percorso-di-messaggistica-digitale\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.webex.com\/wp-content\/uploads\/2022\/03\/webex-contact-center-feature.jpg","datePublished":"2022-03-29T15:14:04+00:00","author":{"@id":"https:\/\/blog.webex.com\/es\/#\/schema\/person\/968a4964a07597d6b704611fc92ab262"},"breadcrumb":{"@id":"https:\/\/blog.webex.com\/it\/customer-stories-it\/tre-considerazioni-per-iniziare-il-percorso-di-messaggistica-digitale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.webex.com\/it\/customer-stories-it\/tre-considerazioni-per-iniziare-il-percorso-di-messaggistica-digitale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/blog.webex.com\/it\/customer-stories-it\/tre-considerazioni-per-iniziare-il-percorso-di-messaggistica-digitale\/#primaryimage","url":"https:\/\/blog.webex.com\/wp-content\/uploads\/2022\/03\/webex-contact-center-feature.jpg","contentUrl":"https:\/\/blog.webex.com\/wp-content\/uploads\/2022\/03\/webex-contact-center-feature.jpg","width":980,"height":520,"caption":"#image_title"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.webex.com\/it\/customer-stories-it\/tre-considerazioni-per-iniziare-il-percorso-di-messaggistica-digitale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.webex.com\/it\/"},{"@type":"ListItem","position":2,"name":"Tre considerazioni per iniziare il percorso di messaggistica digitale"}]},{"@type":"WebSite","@id":"https:\/\/blog.webex.com\/es\/#website","url":"https:\/\/blog.webex.com\/es\/","name":"Webex Blog","description":"Webex by Cisco powers collaboration through industry-leading video conferencing, cloud calling and contact center solutions","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.webex.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/blog.webex.com\/es\/#\/schema\/person\/968a4964a07597d6b704611fc92ab262","name":"Ramy Riad","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/blog.webex.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/6b0b2161f323aaea479f7b17b28928f0aa841e98fc26d2c25bddffda21402b95?s=96&d=wp_user_avatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6b0b2161f323aaea479f7b17b28928f0aa841e98fc26d2c25bddffda21402b95?s=96&d=wp_user_avatar&r=g","caption":"Ramy Riad"},"description":"Ramy leads our global future digital messaging strategy for the Webex cloud communications platform (CPaaS) solution. Ramy is passionate about creating multi-channel customer experiences and ensuring richer, smarter customer interactions for customers. With more than a decades\u2019 experience in telecommunications, Ramy works with global operator groups and governing bodies as well as messaging providers to truly shape the future of business messaging.","url":"https:\/\/blog.webex.com\/it\/contributors\/ramy_riad\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.webex.com\/it\/wp-json\/wp\/v2\/posts\/392964","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.webex.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.webex.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.webex.com\/it\/wp-json\/wp\/v2\/users\/5574"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.webex.com\/it\/wp-json\/wp\/v2\/comments?post=392964"}],"version-history":[{"count":0,"href":"https:\/\/blog.webex.com\/it\/wp-json\/wp\/v2\/posts\/392964\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.webex.com\/it\/wp-json\/wp\/v2\/media\/409451"}],"wp:attachment":[{"href":"https:\/\/blog.webex.com\/it\/wp-json\/wp\/v2\/media?parent=392964"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.webex.com\/it\/wp-json\/wp\/v2\/categories?post=392964"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.webex.com\/it\/wp-json\/wp\/v2\/tags?post=392964"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}