{"id":382142,"date":"2021-02-19T05:31:50","date_gmt":"2021-02-19T13:31:50","guid":{"rendered":"https:\/\/blog.webex.com\/uncategorized-pt-br\/cisco-imimobile-promovendo-o-futuro-da-experiencia-do-cliente-juntos\/"},"modified":"2021-02-19T05:31:50","modified_gmt":"2021-02-19T13:31:50","slug":"cisco-imimobile-promovendo-o-futuro-da-experiencia-do-cliente-juntos","status":"publish","type":"post","link":"https:\/\/blog.webex.com\/pt-br\/experiencia-do-cliente\/cisco-imimobile-promovendo-o-futuro-da-experiencia-do-cliente-juntos\/","title":{"rendered":"Cisco + IMImobile: Promovendo o futuro da experi\u00eancia do cliente, ..."},"content":{"rendered":"<p>Ap\u00f3s anos de considera\u00e7\u00e3o, um amigo meu finalmente cedeu e comprou um Tesla. Ele descreveu uma intera\u00e7\u00e3o com eles recentemente que realmente chamou minha aten\u00e7\u00e3o. Ele recebeu uma notifica\u00e7\u00e3o informando que seus pagamentos estavam em atraso, mas j\u00e1 havia configurado o pagamento autom\u00e1tico. Ele ligou para o departamento de atendimento ao cliente, foi conectado diretamente a um agente que sabia exatamente quem ele era e que acabara de comprar seu carro. Antes que ele pudesse terminar de fazer sua pergunta, ela disse que estava tudo pronto e que o problema estava resolvido. A intera\u00e7\u00e3o acabou quase antes de come\u00e7ar. O motivo que chamou minha aten\u00e7\u00e3o \u00e9 que sua intera\u00e7\u00e3o tinha muitos dos atributos que espero em uma \u00f3tima <em>intera\u00e7\u00e3o<\/em> com o cliente: sem necessidade de esperar, sem necessidade de trabalhar duro para provar quem ele era, sem necessidade de se repetir e com todo o contexto de suas intera\u00e7\u00f5es relevantes anteriores com a empresa.<\/p>\n<h2><span><br \/>\n  <strong>Do atendimento ao cliente \u00e0 experi\u00eancia do cliente <\/strong><br \/>\n<\/span><\/h2>\n<p><a href=\"https:\/\/storage.googleapis.com\/blogs-images\/ciscoblogs\/1\/2021\/02\/Person-holding-phone.png\"><br \/>\n  <img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-355498\" src=\"https:\/\/storage.googleapis.com\/blogs-images\/ciscoblogs\/1\/2021\/02\/Person-holding-phone-768x433.png\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" srcset=\"https:\/\/storage.googleapis.com\/blogs-images\/ciscoblogs\/1\/2021\/02\/Person-holding-phone-300x169.png 300w, https:\/\/storage.googleapis.com\/blogs-images\/ciscoblogs\/1\/2021\/02\/Person-holding-phone-768x433.png 768w\" alt=\"Pessoa segurando o telefone\" width=\"450\" height=\"253\" \/><br \/>\n<\/a>As expectativas dos clientes est\u00e3o aumentando, e isso ocorre porque marcas de consumo como Disney, T-Mobile, Airbnb e Tesla est\u00e3o definindo um novo padr\u00e3o para o que significa uma \u00f3tima experi\u00eancia do cliente. Os clientes desejam interagir quando \u00e9 importante, por exemplo, no meio de uma experi\u00eancia de compra ou quando um item est\u00e1 para ser entregue. Eles querem suporte em seus pr\u00f3prios termos em qualquer modo de comunica\u00e7\u00e3o. Eles querem op\u00e7\u00f5es de autoatendimento ou de se conectar com uma pessoa que tenha as ferramentas certas para atender \u00e0s suas necessidades. E eles realmente apreciam quando voc\u00ea pode antecipar problemas e entrar em contato com eles de maneira proativa. Este \u00e9 o futuro da experi\u00eancia do cliente.<\/p>\n<p>As empresas agora competem n\u00e3o apenas em produtos e servi\u00e7os, mas tamb\u00e9m na qualidade da experi\u00eancia interativa que podem oferecer a seus clientes. Mas a tecnologia de experi\u00eancia do cliente de hoje cria experi\u00eancias fragmentadas e muitas vezes frustrantes que causam a rotatividade de clientes. As empresas n\u00e3o podem mais tolerar silos, porque as intera\u00e7\u00f5es com o cliente n\u00e3o se limitam a um \u00fanico departamento dentro de uma organiza\u00e7\u00e3o, elas ocorrem em muitos pontos de contato, incluindo central de atendimento, organiza\u00e7\u00f5es de experi\u00eancia do cliente, marketing ou nos pr\u00f3prios produtos.<\/p>\n<h2><span><br \/>\n  <strong>Uma jornada \u00fanica e conectada do cliente requer uma plataforma de tecnologia \u00fanica<\/strong><br \/>\n<\/span><\/h2>\n<p>Para fornecer uma jornada \u00fanica e conectada ao cliente, as empresas devem ter visibilidade de todas as intera\u00e7\u00f5es dos clientes em toda a empresa, sejam eles de aplicativos m\u00f3veis, mensagens no Facebook, respondendo a um e-mail de marketing ou conversando com um agente da central de atendimento. A resposta da Cisco \u00e9 a oferta de Experi\u00eancia do Cliente como Servi\u00e7o (CXaaS), que re\u00fane intelig\u00eancia artificial, gerenciamento de experi\u00eancia, ferramentas de colabora\u00e7\u00e3o, recursos omnicanal e programabilidade.\u00a0 Essa plataforma abrangente oferece \u00e0s organiza\u00e7\u00f5es a capacidade de fornecer experi\u00eancias de alta qualidade que os clientes esperam.<\/p>\n<p>Hoje, com a conclus\u00e3o da aquisi\u00e7\u00e3o da IMImobile, demos mais um passo em nosso caminho para entregar este futuro de experi\u00eancia do cliente. O pacote de produtos e solu\u00e7\u00f5es da IMImobile contribui para a nossa vis\u00e3o CXaaS com:<\/p>\n<ul>\n<li><span><br \/>\n  <strong><br \/>\n    <img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-355459\" src=\"https:\/\/storage.googleapis.com\/blogs-images\/ciscoblogs\/1\/2021\/02\/IMImobile-and-Cisco-.jpg\" sizes=\"auto, (max-width: 751px) 100vw, 751px\" srcset=\"https:\/\/storage.googleapis.com\/blogs-images\/ciscoblogs\/1\/2021\/02\/IMImobile-and-Cisco--300x201.jpg 300w, https:\/\/storage.googleapis.com\/blogs-images\/ciscoblogs\/1\/2021\/02\/IMImobile-and-Cisco-.jpg 751w\" alt=\"Agente de experi\u00eancia do cliente trabalhando com CXaaS \" width=\"450\" height=\"302\" \/>A habilita\u00e7\u00e3o de intera\u00e7\u00e3o omnicanal de IMImobile <\/strong><br \/>\n<\/span>inclui mensagens populares e canais sociais, como WhatsApp, RCS, Apple Business Chat, Facebook Messenger, Twitter e WeChat. Ele tamb\u00e9m oferece suporte a canais padr\u00e3o como voz, bate-papo, SMS, e-mail e notifica\u00e7\u00f5es no aplicativo.<\/li>\n<li>Um conjunto de <span><br \/>\n <strong>aplicativos desenvolvidos especificamente<\/strong> <\/span>que fornecem funcionalidade SaaS pronta para uso para intera\u00e7\u00f5es espec\u00edficas de fun\u00e7\u00f5es, incluindo uma solu\u00e7\u00e3o completa de central de atendimento em nuvem, gerenciamento e automa\u00e7\u00e3o de campanhas de marketing, servi\u00e7o e notifica\u00e7\u00f5es operacionais para clientes e assist\u00eancia por v\u00eddeo para equipes e clientes.<\/li>\n<li><span><br \/>\n  <strong>Infraestrutura de plataforma como servi\u00e7o de comunica\u00e7\u00f5es <\/strong>(<strong>CPaaS) para permitir a personaliza\u00e7\u00e3o de comunica\u00e7\u00f5es por meio de<\/strong> <strong>APIs<\/strong><\/span>. Isso fornece uma maneira program\u00e1tica de consumir canais de intera\u00e7\u00e3o para que uma empresa possa criar seus pr\u00f3prios aplicativos ou incorporar comunica\u00e7\u00f5es em experi\u00eancias existentes.<\/p>\n<ul>\n<li>Al\u00e9m do acesso \u00e0 API, a plataforma permite a automa\u00e7\u00e3o e orquestra\u00e7\u00e3o de fluxos de trabalho de intera\u00e7\u00e3o com o cliente. Por exemplo, um fluxo de trabalho pode direcionar uma chamada recebida para um bot de voz que automatiza a intera\u00e7\u00e3o e, se necess\u00e1rio, escalar para um pool de representantes de servi\u00e7o que s\u00e3o qualificados em um tipo espec\u00edfico de resolu\u00e7\u00e3o de problema.<\/li>\n<li>A orquestra\u00e7\u00e3o do fluxo de trabalho permite que qualquer usu\u00e1rio de neg\u00f3cios que n\u00e3o saiba como codificar use um designer visual que pode orquestrar as intera\u00e7\u00f5es com o cliente.<\/li>\n<li>Al\u00e9m de projetar o fluxo de comunica\u00e7\u00e3o, o criador de fluxo tamb\u00e9m pode projetar fluxos de trabalho que afetam os sistemas de neg\u00f3cios internos, como CRM ou remessa ou programa\u00e7\u00e3o. Isso permite que as empresas integrem e alterem rapidamente os fluxos de trabalho sob demanda, economizando tempo e reduzindo custos.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>Ao combinar a solu\u00e7\u00e3o da IMImobile com o <a href=\"https:\/\/www.cisco.com\/c\/en\/us\/products\/contact-center\/webex-contact-center\/index.html\">Webex Contact Center<\/a> e com base em nossos investimentos anteriores no espa\u00e7o, <a href=\"https:\/\/www.cisco.com\/c\/en\/us\/about\/corporate-strategy-office\/acquisitions\/voicea.html\">Voicea<\/a> (IA) e <a href=\"https:\/\/www.cisco.com\/c\/en\/us\/about\/corporate-strategy-office\/acquisitions\/cloudcherry.html\">Cloudcherry<\/a> (Experience Management and Analytics), a Cisco ser\u00e1 capaz de fornecer a oferta CXaaS mais abrangente do mercado, dando \u00e0s empresas a tecnologia necess\u00e1ria para fornecer experi\u00eancias agrad\u00e1veis ao cliente em todo o seu ciclo de vida.<\/p>\n<h2><span><br \/>\n  <strong>Cisco + IMImobile = melhor juntos<\/strong><br \/>\n<\/span><\/h2>\n<p>\u00c0 medida que conhec\u00edamos o neg\u00f3cio IMImobile, o que imediatamente nos impressionou foram as sinergias em nossa proposta de go-to-market. A IMImobile possui uma lista incr\u00edvel de clientes globais de primeira linha, como Barclays, Hermes, Best Buy e Walgreens. Eles s\u00e3o reconhecidos pelo Gartner, Forrester e IDC por seu trabalho em ajudar sua base de clientes corporativos a transformar seu CX e gerenciar as intera\u00e7\u00f5es com o cliente em escala. Estamos entusiasmados em expandir os produtos da IMImobile por meio da distribui\u00e7\u00e3o massiva da Cisco, apresentando-os ao nosso portf\u00f3lio de produtos Webex junto com mais de 600 milh\u00f5es de usu\u00e1rios de reuni\u00f5es por m\u00eas, mais de 100 milh\u00f5es de terminais UCaaS, 1,7 milh\u00f5es de terminais de v\u00eddeo e 3,6 milh\u00f5es de agentes da central de atendimento.<\/p>\n<h2><span><br \/>\n  <strong>O que vem a seguir?<\/strong><br \/>\n<\/span><\/h2>\n<p>Estou muito animado para dar as boas-vindas \u00e0 equipe IMImobile em nossa organiza\u00e7\u00e3o. Ap\u00f3s o encerramento, manteremos as duas equipes funcionando separadamente dentro da minha organiza\u00e7\u00e3o com o esp\u00edrito de apoiar as ambi\u00e7\u00f5es estrat\u00e9gicas existentes da IMImobile. Com o tempo, trabalharemos juntos de maneira reflexiva e diligente para integrar os produtos da IMImobile aos produtos da Cisco e, assim, oferecer o maior valor aos nossos clientes &#8211; e aos seus.<\/p>\n<blockquote>\n<h3><span><br \/>\n  <strong>Visite nosso site para obter mais informa\u00e7\u00f5es sobre esta <a href=\"https:\/\/www.cisco.com\/c\/en\/us\/about\/corporate-strategy-office\/acquisitions\/imimobile.html\">aquisi\u00e7\u00e3o<\/a> e solu\u00e7\u00f5es <a href=\"https:\/\/www.cisco.com\/c\/en\/us\/products\/contact-center\/index.html\">Cisco Contact Center<\/a><\/strong><br \/>\n<\/span><\/h3>\n<\/blockquote>\n<p><strong>Saiba mais<\/strong><\/p>\n<p><a href=\"https:\/\/newsroom.cisco.com\/press-release-content?type=webcontent&#038;articleId=2143832\">A Cisco conclui a aquisi\u00e7\u00e3o da IMImobile PLC [comunicado \u00e0 imprensa)<\/a><\/p>\n<p><a href=\"https:\/\/newsroom.cisco.com\/press-release-content?type=webcontent&#038;articleId=2130728\">A Cisco adquire a IMImobile para incorporar engajamento Omnichannel na experi\u00eancia do cliente como um servi\u00e7o [Comunicado \u00e0 imprensa &#8211; dezembro de 2020]<\/a><\/p>\n<p><a href=\"https:\/\/blogs.cisco.com\/collaboration\/the-future-of-customer-experience-begins-now\">O futuro da experi\u00eancia do cliente come\u00e7a agora [Blog]<\/a><\/p>\n<p><a href=\"https:\/\/video.cisco.com\/video\/6225322780001\">Apresentando o novo Webex Contact Center: A tecnologia que possibilita o futuro do CX [Webinar]<\/a><\/p>\n<p><a href=\"https:\/\/imimobile.com\/\">Website IMImobile<\/a><\/p>\n<p><a href=\"https:\/\/www.cisco.com\/c\/en\/us\/products\/contact-center\/cloud-contact-center-solutions\/index.html\">P\u00e1gina do Webex Contact Center<\/a><\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoje, com a conclus\u00e3o da aquisi\u00e7\u00e3o da IMImobile, demos mais um passo em nosso caminho para entregar o futuro da experi\u00eancia do cliente, com uma jornada de cliente conectada \u00fanica e abrangente.<\/p>\n","protected":false},"author":5480,"featured_media":382143,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[5283,1566],"tags":[7212],"class_list":["post-382142","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-colaboracao","category-experiencia-do-cliente","tag-webex-connect"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cisco + IMImobile: Promovendo o futuro da experi\u00eancia do cliente, juntos | Webex Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.webex.com\/customer-experience\/cisco-imi-delivering-the-future-of-customer-experience-together\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cisco + IMImobile: Promovendo o futuro da experi\u00eancia do cliente, juntos | Webex Blog\" \/>\n<meta property=\"og:description\" content=\"Hoje, com a conclus\u00e3o da aquisi\u00e7\u00e3o da IMImobile, demos mais um passo em nosso caminho para entregar o futuro da experi\u00eancia do cliente, com uma jornada de cliente conectada \u00fanica e abrangente.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.webex.com\/customer-experience\/cisco-imi-delivering-the-future-of-customer-experience-together\/\" \/>\n<meta property=\"og:site_name\" content=\"Webex Blog\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-19T13:31:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.webex.com\/wp-content\/uploads\/2021\/02\/IMIblog-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"770\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Omar Tawakol\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Omar Tawakol\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.webex.com\\\/customer-experience\\\/cisco-imi-delivering-the-future-of-customer-experience-together\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/customer-experience\\\/cisco-imi-delivering-the-future-of-customer-experience-together\\\/\"},\"author\":{\"name\":\"Omar Tawakol\",\"@id\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/#\\\/schema\\\/person\\\/6771b2af6bbbb9d29e8058f2faff7043\"},\"headline\":\"Cisco + IMImobile: Promovendo o futuro da experi\u00eancia do cliente, ...\",\"datePublished\":\"2021-02-19T13:31:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/customer-experience\\\/cisco-imi-delivering-the-future-of-customer-experience-together\\\/\"},\"wordCount\":1258,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/customer-experience\\\/cisco-imi-delivering-the-future-of-customer-experience-together\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.webex.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/IMIblog-1.png\",\"keywords\":[\"Webex Connect\"],\"articleSection\":[\"Colabora\u00e7\u00e3o\",\"Experi\u00eancia do cliente\u00a0\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.webex.com\\\/customer-experience\\\/cisco-imi-delivering-the-future-of-customer-experience-together\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.webex.com\\\/customer-experience\\\/cisco-imi-delivering-the-future-of-customer-experience-together\\\/\",\"url\":\"https:\\\/\\\/blog.webex.com\\\/customer-experience\\\/cisco-imi-delivering-the-future-of-customer-experience-together\\\/\",\"name\":\"Cisco + IMImobile: Promovendo o futuro da experi\u00eancia do cliente, juntos | Webex Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/customer-experience\\\/cisco-imi-delivering-the-future-of-customer-experience-together\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/customer-experience\\\/cisco-imi-delivering-the-future-of-customer-experience-together\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.webex.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/IMIblog-1.png\",\"datePublished\":\"2021-02-19T13:31:50+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/#\\\/schema\\\/person\\\/6771b2af6bbbb9d29e8058f2faff7043\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/customer-experience\\\/cisco-imi-delivering-the-future-of-customer-experience-together\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.webex.com\\\/customer-experience\\\/cisco-imi-delivering-the-future-of-customer-experience-together\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/blog.webex.com\\\/customer-experience\\\/cisco-imi-delivering-the-future-of-customer-experience-together\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.webex.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/IMIblog-1.png\",\"contentUrl\":\"https:\\\/\\\/blog.webex.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/IMIblog-1.png\",\"width\":770,\"height\":533},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.webex.com\\\/customer-experience\\\/cisco-imi-delivering-the-future-of-customer-experience-together\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.webex.com\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cisco + IMImobile: Promovendo o futuro da experi\u00eancia do cliente, juntos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/\",\"name\":\"Webex Blog\",\"description\":\"Webex by Cisco powers collaboration through industry-leading video conferencing, cloud calling and contact center solutions\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/#\\\/schema\\\/person\\\/6771b2af6bbbb9d29e8058f2faff7043\",\"name\":\"Omar Tawakol\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1801925157ac700821fd7271d93bbdfc45df789c97fd84e6627281799caecac2?s=96&d=wp_user_avatar&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1801925157ac700821fd7271d93bbdfc45df789c97fd84e6627281799caecac2?s=96&d=wp_user_avatar&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1801925157ac700821fd7271d93bbdfc45df789c97fd84e6627281799caecac2?s=96&d=wp_user_avatar&r=g\",\"caption\":\"Omar Tawakol\"},\"description\":\"Omar Tawakol is the Vice President &amp; General Manager of the Cisco Contact Center business unit. In this role, Omar is responsible for the development and execution of the Cisco Contact Center strategy and portfolio. Prior to this role, Omar was the co-founder and CEO of Voicea which he led until its acquisition by Cisco in August 2019. Voicea is a voice-based AI assistant platform that is used by over 10,000 companies and had attracted investments from Cisco, Google, Salesforce and Microsoft. Prior to Voicea, Omar Tawakol was the founder and CEO of BlueKai which built the worlds largest consumer data marketplace and data management platform. BlueKai was acquired by Oracle in 2014, and Omar served as the Senior VP &amp; GM of the Oracle Data Cloud business unit. Omar earned an MS in Computer Science from Stanford University and a BS from Massachusetts Institute of Technology.\",\"url\":\"https:\\\/\\\/blog.webex.com\\\/pt-br\\\/contributors\\\/omartawakol\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cisco + IMImobile: Promovendo o futuro da experi\u00eancia do cliente, juntos | Webex Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.webex.com\/customer-experience\/cisco-imi-delivering-the-future-of-customer-experience-together\/","og_locale":"pt_BR","og_type":"article","og_title":"Cisco + IMImobile: Promovendo o futuro da experi\u00eancia do cliente, juntos | Webex Blog","og_description":"Hoje, com a conclus\u00e3o da aquisi\u00e7\u00e3o da IMImobile, demos mais um passo em nosso caminho para entregar o futuro da experi\u00eancia do cliente, com uma jornada de cliente conectada \u00fanica e abrangente.","og_url":"https:\/\/blog.webex.com\/customer-experience\/cisco-imi-delivering-the-future-of-customer-experience-together\/","og_site_name":"Webex Blog","article_published_time":"2021-02-19T13:31:50+00:00","og_image":[{"width":770,"height":533,"url":"https:\/\/blog.webex.com\/wp-content\/uploads\/2021\/02\/IMIblog-1.png","type":"image\/png"}],"author":"Omar Tawakol","twitter_misc":{"Escrito por":"Omar Tawakol","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.webex.com\/customer-experience\/cisco-imi-delivering-the-future-of-customer-experience-together\/#article","isPartOf":{"@id":"https:\/\/blog.webex.com\/customer-experience\/cisco-imi-delivering-the-future-of-customer-experience-together\/"},"author":{"name":"Omar Tawakol","@id":"https:\/\/blog.webex.com\/es\/#\/schema\/person\/6771b2af6bbbb9d29e8058f2faff7043"},"headline":"Cisco + IMImobile: Promovendo o futuro da experi\u00eancia do cliente, ...","datePublished":"2021-02-19T13:31:50+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.webex.com\/customer-experience\/cisco-imi-delivering-the-future-of-customer-experience-together\/"},"wordCount":1258,"commentCount":0,"image":{"@id":"https:\/\/blog.webex.com\/customer-experience\/cisco-imi-delivering-the-future-of-customer-experience-together\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.webex.com\/wp-content\/uploads\/2021\/02\/IMIblog-1.png","keywords":["Webex Connect"],"articleSection":["Colabora\u00e7\u00e3o","Experi\u00eancia do cliente\u00a0"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.webex.com\/customer-experience\/cisco-imi-delivering-the-future-of-customer-experience-together\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.webex.com\/customer-experience\/cisco-imi-delivering-the-future-of-customer-experience-together\/","url":"https:\/\/blog.webex.com\/customer-experience\/cisco-imi-delivering-the-future-of-customer-experience-together\/","name":"Cisco + IMImobile: Promovendo o futuro da experi\u00eancia do cliente, juntos | Webex Blog","isPartOf":{"@id":"https:\/\/blog.webex.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.webex.com\/customer-experience\/cisco-imi-delivering-the-future-of-customer-experience-together\/#primaryimage"},"image":{"@id":"https:\/\/blog.webex.com\/customer-experience\/cisco-imi-delivering-the-future-of-customer-experience-together\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.webex.com\/wp-content\/uploads\/2021\/02\/IMIblog-1.png","datePublished":"2021-02-19T13:31:50+00:00","author":{"@id":"https:\/\/blog.webex.com\/es\/#\/schema\/person\/6771b2af6bbbb9d29e8058f2faff7043"},"breadcrumb":{"@id":"https:\/\/blog.webex.com\/customer-experience\/cisco-imi-delivering-the-future-of-customer-experience-together\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.webex.com\/customer-experience\/cisco-imi-delivering-the-future-of-customer-experience-together\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/blog.webex.com\/customer-experience\/cisco-imi-delivering-the-future-of-customer-experience-together\/#primaryimage","url":"https:\/\/blog.webex.com\/wp-content\/uploads\/2021\/02\/IMIblog-1.png","contentUrl":"https:\/\/blog.webex.com\/wp-content\/uploads\/2021\/02\/IMIblog-1.png","width":770,"height":533},{"@type":"BreadcrumbList","@id":"https:\/\/blog.webex.com\/customer-experience\/cisco-imi-delivering-the-future-of-customer-experience-together\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.webex.com\/pt-br\/"},{"@type":"ListItem","position":2,"name":"Cisco + IMImobile: Promovendo o futuro da experi\u00eancia do cliente, juntos"}]},{"@type":"WebSite","@id":"https:\/\/blog.webex.com\/es\/#website","url":"https:\/\/blog.webex.com\/es\/","name":"Webex Blog","description":"Webex by Cisco powers collaboration through industry-leading video conferencing, cloud calling and contact center solutions","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.webex.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/blog.webex.com\/es\/#\/schema\/person\/6771b2af6bbbb9d29e8058f2faff7043","name":"Omar Tawakol","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/1801925157ac700821fd7271d93bbdfc45df789c97fd84e6627281799caecac2?s=96&d=wp_user_avatar&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1801925157ac700821fd7271d93bbdfc45df789c97fd84e6627281799caecac2?s=96&d=wp_user_avatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1801925157ac700821fd7271d93bbdfc45df789c97fd84e6627281799caecac2?s=96&d=wp_user_avatar&r=g","caption":"Omar Tawakol"},"description":"Omar Tawakol is the Vice President &amp; General Manager of the Cisco Contact Center business unit. In this role, Omar is responsible for the development and execution of the Cisco Contact Center strategy and portfolio. Prior to this role, Omar was the co-founder and CEO of Voicea which he led until its acquisition by Cisco in August 2019. Voicea is a voice-based AI assistant platform that is used by over 10,000 companies and had attracted investments from Cisco, Google, Salesforce and Microsoft. Prior to Voicea, Omar Tawakol was the founder and CEO of BlueKai which built the worlds largest consumer data marketplace and data management platform. BlueKai was acquired by Oracle in 2014, and Omar served as the Senior VP &amp; GM of the Oracle Data Cloud business unit. Omar earned an MS in Computer Science from Stanford University and a BS from Massachusetts Institute of Technology.","url":"https:\/\/blog.webex.com\/pt-br\/contributors\/omartawakol\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.webex.com\/pt-br\/wp-json\/wp\/v2\/posts\/382142","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.webex.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.webex.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.webex.com\/pt-br\/wp-json\/wp\/v2\/users\/5480"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.webex.com\/pt-br\/wp-json\/wp\/v2\/comments?post=382142"}],"version-history":[{"count":0,"href":"https:\/\/blog.webex.com\/pt-br\/wp-json\/wp\/v2\/posts\/382142\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.webex.com\/pt-br\/wp-json\/wp\/v2\/media\/382143"}],"wp:attachment":[{"href":"https:\/\/blog.webex.com\/pt-br\/wp-json\/wp\/v2\/media?parent=382142"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.webex.com\/pt-br\/wp-json\/wp\/v2\/categories?post=382142"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.webex.com\/pt-br\/wp-json\/wp\/v2\/tags?post=382142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}