{"id":386046,"date":"2019-06-11T09:45:19","date_gmt":"2019-06-11T16:45:19","guid":{"rendered":"https:\/\/blog.webex.com\/uncategorized-pt-br\/conheca-voce-o-workspace-cognitivo-de-tres\/"},"modified":"2019-06-11T09:45:19","modified_gmt":"2019-06-11T16:45:19","slug":"conheca-voce-o-workspace-cognitivo-de-tres","status":"publish","type":"post","link":"https:\/\/blog.webex.com\/pt-br\/collaboration\/hybrid-work\/conheca-voce-o-workspace-cognitivo-de-tres\/","title":{"rendered":"Conhe\u00e7a voc\u00ea \u2014 O workspace cognitivo de tr\u00eas"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-287192\" src=\"https:\/\/alln-extcloud-storage.cisco.com\/ciscoblogs\/5cff61089aaae-300x200.jpg\" alt=\"Conhe\u00e7a voc\u00ea - O workspace cognitivo de tr\u00eas\" width=\"300\" height=\"200\" \/>O futuro do trabalho ser\u00e1 de tr\u00eas minutos. E a boa not\u00edcia \u00e9 que ele est\u00e1 aqui agora. \u00c9 parte de uma nova abordagem chamada colabora\u00e7\u00e3o cognitiva que incorpora intelig\u00eancia inteligente com o contexto certo com as pessoas certas para promover conex\u00f5es mais aprofundadas personalizadas por humanos.<\/p>\n<p>As \u00faltimas d\u00e9cadas t\u00eam visto o trabalho colaborativo como uma atividade dependente do espa\u00e7o f\u00edsico e da tecnologia de comunica\u00e7\u00e3o como seus principais ativos. Salas de reuni\u00f5es foram necess\u00e1rias para conversas entre v\u00e1rias pessoas e chamadas de confer\u00eancia. Ferramentas de e-mail e confer\u00eancia na Web permitidas para v\u00eddeo e r\u00e1pida difus\u00e3o de mensagens e documentos. Essas foram todas as coisas boas. Eles ajudou a levar o processo de colabora\u00e7\u00e3o adiante e com a bilidade de tecnologias m\u00f3veis e home offices, eles ajudou a tirar v\u00e1rias pessoas da caixa do &#8220;escrit\u00f3rio&#8221;.<\/p>\n<p>Mas agora que conectividade confi\u00e1vel foi estabelecida, \u00e9 hora de examinar o que n\u00e3o est\u00e1 l\u00e1: uma pe\u00e7a faltando no quebra-cabe\u00e7a da colabora\u00e7\u00e3o, uma dimens\u00e3o ausente que est\u00e1 se tornando mais vital como um usu\u00e1rio de produtividade r\u00e1pida e eficiente. Estou me referindo \u00e0 profundidade de rela\u00e7\u00e3o interpersonal que vem das informa\u00e7\u00f5es.<\/p>\n<h2>O problema: Falta de conectividade humana verdadeira<\/h2>\n<p>Quando voc\u00ea v\u00ea pessoas sentados do seu lado em uma reuni\u00e3o, seja em pessoa ou em uma videoconfer\u00eancia, o que voc\u00ea sabe sobre essas pessoas? Quem s\u00e3o eles? De onde eles vieram em termos de educa\u00e7\u00e3o e experi\u00eancia de trabalho anterior? Quem voc\u00ea conheceria em comum? O Insights em pessoas permite que reuni\u00f5es e projetos pro progressem mais rapidamente, diminuindo a fase de conhecimento de voc\u00ea e ao mesmo tempo maximizando os <a href=\"https:\/\/youtu.be\/C4yXjuBfd8E\">benef\u00edcios da mesma<\/a> fase.<\/p>\n<p>As pessoas j\u00e1 t\u00eam tentando fazer isso, \u00e9 claro, usando uma sess\u00e3o de auto introdu\u00e7\u00e3o &#8220;ao redor da tabela&#8221;. Mas este \u00e9 um exemplo de um exerc\u00edcio demorado na sobrecarga de informa\u00e7\u00f5es, que resulta na sa\u00edda de mais pessoas do que em vez de consumir novas informa\u00e7\u00f5es. Tamb\u00e9m \u00e9 poss\u00edvel google uma pessoa ou pesquis\u00e1-la no LinkedIn, mas esta tem as duas desvantagens de informa\u00e7\u00f5es que est\u00e3o fora de prazo, bem como o fato de que quase todos os nomes s\u00e3o compartilhados por muitas outras pessoas no planeta. Encontrar a pessoa certa \u00e9 demorada. Escolher a pessoa errada pode ser perigosos.<\/p>\n<p>Quando conex\u00f5es como estas permanecem incompletas, uma grande quantidade de valor do projeto tamb\u00e9m \u00e9 perdida. A falta de conex\u00e3o humana leva \u00e0 falta de propriedade por parte dos membros da equipe. Como qualquer \u00f3timo l\u00edder vai dizer, uma equipe precisa de uma conex\u00e3o melhor e din\u00e2mica para manter din\u00e2mica, inspira\u00e7\u00e3o e coes\u00e3o. N\u00e3o \u00e9 de modo nenhum que um espa\u00e7o para dizer que a mesma coisa se aplica a reuni\u00f5es e projetos.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-287186\" src=\"https:\/\/alln-extcloud-storage.cisco.com\/ciscoblogs\/5cff5d9a75efb.png\" alt=\"Conhe\u00e7a voc\u00ea - O workspace cognitivo de tr\u00eas\" width=\"974\" height=\"158\" \/><\/p>\n<p>\u00a0<\/p>\n<h2>O futuro do trabalho: Colabora\u00e7\u00e3o e insights cognitivos<\/h2>\n<p>A Colabora\u00e7\u00e3o cognitiva ajuda a oferecer experi\u00eancias enormemente personalizadas e de transforma\u00e7\u00e3o para o local de trabalho. Ele usa intelig\u00eancia virtual e aprendizagem de m\u00e1quina para ajudar em uma variedade de atividades relacionadas a reuni\u00f5es e projetos, desde log-ons sem esfor\u00e7o at\u00e9 o reconhecimento facial que fornece aos participantes da tela vozes virtuais e comandos falados para o pr\u00f3prio sala de reuni\u00e3o.<\/p>\n<p>Um dos conceitos mais importantes \u00e9 a capacidade de obter informa\u00e7\u00f5es instant\u00e2neas e just-in-time para entender e se identificar melhor com as pessoas na reuni\u00e3o. Mas primeiro, vamos colocar isso em contexto:<\/p>\n<p>Um dos benef\u00edcios das confer\u00eancias na Web, al\u00e9m da economia de tempo em viagens, \u00e9 o fato de que os outros participantes est\u00e3o vis\u00edveis na tela. Ter rostos para olhar em vez de apenas vozes para ouvir ou mensagens de texto para ler, proporciona um benef\u00edcio imensur\u00e1vel ao progresso de um projeto.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-287195\" src=\"https:\/\/alln-extcloud-storage.cisco.com\/ciscoblogs\/5cff62487a0e1-300x200.jpg\" alt=\"O workspace cognitivo de tr\u00eas pessoas\" width=\"300\" height=\"200\" \/>Linguagem corporal, contato visual, desbloqueio facial, essas s\u00e3o todas as pistas que ajudam a levar as conversas adiante. Eles representam a ess\u00eancia da conex\u00e3o humana e ajudam a refor\u00e7ar componentes essenciais, como confian\u00e7a e sinergia. Mas somente recentemente a tecnologia ficou dispon\u00edvel o suficiente e acess\u00edvel o suficiente para que as empresas a aceitarem. Videoconfer\u00eancia de alta qualidade desta maneira promete melhorar muito o processo de reuni\u00e3o e colabora\u00e7\u00e3o.<\/p>\n<p>Deixar todos t\u00e3o claramente vis\u00edveis na tela fornece uma oportunidade perfeita para fechar o loop adicionando insights que descrevem cada pessoa e adicionem contexto.<\/p>\n<p>\u00a0<\/p>\n<p><a href=\"https:\/\/engage2demand.cisco.com\/LP=16296?ccid=cc001191&#038;oid=rptco016710https:\/\/www.cisco.com\/c\/dam\/en\/us\/solutions\/collaboration\/people-have-spoken-infographic.pdf?ccid=cc001191&#038;oid=ifgco016874\">   <img loading=\"lazy\" decoding=\"async\" class=\"wp-image-287190 size-medium\" src=\"https:\/\/alln-extcloud-storage.cisco.com\/ciscoblogs\/5cff5f75af89a-300x572.png\" alt=\"Conhe\u00e7a voc\u00ea - O workspace cognitivo de tr\u00eas \" width=\"300\" height=\"572\" \/> <\/a> Novos insights da pesquisa do Insights[\/legenda]<\/p>\n<h2>Por que os insights s\u00e3o vitais para o sucesso da equipe\/projeto<\/h2>\n<p>A nossa \u00e9 uma era em que as pessoas est\u00e3o mais conectadas fisicamente do que nunca, gra\u00e7as a tecnologias sem fio e \u00e0 Internet, mas, \u00e0s mesmas pessoas, tamb\u00e9m est\u00e3o se sente menos conectadas incorretamente.<\/p>\n<p>A inova\u00e7\u00e3o \u00e9 o inverso, as pessoas precisam fazer pesquisas nas suas ideias, se sentir conectadas e se conhecerem em um n\u00edvel mais humano em rela\u00e7\u00e3o a um n\u00edvel superficial. Precisa haver uma terceira dimens\u00e3o na rela\u00e7\u00e3o.<\/p>\n<p>H\u00e1 muitas pessoas que j\u00e1 viram o valor das informa\u00e7\u00f5es e o foram fisicamente integrados em seus ambientes. Steve Jobs sempre garante que seus workspaces na Apple fornem oportunidades amplas para as pessoas se reunirem e se socializarem no caminho para a cafeteria. Havia tomadas em todos os lugares, e a cultura corporativa permitia que as pessoas levem seus laptops com elas e conversem com outras pessoas no hor\u00e1rio da empresa.<\/p>\n<p>Muitas outras organiza\u00e7\u00f5es t\u00eam seguido o processo e n\u00e3o apenas inicializa\u00e7\u00f5es de alta tecnologia de ponta. Eles reconheceram que a inclus\u00e3o vital na promo\u00e7\u00e3o de um ambiente de trabalho produtivo e colaborativo \u00e9 profunda: as pessoas precisam de mais detalhes em suas intera\u00e7\u00f5es e relacionamentos.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-287198 alignleft\" src=\"https:\/\/alln-extcloud-storage.cisco.com\/ciscoblogs\/5cff63eb425f0-300x200.jpg\" alt=\"Conhe\u00e7a voc\u00ea - O workspace cognitivo de tr\u00eas\" width=\"300\" height=\"200\" \/><\/p>\n<p>Agora, a tecnologia existe que permite que os dois mundos de web confer\u00eancia e profunda intera\u00e7\u00e3o humana se misturem sem esfor\u00e7o por meio de insights conduzidos pela Colabora\u00e7\u00e3o cognitiva. Isso, acredito, ser\u00e1 a pr\u00f3xima onda de produtividade e inova\u00e7\u00e3o corporativas possibilitada por um workspace de tr\u00eas realmente tr\u00eas empresas.<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<hr \/>\n<p>Veja nossa Colabora\u00e7\u00e3o cognitiva dar vida de maneira Webex mesmo no nosso novo Webex Musical &#8211; <a href=\"https:\/\/youtu.be\/C4yXjuBfd8E\">Conhe\u00e7a<\/a>voc\u00ea.<\/p>\n<p>Para obter mais informa\u00e7\u00f5es da pesquisa sobre a Dimension Research e como voc\u00ea pode criar uma for\u00e7a de trabalho mais eficaz atrav\u00e9s de colabora\u00e7\u00e3o cognitiva, leia o relat\u00f3rio completo <a href=\"https:\/\/engage2demand.cisco.com\/LP=16296?ccid=cc001191&#038;oid=rptco016710https:\/\/www.cisco.com\/c\/dam\/en\/us\/solutions\/collaboration\/people-have-spoken-infographic.pdf?ccid=cc001191&#038;oid=ifgco016874\"><\/a>aqui.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O futuro do trabalho ser\u00e1 de tr\u00eas minutos. E a boa not\u00edcia \u00e9 que ele est\u00e1 aqui agora. Ela faz parte de uma nova abordagem chamada colabora\u00e7\u00e3o cognitiva, incorporando intelig\u00eancia inteligente com o contexto certo.<\/p>\n","protected":false},"author":5377,"featured_media":386047,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[3637,1269],"tags":[7249,9972,5292,7250,499,6046,10050,10049,2552,573,10048,10047],"class_list":["post-386046","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-collaboration","category-hybrid-work","tag-ciscocx-pt-br","tag-clus-pt-br","tag-blogs-da-cisco","tag-cisco-cx-pt-br","tag-cisco-live","tag-colaboracao-cognitiva","tag-conectividade-humana","tag-conexao-humana","tag-futuro-do-trabalho","tag-artificial-intelligence","tag-local-de-trabalho-conectado-da-cisco","tag-videoconferencia-pt-br-7"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conhe\u00e7a voc\u00ea \u2014 O workspace cognitivo de tr\u00eas | Webex Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.webex.com\/pt-br\/trabalho-hibrido\/conheca-voce-o-workspace-cognitivo-de-tres\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conhe\u00e7a voc\u00ea \u2014 O workspace cognitivo de tr\u00eas | Webex Blog\" \/>\n<meta property=\"og:description\" content=\"O futuro do trabalho ser\u00e1 de tr\u00eas minutos. E a boa not\u00edcia \u00e9 que ele est\u00e1 aqui agora. Ela faz parte de uma nova abordagem chamada colabora\u00e7\u00e3o cognitiva, incorporando intelig\u00eancia inteligente com o contexto certo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.webex.com\/pt-br\/trabalho-hibrido\/conheca-voce-o-workspace-cognitivo-de-tres\/\" \/>\n<meta property=\"og:site_name\" content=\"Webex Blog\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-11T16:45:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.webex.com\/wp-content\/uploads\/2019\/06\/5cff619352d67-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2119\" \/>\n\t<meta property=\"og:image:height\" content=\"1414\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Aruna Ravichandran\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Aruna Ravichandran\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.webex.com\\\/pt-br\\\/trabalho-hibrido\\\/conheca-voce-o-workspace-cognitivo-de-tres\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/pt-br\\\/trabalho-hibrido\\\/conheca-voce-o-workspace-cognitivo-de-tres\\\/\"},\"author\":{\"name\":\"Aruna Ravichandran\",\"@id\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/#\\\/schema\\\/person\\\/13123e3d3a33894876e3bb847361fae4\"},\"headline\":\"Conhe\u00e7a voc\u00ea \u2014 O workspace cognitivo de tr\u00eas\",\"datePublished\":\"2019-06-11T16:45:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/pt-br\\\/trabalho-hibrido\\\/conheca-voce-o-workspace-cognitivo-de-tres\\\/\"},\"wordCount\":1125,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/pt-br\\\/trabalho-hibrido\\\/conheca-voce-o-workspace-cognitivo-de-tres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.webex.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/5cff619352d67-1.jpg\",\"keywords\":[\"#CiscoCX\",\"#CLUS\",\"Blogs da Cisco\",\"Cisco CX\",\"Cisco Live\",\"colabora\u00e7\u00e3o cognitiva\",\"conectividade humana\",\"conex\u00e3o humana\",\"futuro do trabalho\",\"Artificial Intelligence\",\"local de trabalho conectado da cisco\",\"videoconfer\u00eancia\"],\"articleSection\":[\"Collaboration\",\"Hybrid Work\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.webex.com\\\/pt-br\\\/trabalho-hibrido\\\/conheca-voce-o-workspace-cognitivo-de-tres\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.webex.com\\\/pt-br\\\/trabalho-hibrido\\\/conheca-voce-o-workspace-cognitivo-de-tres\\\/\",\"url\":\"https:\\\/\\\/blog.webex.com\\\/pt-br\\\/trabalho-hibrido\\\/conheca-voce-o-workspace-cognitivo-de-tres\\\/\",\"name\":\"Conhe\u00e7a voc\u00ea \u2014 O workspace cognitivo de tr\u00eas | Webex Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/pt-br\\\/trabalho-hibrido\\\/conheca-voce-o-workspace-cognitivo-de-tres\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/pt-br\\\/trabalho-hibrido\\\/conheca-voce-o-workspace-cognitivo-de-tres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.webex.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/5cff619352d67-1.jpg\",\"datePublished\":\"2019-06-11T16:45:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/#\\\/schema\\\/person\\\/13123e3d3a33894876e3bb847361fae4\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.webex.com\\\/pt-br\\\/trabalho-hibrido\\\/conheca-voce-o-workspace-cognitivo-de-tres\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.webex.com\\\/pt-br\\\/trabalho-hibrido\\\/conheca-voce-o-workspace-cognitivo-de-tres\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/blog.webex.com\\\/pt-br\\\/trabalho-hibrido\\\/conheca-voce-o-workspace-cognitivo-de-tres\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.webex.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/5cff619352d67-1.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.webex.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/5cff619352d67-1.jpg\",\"width\":2119,\"height\":1414},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.webex.com\\\/pt-br\\\/trabalho-hibrido\\\/conheca-voce-o-workspace-cognitivo-de-tres\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.webex.com\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conhe\u00e7a voc\u00ea \u2014 O workspace cognitivo de tr\u00eas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/\",\"name\":\"Webex Blog\",\"description\":\"Webex by Cisco powers collaboration through industry-leading video conferencing, cloud calling and contact center solutions\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.webex.com\\\/es\\\/#\\\/schema\\\/person\\\/13123e3d3a33894876e3bb847361fae4\",\"name\":\"Aruna Ravichandran\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7448744d0884becd5a26d9b152a552ea57a4ade4d71ce42122061ea2ab76575?s=96&d=wp_user_avatar&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7448744d0884becd5a26d9b152a552ea57a4ade4d71ce42122061ea2ab76575?s=96&d=wp_user_avatar&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7448744d0884becd5a26d9b152a552ea57a4ade4d71ce42122061ea2ab76575?s=96&d=wp_user_avatar&r=g\",\"caption\":\"Aruna Ravichandran\"},\"description\":\"Aruna drives significant revenue growth and brand value through a powerful blend of technological expertise, data science acumen, strategic storytelling, and marketing innovation. An early adopter of marketing automation and AI, Aruna stays at the forefront of technological advancements, consistently leveraging them to disrupt competitive markets. Her leadership in SaaS marketing and enterprise technology and her vision for AI's role in shaping customer and employee experiences have made her a sought-after thought leader in the industry. Beyond her professional achievements, Aruna is a passionate advocate for women in technology and making the STEM fields more inclusive and accessible. Aruna has an MBA and MS in Computer Engineering from Santa Clara University and a BS in Computer Science from Bangalore Institute of Technology. She is an alumna of the CMO Leadership program at Kellogg Business School. She serves on Cal Polytechnic San Luis Obispo, Fast Company, Forbes Technology Council, and Vox Media boards.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/aruna2u\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/aruna13\"],\"url\":\"https:\\\/\\\/blog.webex.com\\\/pt-br\\\/contributors\\\/arunaravichandran-2\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conhe\u00e7a voc\u00ea \u2014 O workspace cognitivo de tr\u00eas | Webex Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.webex.com\/pt-br\/trabalho-hibrido\/conheca-voce-o-workspace-cognitivo-de-tres\/","og_locale":"pt_BR","og_type":"article","og_title":"Conhe\u00e7a voc\u00ea \u2014 O workspace cognitivo de tr\u00eas | Webex Blog","og_description":"O futuro do trabalho ser\u00e1 de tr\u00eas minutos. E a boa not\u00edcia \u00e9 que ele est\u00e1 aqui agora. Ela faz parte de uma nova abordagem chamada colabora\u00e7\u00e3o cognitiva, incorporando intelig\u00eancia inteligente com o contexto certo.","og_url":"https:\/\/blog.webex.com\/pt-br\/trabalho-hibrido\/conheca-voce-o-workspace-cognitivo-de-tres\/","og_site_name":"Webex Blog","article_published_time":"2019-06-11T16:45:19+00:00","og_image":[{"width":2119,"height":1414,"url":"https:\/\/blog.webex.com\/wp-content\/uploads\/2019\/06\/5cff619352d67-1.jpg","type":"image\/jpeg"}],"author":"Aruna Ravichandran","twitter_misc":{"Escrito por":"Aruna Ravichandran","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.webex.com\/pt-br\/trabalho-hibrido\/conheca-voce-o-workspace-cognitivo-de-tres\/#article","isPartOf":{"@id":"https:\/\/blog.webex.com\/pt-br\/trabalho-hibrido\/conheca-voce-o-workspace-cognitivo-de-tres\/"},"author":{"name":"Aruna Ravichandran","@id":"https:\/\/blog.webex.com\/es\/#\/schema\/person\/13123e3d3a33894876e3bb847361fae4"},"headline":"Conhe\u00e7a voc\u00ea \u2014 O workspace cognitivo de tr\u00eas","datePublished":"2019-06-11T16:45:19+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.webex.com\/pt-br\/trabalho-hibrido\/conheca-voce-o-workspace-cognitivo-de-tres\/"},"wordCount":1125,"commentCount":0,"image":{"@id":"https:\/\/blog.webex.com\/pt-br\/trabalho-hibrido\/conheca-voce-o-workspace-cognitivo-de-tres\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.webex.com\/wp-content\/uploads\/2019\/06\/5cff619352d67-1.jpg","keywords":["#CiscoCX","#CLUS","Blogs da Cisco","Cisco CX","Cisco Live","colabora\u00e7\u00e3o cognitiva","conectividade humana","conex\u00e3o humana","futuro do trabalho","Artificial Intelligence","local de trabalho conectado da cisco","videoconfer\u00eancia"],"articleSection":["Collaboration","Hybrid Work"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.webex.com\/pt-br\/trabalho-hibrido\/conheca-voce-o-workspace-cognitivo-de-tres\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.webex.com\/pt-br\/trabalho-hibrido\/conheca-voce-o-workspace-cognitivo-de-tres\/","url":"https:\/\/blog.webex.com\/pt-br\/trabalho-hibrido\/conheca-voce-o-workspace-cognitivo-de-tres\/","name":"Conhe\u00e7a voc\u00ea \u2014 O workspace cognitivo de tr\u00eas | Webex Blog","isPartOf":{"@id":"https:\/\/blog.webex.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.webex.com\/pt-br\/trabalho-hibrido\/conheca-voce-o-workspace-cognitivo-de-tres\/#primaryimage"},"image":{"@id":"https:\/\/blog.webex.com\/pt-br\/trabalho-hibrido\/conheca-voce-o-workspace-cognitivo-de-tres\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.webex.com\/wp-content\/uploads\/2019\/06\/5cff619352d67-1.jpg","datePublished":"2019-06-11T16:45:19+00:00","author":{"@id":"https:\/\/blog.webex.com\/es\/#\/schema\/person\/13123e3d3a33894876e3bb847361fae4"},"breadcrumb":{"@id":"https:\/\/blog.webex.com\/pt-br\/trabalho-hibrido\/conheca-voce-o-workspace-cognitivo-de-tres\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.webex.com\/pt-br\/trabalho-hibrido\/conheca-voce-o-workspace-cognitivo-de-tres\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/blog.webex.com\/pt-br\/trabalho-hibrido\/conheca-voce-o-workspace-cognitivo-de-tres\/#primaryimage","url":"https:\/\/blog.webex.com\/wp-content\/uploads\/2019\/06\/5cff619352d67-1.jpg","contentUrl":"https:\/\/blog.webex.com\/wp-content\/uploads\/2019\/06\/5cff619352d67-1.jpg","width":2119,"height":1414},{"@type":"BreadcrumbList","@id":"https:\/\/blog.webex.com\/pt-br\/trabalho-hibrido\/conheca-voce-o-workspace-cognitivo-de-tres\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.webex.com\/pt-br\/"},{"@type":"ListItem","position":2,"name":"Conhe\u00e7a voc\u00ea \u2014 O workspace cognitivo de tr\u00eas"}]},{"@type":"WebSite","@id":"https:\/\/blog.webex.com\/es\/#website","url":"https:\/\/blog.webex.com\/es\/","name":"Webex Blog","description":"Webex by Cisco powers collaboration through industry-leading video conferencing, cloud calling and contact center solutions","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.webex.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/blog.webex.com\/es\/#\/schema\/person\/13123e3d3a33894876e3bb847361fae4","name":"Aruna Ravichandran","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/c7448744d0884becd5a26d9b152a552ea57a4ade4d71ce42122061ea2ab76575?s=96&d=wp_user_avatar&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7448744d0884becd5a26d9b152a552ea57a4ade4d71ce42122061ea2ab76575?s=96&d=wp_user_avatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7448744d0884becd5a26d9b152a552ea57a4ade4d71ce42122061ea2ab76575?s=96&d=wp_user_avatar&r=g","caption":"Aruna Ravichandran"},"description":"Aruna drives significant revenue growth and brand value through a powerful blend of technological expertise, data science acumen, strategic storytelling, and marketing innovation. An early adopter of marketing automation and AI, Aruna stays at the forefront of technological advancements, consistently leveraging them to disrupt competitive markets. Her leadership in SaaS marketing and enterprise technology and her vision for AI's role in shaping customer and employee experiences have made her a sought-after thought leader in the industry. Beyond her professional achievements, Aruna is a passionate advocate for women in technology and making the STEM fields more inclusive and accessible. Aruna has an MBA and MS in Computer Engineering from Santa Clara University and a BS in Computer Science from Bangalore Institute of Technology. She is an alumna of the CMO Leadership program at Kellogg Business School. She serves on Cal Polytechnic San Luis Obispo, Fast Company, Forbes Technology Council, and Vox Media boards.","sameAs":["https:\/\/www.linkedin.com\/in\/aruna2u\/","https:\/\/x.com\/https:\/\/twitter.com\/aruna13"],"url":"https:\/\/blog.webex.com\/pt-br\/contributors\/arunaravichandran-2\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.webex.com\/pt-br\/wp-json\/wp\/v2\/posts\/386046","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.webex.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.webex.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.webex.com\/pt-br\/wp-json\/wp\/v2\/users\/5377"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.webex.com\/pt-br\/wp-json\/wp\/v2\/comments?post=386046"}],"version-history":[{"count":0,"href":"https:\/\/blog.webex.com\/pt-br\/wp-json\/wp\/v2\/posts\/386046\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.webex.com\/pt-br\/wp-json\/wp\/v2\/media\/386047"}],"wp:attachment":[{"href":"https:\/\/blog.webex.com\/pt-br\/wp-json\/wp\/v2\/media?parent=386046"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.webex.com\/pt-br\/wp-json\/wp\/v2\/categories?post=386046"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.webex.com\/pt-br\/wp-json\/wp\/v2\/tags?post=386046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}